{"id":82930,"date":"2018-09-14T00:00:00","date_gmt":"2018-09-14T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/baloncesto\/deportes\/20180914\/eddie-casiano-tenemos-que-buscar-la-manera-de-ganar\/"},"modified":"2025-07-16T06:46:56","modified_gmt":"2025-07-16T06:46:56","slug":"eddie-casiano-tenemos-que-buscar-la-manera-de-ganar","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20180914\/eddie-casiano-tenemos-que-buscar-la-manera-de-ganar\/","title":{"rendered":"Eddie Casiano: &#8216;Tenemos que buscar la manera de ganar&#8217;"},"content":{"rendered":"<p><i>El quinteto patrio juega ma\u00f1ana contra Panam\u00e1<\/i><\/p>\n<p>Para Eddie Casiano, tecnico del Equipo Nacional de baloncesto, no hay espacio para perder abriendo la primera ventada de la segunda ronda en los clasificatorios al Mundial FIBA y mucho m\u00e1s cuando se va a defender la casa.<\/p>\n<p>&#8216;Los 12 Magn\u00edficos&#8217; enfrentar\u00e1n ma\u00f1ana al conjunto de Panam\u00e1 desde las 7:00 p.m. en el Coliseo Roberto Clemente en Hato Rey.<\/p>\n<p>&#8216;Tenemos que salir (a ganar) s\u00ed o s\u00ed. Aqu\u00ed no hay derrotas. Tenemos que buscar la manera de ganar y buscar todas las alternativas de ganar. No podemos tener una derrota en la cancha de nosotros&#8217;, dijo hoy Casiano previo a una sesi\u00f3n de entrenamiento efectuada sobre el tabloncillo del Clemente.<\/p>\n<p>La escuadra se complet\u00f3 durante esta semana con el receso de la Serie Final del Baloncesto Superior Nacional (BSN). Casiano explic\u00f3 que muchos han jugado bajo su mandato y se ha cubierto la mayor cantidad de situaciones que quer\u00edan hacer.<\/p>\n<p>&#8216;Yo creo que el grupo est\u00e1 ya casi preparado. En el poco tiempo que hemos tenido hemos cumplido bastante con lo que queremos hacer. Han jugado ya conmigo. Algunos ya est\u00e1n acostumbrados a este escenario as\u00ed que hay que sacarle provecho. Va a ser un juego duro&#8217;, agreg\u00f3.<\/p><div class=\"notic-content-middle\" id=\"notic-3157021557\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Durante la tarde de hoy, Casiano hizo un corte reduciendo su listado a un total de 13 jugadores. Jonathan Rodr\u00edguez qued\u00f3 fuera del conjunto. Se espera que ma\u00f1ana en horas de la ma\u00f1ana complete un \u00faltimo corte.<\/p>\n<p>Hasta el momento, la escuadra qued\u00f3 confeccionada con Jose Juan Barea, David Huertas, Javier Mojica, Devon Collier, Ricky S\u00e1nchez, \u00c1ngel Vassallo, Gian Clavell, Gary Browne, \u00c1ngel Rodr\u00edguez, Gilberto Clavell, Alexander Franklin, Carlos Yao L\u00f3pez y Jorge Bryan D\u00edaz.<\/p>\n<p>El armador y capit\u00e1n del quinteto patrio, Jose Juan Barea, precis\u00f3 que ser\u00e1 un juego importante donde la fanaticada servir\u00e1 como el sexto hombre en cancha tal y como sucedi\u00f3 a principios del mes de julio pasado cuando fueron pieza clave en el triunfo ante Mexico. Los boricuas jugar\u00e1n ante cancha llena tras la venta total de boletos.<\/p>\n<p>&#8216;Es una oportunidad de ganar un juego importante aqu\u00ed en casa. Tenemos que aprovechar estas oportunidades. Un equipo de Panam\u00e1 que es grande, atletico y van a ir bien duro al rebote. Yo entiendo que con la energ\u00eda que nos va a dar la fanaticada y el grupo que tenemos, que tenemos muchachos que est\u00e1n en un buen ritmo de la Liga Superior. Esperamos arrancar bien y ganar ese importante juego que tenemos ma\u00f1ana&#8217;, enfatiz\u00f3 Barea.<\/p>\n<p>Casiano, por su parte, indic\u00f3 que todo el conjunto se encuentra saludable. El \u00fanico jugador que no estar\u00eda al 100 por ciento ser\u00eda el armador, \u00c1ngel Rodr\u00edguez, quien se recupera de una lesi\u00f3n en unos de sus tobillos. Su convocatoria alarm\u00f3 a todos en los Vaqueros de Bayam\u00f3n pues continuaba recuper\u00e1ndose y declin\u00f3 participar en el BSN. Rodr\u00edguez fue el Novato del A\u00f1o en esta temporada.<\/p>","protected":false},"excerpt":{"rendered":"<p>El quinteto patrio juega ma\u00f1ana contra Panam\u00e1 Para Eddie Casiano, tecnico del Equipo Nacional de baloncesto, no hay espacio para perder abriendo la primera ventada de la segunda ronda en los clasificatorios al Mundial FIBA y mucho m\u00e1s cuando se va a defender la casa. &#8216;Los 12 Magn\u00edficos&#8217; enfrentar\u00e1n ma\u00f1ana al conjunto de Panam\u00e1 desde [&hellip;]<\/p>","protected":false},"author":0,"featured_media":417386,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[33,31],"tags":[],"class_list":["post-82930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/82930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=82930"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/82930\/revisions"}],"predecessor-version":[{"id":417390,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/82930\/revisions\/417390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/417386"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=82930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=82930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=82930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}