{"id":82720,"date":"2012-06-29T00:00:00","date_gmt":"2012-06-29T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20120629\/apagon-aee-explica-y-quedan-130000-sin-luz\/"},"modified":"2025-07-16T07:06:11","modified_gmt":"2025-07-16T07:06:11","slug":"apagon-aee-explica-y-quedan-130000-sin-luz","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20120629\/apagon-aee-explica-y-quedan-130000-sin-luz\/","title":{"rendered":"Apag\u00f3n: AEE explica y quedan 130,000 sin luz"},"content":{"rendered":"<p>El director de generaci\u00f3n de la AEE, Josu\u00e9 Ortiz, a quien se rumora nombrar\u00e1n nuevo director ejecutivo de la agencia, practic\u00f3 sus posibles funciones hace uos minutos, explicando que lo ocurrido se debi\u00f3 al &#8216;colapso de las fases B y C de la l\u00ednea n\u00famero 36-2 de 115 mil voltios, que discurre entre Monacillos y Juncos&#8217;.<\/p>\n<p>El ingeniero explic\u00f3 que &#8216;Monacillos es el centro de control energ\u00e9tico de Puerto Rico. Es un punto el\u00e9ctrico donde llega la energ\u00eda y desde ese punto se distribuye la energ\u00eda a otros pueblos&#8217;.<\/p>\n<p>El sistema para proteger el baj\u00f3n energ\u00e9tico se autoprotegi\u00f3 tumbando la planta Ecoel\u00e9ctrica, Aguirre I, Planta de San Juan y Palo Seco. Durante el apag\u00f3n, 900 mil abonados se quedaron sin servicio el\u00e9ctrico, y al momento quedan s\u00f3lo 130 mil a\u00fan sin luz.<\/p>\n<p>A\u00fan no se determina qu\u00e9 provoc\u00f3 la ruptura de los cables, y los t\u00e9cnicos esperan el an\u00e1lisis de laboratorio. Ortiz dijo no estar pendiente a su prosible nombramiento como director de la agencia y estar enfocado en resolver la crisis.<\/p>\n<p><strong>El regreso de la luz<\/strong><\/p>\n<p>Poco m\u00e1s de dos horas despu\u00e9s de que una aver\u00eda en el sistema de la Autoridad de Energ\u00eda El\u00e9ctrica (AEE) dejara sin electricidad al 75% de los abonados en toda la isla, la luz comienza a regresar a algunas \u00e1reas afectadas. As\u00ed lo confirmaron lectores de NotiCel del Viejo San Juan, Vega Baja y Cidra, entre otros municipios. Los sem\u00e1foros del \u00e1rea metropolitana vuelven a funcionar.<\/p>\n<p>Desde Barceloneta hasta Cayey, tres cuartas partes de Puerto Rico se quedaron sin servicio el\u00e9ctrico.<\/p><div class=\"notic-content-middle\" id=\"notic-551429066\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El presidente de la UTIER, \u00c1ngel Figueroa Jaramillo, dijo a la estaci\u00f3n radial de noticias Radio Isla 1320 que &#8216;la informaci\u00f3n oficial que tenemos es que un 75 por ciento de la Isla se qued\u00f3 sin servicio&#8217;. Figueroa Jaramillo indic\u00f3 que la situaci\u00f3n se le adjudica &#8216;a una aver\u00eda en una l\u00ednea principal de 115 voltios en la central de Monacillos&#8217;, en Guaynabo.<\/p>\n<p>Los ciudadanos inundaron las redes sociales cibern\u00e9ticas quej\u00e1ndose sobre la situaci\u00f3n. NotiCel recibi\u00f3 quejas de abonados de localidades como Ponce, Vega Baja y Santurce, entre muchas otras.<\/p>\n<p>El apag\u00f3n afect\u00f3 las principales v\u00edas de tr\u00e1nsito del Pa\u00eds, dejando sin funci\u00f3n la mayor\u00eda de sus sem\u00e1foros. No se reportaron accidentes de gravedad relacionados a esto, pero se esperaba una avalancha de incidencias en cualquier momento.<\/p>\n<p>Otoniel Cruz, director ejecutivo de la AEE, confirm\u00f3 a Radio Isla que, de hecho, tres cuartas partes de Puerto Rico perdieron el servicio el\u00e9ctrico. Seg\u00fan \u00e9l, porque se da\u00f1\u00f3 &#8216;una l\u00ednea que viene del sur&#8217;. Cruz, involucrado en estos momentos en distintas controversias por supuesta corrupci\u00f3n en contratos otorgados a miembros del Partido Nuevo Progresista (PNP), se atrevi\u00f3 a decir que el servicio se reestablecer\u00eda dentro de un m\u00e1ximo de dos horas, &#8216;pues estamos trabajando en eso&#8217;.<\/p>\n<p>La AEE pasa por uno de los peores momentos de su historia, con m\u00faltiples se\u00f1alamientos de corrupci\u00f3n y aumentos en las tarifas durante este pasado cuatrienio.<\/p>\n<p>Pendientes a NotiCel para el desarrollo de esta historia.<\/p>","protected":false},"excerpt":{"rendered":"<p>El director de generaci\u00f3n de la AEE, Josu\u00e9 Ortiz, a quien se rumora nombrar\u00e1n nuevo director ejecutivo de la agencia, practic\u00f3 sus posibles funciones hace uos minutos, explicando que lo ocurrido se debi\u00f3 al &#8216;colapso de las fases B y C de la l\u00ednea n\u00famero 36-2 de 115 mil voltios, que discurre entre Monacillos y [&hellip;]<\/p>","protected":false},"author":0,"featured_media":418699,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-82720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/82720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=82720"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/82720\/revisions"}],"predecessor-version":[{"id":418701,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/82720\/revisions\/418701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/418699"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=82720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=82720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=82720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}