{"id":8138,"date":"2020-01-25T00:00:00","date_gmt":"2020-01-25T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/top-stories\/20200125\/durante-el-sismo-de-6-4-la-tierra-se-movio-mas-rapido-de-lo-que-anticipan-c\/"},"modified":"2025-07-20T16:09:03","modified_gmt":"2025-07-20T16:09:03","slug":"durante-el-sismo-de-6-4-la-tierra-se-movio-mas-rapido-de-lo-que-anticipan-c","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200125\/durante-el-sismo-de-6-4-la-tierra-se-movio-mas-rapido-de-lo-que-anticipan-c\/","title":{"rendered":"Durante el sismo de 6.4 la tierra se movi\u00f3 m\u00e1s r\u00e1pido de lo que anticipan c"},"content":{"rendered":"<p><i>Programa de la UPR revela datos tras el sismo<\/i><\/p>\n<p>La rapidez con la que se movi\u00f3 el suelo durante el sismo de 6.4 grados fue mucho mayor a la m\u00e1xima contemplada en el dise\u00f1o de los edificios en Puerto Rico, seg\u00fan las mediciones preliminares de los registros de aceleraciones en Ponce recopilados por el Programa de Movimiento Fuerte de Puerto Rico del Departamento de Ingenier\u00eda Civil del Recinto Universitario de Mayag\u00fcez de la Universidad de Puerto Rico (UPR)<\/p>\n<p>A ra\u00edz de estos nuevos datos, las autoridades deber\u00edan modificar los c\u00f3digos de construcci\u00f3n para atemperarlos a la fuerza de este terremoto, afirm\u00f3 el Dr. Luis E. Su\u00e1rez, Catedr\u00e1tico del Departamento de Ingenier\u00eda Civil de la UPR de Mayag\u00fcez.<\/p>\n<p>La aceleraci\u00f3n del suelo causada por este terremoto fue de 0.4 g, seg\u00fan los datos recopilados por el Programa de Movimiento Fuerte. Esta velocidad supera los 0.2g en los que se basan los c\u00f3digos de construcci\u00f3n en la isla.<\/p>\n<p>&#8216;Las aceleraciones que nuestros instrumentos han medido son superiores a la de los c\u00f3digos (vigentes). Nos damos cuanta que con la nueva informaci\u00f3n que hemos recopilado con el sismo de 6.4 grados del 7 enero de 2020 ese espectro hay que modificarlo. Esto es un hallazgo preliminar que se debe trabajar por las agencias pertinentes y expertos, pero hemos encontrado que no es adecuada la actual&#8217;, dijo Su\u00e1rez en entrevista con NotiCel.<\/p>\n<p>La aceleraci\u00f3n del suelo es la rapidez con la que se mover\u00e1n las part\u00edculas de la tierra al momento de un sismo. El Dr. Su\u00e1rez afirm\u00f3 que conocer ese detalle es imprescindible para dise\u00f1ar estructuras que resistan un nuevo sismo, ya que la fuerza de una estructura se calcula con la masa de la estructura y la aceleraci\u00f3n del suelo.<\/p>\n<p>Al momento de establecer los c\u00f3digos de construcci\u00f3n se toma en cuenta el peso que tendr\u00eda que sostener el edificio, ya sea por la cantidad de personas que recibir\u00e1, el mobiliario que tendr\u00eda que sostener, etc. En otras palabras, se utiliza un estimado del peso que el edificio podr\u00eda recibir para anticipar c\u00f3mo este se debe construir para que la estructura resista alg\u00fan sismo.<\/p>\n<p>Se considera adem\u00e1s, la fuerza que ejercer\u00eda un temblor, es decir, cu\u00e1n r\u00e1pido se mover\u00eda el suelo. Esa fuerza, contrario -a la primera- no es f\u00e1cil de calcular porque no se puede anticipar con exactitud la magnitud del terremoto que podr\u00eda afectar la estructura.<\/p>\n<p>Para calcular dicha aceleraci\u00f3n los expertos incluyen en los c\u00f3digos unas curvas llamadas Espectros de Dise\u00f1o.<\/p>\n<p>De acuerdo con el academico, durante un sismo las part\u00edculas de la tierra se desplazan, o sea, se mueven. Asegur\u00f3 que el problema no es que el suelo se mueva, sino que se mueva muy r\u00e1pido -m\u00e1s de lo que se calcul\u00f3 al momento de su construcci\u00f3n- y la estructura no lo resista como ocurri\u00f3 en el terremoto de 6.4 grados del pasado 7 de enero.<\/p>\n<p>&#8216;Estas curvas est\u00e1n provistas en los c\u00f3digos de construcci\u00f3n porque uno entra por el eje horizontal llega a la curva y saca la aceleraci\u00f3n, que es lo fundamental para dise\u00f1ar una estructura que resista un terremoto. Era dif\u00edcil estimar porque no hab\u00eda una referencia reciente&#8217;, indic\u00f3 el Catedr\u00e1tico.<\/p>\n<p>Explic\u00f3 que en Puerto Rico, al igual que en otros lugares donde no hab\u00eda habido sismos recientes, se utiliza la informaci\u00f3n de movimientos tel\u00faricos en otros pa\u00edses con fallas similares. Esta informaci\u00f3n se adapta y se utiliza para calcular la curva o Espectro de Dise\u00f1o establecida en los c\u00f3digos de construcci\u00f3n.<\/p>\n<p>De acuerdo con el Catedr\u00e1tico en Ingenier\u00eda Civil, con la informaci\u00f3n recopilada se deber\u00eda revisar los c\u00f3digos de construcci\u00f3n y modificar los par\u00e1metros para calcular la aceleraci\u00f3n para que sean mayores a los actuales.<\/p>\n<p>Sostuvo que estos cambios en los c\u00f3digos ocurren en todos los pa\u00edses y jurisdicciones luego de ocurrido un terremoto, ya que lo l\u00f3gico es que se revise el dise\u00f1o s\u00edsmico para que refleje la nueva realidad. Tal fue el caso de Mexico y en el estado de California.<\/p>\n<p>&#8216;Esas curvas no est\u00e1n escritas en piedra. Ser van modificando a medida que se tiene nueva informaci\u00f3n. Si se descubre una falla nueva que no se hab\u00eda considerado se van cambiando. Esa falla que estaba dormida no se hab\u00eda tomado en cuenta. Ahora con la nueva informaci\u00f3n como se descubri\u00f3 que la falla estaba viva, se activ\u00f3 y provoc\u00f3 un sismo pues entonces hay que cambiar el c\u00f3digo para que refleje esa nueva informaci\u00f3n&#8217;, asegur\u00f3.<\/p>\n<p>La curva utilizada por el Programa de Movimiento Fuerte para proyectar cu\u00e1l deber\u00eda ser el estimado m\u00e1ximo de la aceleraci\u00f3n del suelo a ra\u00edz de la medici\u00f3n del sismo del pasado 7 de enero, no corresponde a los c\u00f3digos de construcci\u00f3n m\u00e1s recientes, sino a uno utilizado por muchos a\u00f1os.<\/p>\n<p>La intenci\u00f3n ahora, seg\u00fan el academico, es que los resultados se adapten mejor a la realidad debido a que la mayor\u00eda de las estructuras no son de reciente construcci\u00f3n. Los resultados, aclar\u00f3, son &#8216;preliminares personales y de ninguna manera oficiales&#8217;.<\/p>\n<p>El Programa de Movimiento Fuerte tiene instrumentos para medir los temblores en distintos puntos en Puerto Rico. Este Programa tiene instrumentos para medir solo los movimientos tel\u00faricos fuertes que se conocen como sensores, por lo que la medici\u00f3n es precisa a mayor magnitud.<\/p>\n<p>Los instrumentos que utiliza la Red S\u00edsmica (sism\u00f3grafos) son instrumentos sumamente sensibles. Aunque pueden sentir cualquier temblor ya sea uno imperceptible, suelen saturarse al haber temblores de mayor intensidad, explic\u00f3 Su\u00e1rez.<\/p>\n<p>&#8216;Ese es el precio que hay que pagar para poder medir un sismo de magnitud 2.0. Los nuestros no miden para nada esos movimientos. Siguen dormidos. Cuando viene uno de magnitud 5.0 entonces se despiertan. En cambio los de la Red S\u00edsmica pueden sentir cualquier movimiento aunque nadie lo sienta&#8217;, sostuvo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Programa de la UPR revela datos tras el sismo La rapidez con la que se movi\u00f3 el suelo durante el sismo de 6.4 grados fue mucho mayor a la m\u00e1xima contemplada en el dise\u00f1o de los edificios en Puerto Rico, seg\u00fan las mediciones preliminares de los registros de aceleraciones en Ponce recopilados por el Programa [&hellip;]<\/p>","protected":false},"author":0,"featured_media":539189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-8138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/8138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=8138"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/8138\/revisions"}],"predecessor-version":[{"id":539190,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/8138\/revisions\/539190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/539189"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=8138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=8138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=8138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}