{"id":81185,"date":"2012-05-25T00:00:00","date_gmt":"2012-05-25T04:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/deportes\/20120525\/el-coi-pone-bajo-lupa-a-madrid-tokio-y-estambul\/"},"modified":"2025-07-16T09:34:36","modified_gmt":"2025-07-16T09:34:36","slug":"el-coi-pone-bajo-lupa-a-madrid-tokio-y-estambul","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20120525\/el-coi-pone-bajo-lupa-a-madrid-tokio-y-estambul\/","title":{"rendered":"El COI pone bajo lupa a Madrid, Tokio y Estambul"},"content":{"rendered":"<p>El COI ha reducido a cuatro las presentaciones internacionales que Madrid, Tokio y Estambul, candidatas a organizar los Juegos Ol\u00edmpicos de 2020, podr\u00e1n hacer antes de la elecci\u00f3n.<\/p>\n<p>El objetivo es ahorrar costes, informaron a las tres ciudades Gilbert Felli, director ejecutivo del COI para los Juegos, y Jacqueline Barrett, jefa de relaciones con las candidaturas.<\/p>\n<p>Se han eliminado las presentaciones en las asambleas de comit\u00e9s ol\u00edmpicos continentales -pero s\u00ed pueden asistir a ellas- y las comparecencias se limitar\u00e1n a la reuni\u00f3n de ACNO (Asociaci\u00f3n mundial de Comit\u00e9s Ol\u00edmpicos), en lugar y fecha por determinar, a la convenci\u00f3n de Sportaccord, en San Petersburgo del 26 al 31 de mayo de 2013, al encuentro organizado por el COI con sus miembros en Lausana los d\u00edas 3 y 4 de julio del mismo a\u00f1o y a la presentaci\u00f3n final el d\u00eda de la elecci\u00f3n, el 7 de septiembre en Buenos Aires.<\/p>\n<p>&#8216;Solo por no tener que hacer un v\u00eddeo promocional distinto para cada asociaci\u00f3n continental ya se ahorrar\u00e1 mucho dinero&#8217;, coment\u00f3 a Efe V\u00edctor S\u00e1nchez, consejero delegado de la candidatura.<\/p>\n<p>Las tres ciudades mantuvieron hoy una reuni\u00f3n informativa en Quebec con los responsables del COI, que les informaron de los pasos que pueden dar a partir de ahora y c\u00f3mo deben conducir su campa\u00f1a internacional.<\/p>\n<p>Por parte de Madrid asistieron Alejandro Blanco, Theresa Zabell, V\u00edctor S\u00e1nchez y Manuel Parga, director financiero de la candidatura.<\/p><div class=\"notic-content-middle\" id=\"notic-2102474504\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>No se les permite publicitarse en revistas de federaciones internacionales; hacer comentarios sobre las ciudades rivales; participar en debates entre las candidatas; entrevistar o sacar im\u00e1genes de los miembros del COI en las publicaciones propias (excepto los de su pa\u00eds); visitar o ser visitados por ellos; ofrecer regalos; y promocionarse en Suiza en cualquier momento o en Buenos Aires tres semanas antes de la elecci\u00f3n.<\/p>\n<p>En los Juegos de Londres del pr\u00f3ximo verano participar\u00e1n en el programa de observadores y podr\u00e1n ofrecer una conferencia de prensa de media hora, as\u00ed como montar un expositor en la sala de hospitalidad del comit\u00e9 nacional correspondiente.<\/p>\n<p>Del 17 al 21 de noviembre se celebrar\u00e1 en R\u00edo de Janeiro una reuni\u00f3n para analizar las conclusiones de los Juegos de Londres, a la que las candidatas est\u00e1n invitadas.<\/p>\n<p>El informe de candidatura debe entregarse antes del 7 de enero de 2013 y puede hacerse p\u00fablico el d\u00eda siguiente. Antes de entonces no se puede hacer promoci\u00f3n internacional, distribuir material publicitario o invitar a las embajadas espa\u00f1olas a los miembros del COI.<\/p>\n<p>Otra novedad, explicaron V\u00edctor S\u00e1nchez y Theresa Zabell, es que no ser\u00e1 necesario detallar en el informe de candidatura algunos aspectos que ya han quedado suficientemente explicados en el cuestionario de la primera fase.<\/p>\n<p>As\u00ed, los cap\u00edtulos de estructura pol\u00edtica y econ\u00f3mica, tecnolog\u00eda, meteorolog\u00eda, inmigraci\u00f3n y aduanas y pol\u00edtica antidopaje no ser\u00e1n revisados por el COI, salvo que una ciudad tenga un seguimiento concreto sobre uno de ellos, caso de Madrid con las cifras econ\u00f3micas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El COI ha reducido a cuatro las presentaciones internacionales que Madrid, Tokio y Estambul, candidatas a organizar los Juegos Ol\u00edmpicos de 2020, podr\u00e1n hacer antes de la elecci\u00f3n. El objetivo es ahorrar costes, informaron a las tres ciudades Gilbert Felli, director ejecutivo del COI para los Juegos, y Jacqueline Barrett, jefa de relaciones con las [&hellip;]<\/p>","protected":false},"author":0,"featured_media":428998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-81185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/81185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=81185"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/81185\/revisions"}],"predecessor-version":[{"id":428999,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/81185\/revisions\/428999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/428998"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=81185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=81185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=81185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}