{"id":804760,"date":"2023-01-24T11:19:35","date_gmt":"2023-01-24T15:19:35","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/policiacas\/20230124\/se-busca-por-carjacking-ocurrido-en-canovanas\/"},"modified":"2025-08-15T05:03:32","modified_gmt":"2025-08-15T05:03:32","slug":"se-busca-por-carjacking-ocurrido-en-canovanas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20230124\/se-busca-por-carjacking-ocurrido-en-canovanas\/","title":{"rendered":"Se busca por \u201ccarjacking\u201d ocurrido en Can\u00f3vanas"},"content":{"rendered":"<h3>Se presume armado y peligroso.<\/h3>\n<p>Agentes de la Divisi\u00f3n de Robo del Cuerpo de Investigaciones Criminales (CIC) de Carolina solicitaron el martes la cooperaci\u00f3n ciudadana para dar con el paradero de un sujeto sospechoso de cometer el delito de carjacking, en hechos ocurridos el 7 de enero de 2023, en la calle Main de la urbanizaci\u00f3n Quintas de Can\u00f3vanas, en el municipio de Can\u00f3vanas.<\/p>\n<p>Seg\u00fan se inform\u00f3, el hombre fue descrito como de 5\u20195\u201d de estatura, 140 libras de peso, tez trigue\u00f1a y de 30 a 45 a\u00f1os.  Se presume armado y peligroso.<\/p><div class=\"notic-content-middle\" id=\"notic-1585620931\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Por los hechos que se busca, se remontan a la mencionada fecha, cuando el hombre, mediante carjacking y utilizando un arma de fuego, hurt\u00f3 el veh\u00edculo BMW, 528i, color gris, a\u00f1o 2009, tablilla JXN-675. En el incidente, la v\u00edctima result\u00f3 ilesa.<\/p>\n<p>Si posee informaci\u00f3n que ayude a dar con el paradero de este sujeto, favor de comunicarse con la Divisi\u00f3n de Robo del C.I.C. Carolina, al tel\u00e9fono 787-257-7500 extensi\u00f3n 1554 o a la l\u00ednea confidencia de la Polic\u00eda de Puerto Rico 787-343-2020. Toda llamada ser\u00e1 tratada de manera confidencial.<\/p>","protected":false},"excerpt":{"rendered":"<p>Se presume armado y peligroso. Agentes de la Divisi\u00f3n de Robo del Cuerpo de Investigaciones Criminales (CIC) de Carolina solicitaron el martes la cooperaci\u00f3n ciudadana para dar con el paradero de un sujeto sospechoso de cometer el delito de carjacking, en hechos ocurridos el 7 de enero de 2023, en la calle Main de la [&hellip;]<\/p>","protected":false},"author":25,"featured_media":843609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[],"class_list":["post-804760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/804760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=804760"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/804760\/revisions"}],"predecessor-version":[{"id":843611,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/804760\/revisions\/843611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/843609"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=804760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=804760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=804760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}