{"id":80156,"date":"2014-07-04T00:00:00","date_gmt":"2014-07-04T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20140704\/18-meses-de-carcel-para-el-exjefe-de-prensa-del-primer-ministro-britanico\/"},"modified":"2025-07-16T11:01:28","modified_gmt":"2025-07-16T11:01:28","slug":"18-meses-de-carcel-para-el-exjefe-de-prensa-del-primer-ministro-britanico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20140704\/18-meses-de-carcel-para-el-exjefe-de-prensa-del-primer-ministro-britanico\/","title":{"rendered":"18 meses de c\u00e1rcel para el exjefe de prensa del primer ministro brit\u00e1nico"},"content":{"rendered":"<p>Andy Coulson, exjefe de prensa del primer ministro brit\u00e1nico, David Cameron, fue condenado hoy en Londres a 18 meses de prisi\u00f3n por el caso de las escuchas en la prensa.<\/p>\n<p>El tribunal penal de Old Bailey conden\u00f3 a Coulson despu\u00e9s de que fuese declarado culpable la semana pasada de conspirar para interceptar tel\u00e9fonos entre 2000 y 2006 cuando trabajaba para el desaparecido dominical brit\u00e1nico &#8216;News of the World&#8217; (NoW).<\/p>\n<p>Coulson, que fue director de ese rotativo entre 2003 y 2007, dimiti\u00f3 como director de comunicaciones de Cameron en enero de 2011 a ra\u00edz de las investigaciones de la Polic\u00eda sobre los pinchazos de tel\u00e9fonos de ricos y famosos para obtener exclusivas.<\/p>\n<p>Al dar a conocer la pena, el juez John Saunders dijo que Coulson, de 46 a\u00f1os, deb\u00eda asumir la culpa por las escuchas en el NoW porque estaba al tanto de ellas y &#8216;las incentiv\u00f3 cuando debi\u00f3 impedirlas&#8217;.<\/p>\n<p>El magistrado a\u00f1adi\u00f3 que ha quedado claro que el periodista consider\u00f3 en su d\u00eda que esos pinchazos eran necesarios para mantener el nivel &#8216;competitivo&#8217; del dominical en el mercado brit\u00e1nico.<\/p>\n<p>Adem\u00e1s de Coulson, fueron condenadas hoy otras cuatro personas que admitieron en su d\u00eda haber conspirado para pinchar tel\u00e9fonos.<\/p>\n<p>Se trata del exdirector de informaci\u00f3n del NoW Greg Miskiw y el periodista Neville Thurlbeck, condenados a seis meses de c\u00e1rcel.<\/p>\n<p>Al tambi\u00e9n periodista James Weatherup se le impuso una pena de seis meses que cumplir\u00e1 en libertad condicional y al investigador privado Glenn Mulcaire una condena de cuatro meses pero en libertad condicional, aunque los dos deber\u00e1n hacer trabajos comunitarios.<\/p>\n<p>Coulson estuvo varios a\u00f1os en el dominical antes de empezar a trabajar para Cameron, primero cuando \u00e9ste fue l\u00edder de la oposici\u00f3n conservadora y despu\u00e9s cuando lleg\u00f3 al poder en mayo de 2010.<\/p><div class=\"notic-content-middle\" id=\"notic-2943179436\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>No obstante, el exdirector de comunicaciones de Cameron ser\u00e1 sometido a un nuevo juicio por un cargo que qued\u00f3 pendiente, al no hallar un veredicto un\u00e1nime el jurado, que qued\u00f3 disuelto.<\/p>\n<p>En concreto, el periodista ser\u00e1 juzgado, en una fecha todav\u00eda por determinar, por un cargo relacionado con el supuesto soborno a un polic\u00eda para obtener los tel\u00e9fonos de miembros de la familia real.<\/p>\n<p>Adem\u00e1s de Coulson, ser\u00e1 procesado tambi\u00e9n por los mismos cargos el experiodista de la realeza del dominical, Clive Goodman.<\/p>\n<p>Al darse a conocer la semana pasada el dictamen del proceso, la exdirectora del &#8216;News of the World&#8217; Rebekah Brooks fue absuelta de todos los cargos relacionados con las escuchas ilegales.<\/p>\n<p>El marido de Brooks, Charlie Brooks, y su asistente personal, Cheryl Carter, ambos acusados en relaci\u00f3n con las escuchas, fueron tambi\u00e9n absueltos del cargo de obstrucci\u00f3n a la Justicia.<\/p>\n<p>Otro de los imputados, el director de seguridad del &#8216;News of the World&#8217;, Mark Hanna, fue absuelto del cargo de obstrucci\u00f3n a la Justicia, as\u00ed como el exdirector gerente del dominical Stuart Kuttner, sobre el que pesaba la misma acusaci\u00f3n.<\/p>\n<p>Este caso caus\u00f3 una gran conmoci\u00f3n en el Reino Unido al revelarse en 2011 el alcance de los pinchazos del &#8216;News of the World&#8217;.<\/p>\n<p>El due\u00f1o del rotativo, el empresario Rupert Murdoch, decidi\u00f3 en 2011 clausurarlo a ra\u00edz del esc\u00e1ndalo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Andy Coulson, exjefe de prensa del primer ministro brit\u00e1nico, David Cameron, fue condenado hoy en Londres a 18 meses de prisi\u00f3n por el caso de las escuchas en la prensa. El tribunal penal de Old Bailey conden\u00f3 a Coulson despu\u00e9s de que fuese declarado culpable la semana pasada de conspirar para interceptar tel\u00e9fonos entre 2000 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":435165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-80156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/80156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=80156"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/80156\/revisions"}],"predecessor-version":[{"id":435166,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/80156\/revisions\/435166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/435165"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=80156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=80156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=80156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}