{"id":79818,"date":"2014-03-04T00:00:00","date_gmt":"2014-03-04T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20140304\/actor-de-captain-phillips-con-problemas-economicos\/"},"modified":"2025-07-16T11:24:29","modified_gmt":"2025-07-16T11:24:29","slug":"actor-de-captain-phillips-con-problemas-economicos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20140304\/actor-de-captain-phillips-con-problemas-economicos\/","title":{"rendered":"Actor de &#8216;Captain Phillips&#8217; con problemas econ\u00f3micos"},"content":{"rendered":"<p>Barkhad Abdi, nominado al Oscar como mejor Actor de Reparto, lleva viviendo meses de una intensa vida p\u00fablica luego de que su interpretaci\u00f3n del pirata somal\u00ed &#8216;Muse&#8217; en la pel\u00edcula &#8216;Captain Phillips&#8217; acaparara la atenci\u00f3n de cr\u00edticos y entusiastas del cine.<\/p>\n<p>Sin embargo, la fama que ha rodeado \u00faltimamente al actor de 28 a\u00f1os oculta la realidad de este nuevo talento: Abdi s\u00f3lo recibi\u00f3 $65 mil por su interpretaci\u00f3n en el film que cost\u00f3 $55 millones. As\u00ed lo reporta el portal de noticias de entretenimiento E!, citando a su vez a The New Yorker.<\/p>\n<p>La filmaci\u00f3n de la pel\u00edcula culmin\u00f3 hace unos dos a\u00f1os.<\/p>\n<p>Este \u00faltimo medio reporta que cuando Abdi est\u00e1 en Los \u00c1ngeles para promocionar la pel\u00edcula, el estudio le paga una pensi\u00f3n diaria para sus gastos y lo hospeda en el Beverly Hilton. Mientras, la transportaci\u00f3n exclusiva del estudio s\u00f3lo la puede usar para eventos de publicidad. Su ropa es alquilada.<\/p>\n<p>Por un tiempo, el somal\u00ed regres\u00f3 a trabajar en la tienda de tel\u00e9fonos celular de su hermano, pero una vez la pel\u00edcula estren\u00f3, decidi\u00f3 renunciar ya que una vez la pel\u00edcula saliera, las cr\u00edticas ser\u00edan buenas o malas y &#8216;de cualquier manera, no puedo estar trabajado aqu\u00ed&#8217;.<\/p>\n<p>Abdi gan\u00f3 un BAFTA como mejor actor de reparto y est\u00e1 en busca de su pr\u00f3xima pel\u00edcula.<\/p>","protected":false},"excerpt":{"rendered":"<p>Barkhad Abdi, nominado al Oscar como mejor Actor de Reparto, lleva viviendo meses de una intensa vida p\u00fablica luego de que su interpretaci\u00f3n del pirata somal\u00ed &#8216;Muse&#8217; en la pel\u00edcula &#8216;Captain Phillips&#8217; acaparara la atenci\u00f3n de cr\u00edticos y entusiastas del cine. Sin embargo, la fama que ha rodeado \u00faltimamente al actor de 28 a\u00f1os oculta [&hellip;]<\/p>","protected":false},"author":0,"featured_media":436729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-79818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/79818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=79818"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/79818\/revisions"}],"predecessor-version":[{"id":436732,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/79818\/revisions\/436732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/436729"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=79818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=79818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=79818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}