{"id":79570,"date":"2014-01-11T00:00:00","date_gmt":"2014-01-11T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20140111\/celebra-la-academia-del-pais-el-nacimiento-de-hostos\/"},"modified":"2025-07-16T11:45:25","modified_gmt":"2025-07-16T11:45:25","slug":"celebra-la-academia-del-pais-el-nacimiento-de-hostos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140111\/celebra-la-academia-del-pais-el-nacimiento-de-hostos\/","title":{"rendered":"Celebra la academia del Pa\u00eds el nacimiento de Hostos"},"content":{"rendered":"<p>El principal centro educativo del Pa\u00eds conmemor\u00f3 el s\u00e1bado 175 a\u00f1os de natalicio de uno de los principales pilares del movimiento independentista de Puerto Rico, don Eugenio Mar\u00eda de Hostos, prominente abogado y mayag\u00fcezano ilustre que sirvi\u00f3, entre much\u00edsimas otras funciones, como educador, fil\u00f3sofo, intelectual y soci\u00f3logo.<\/p>\n<p>El Recinto de R\u00edo Piedras de la Universidad de Puerto Rico conmemor\u00f3 el natalicio del llamado &#8216;Ciudadano de Am\u00e9rica&#8217; con una serie de actividades en el referido campus universitario.<\/p>\n<p>Hostos naci\u00f3 el once de enero del a\u00f1o 1839 en Mayag\u00fcez y falleci\u00f3 en la Rep\u00fablica Dominicana el once de agosto de 1903 en la ciudad de Santo Domingo, en la Rep\u00fablica Dominicana. Su estampa adorna muchos bufetes de abogados y artisttas, quienes recuerdan su oficio como autor de libros, cuentos, obras de teatro y poes\u00edas del ideal que profesaba.<\/p>\n<p>La primera de ellas consisti\u00f3 de un mensaje por el exrector riopiedrense y excomisionado de Vieques, el doctor Juan R. Fern\u00e1ndez, quien exhort\u00f3 a &#8216;convertir los ecos hostosianos en plenos sonidos sociales&#8217;.<\/p>\n<p>En su alocuci\u00f3n, Rodr\u00edguez destac\u00f3 la importancia del poder social versus el poder pol\u00edtico y el de una cultura social puertorrique\u00f1a m\u00e1s participativa.<\/p><div class=\"notic-content-middle\" id=\"notic-2081342282\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>&#8216;Todo el mundo habla de una crisis y dentro de esa situaci\u00f3n percibo una serie de movimientos en la sociedad puertorrique\u00f1a que se conoce como los \u2018ecos hostosianos. Debido a la incompetencia de la clase pol\u00edtica, pues ha surgido un progresivo enajenamiento entre el pueblo, nosotros, y el gobierno. No hay una relaci\u00f3n tan cercana como la hubo antes&#8217;, dijo.<\/p>\n<p>De acuerdo al doctor, los movimientos sociales que han surgido en los pasados a\u00f1os son el producto de una clase pol\u00edtica que no ha logrado un contacto y comunicaci\u00f3n con los ciudadanos.<\/p>\n<p>&#8216;La ampliaci\u00f3n del proceso democr\u00e1tico para que sea uno menos excluyente. Hay que promover la participaci\u00f3n ciudadana democr\u00e1tica, no solo cada cuatro a\u00f1os, sino todo el tiempo. La recomendaci\u00f3n ser\u00eda que veamos esto como una asignaci\u00f3n que nos hizo Hostos, que como era un buen maestro, era muy bueno dando asignaciones y nos encomend\u00f3 construir la patria con los alineamientos que \u00e9l mismo nos ofreci\u00f3. Lo que me pregunto es; si podemos hacerlo, si estamos dispuestos a seguir esas recomendaciones&#8217;, agreg\u00f3 el tambi\u00e9n miembro de la Alianza Pro Libre Asociaci\u00f3n Soberana (ALAS).<\/p>\n<p>La actividad, se llev\u00f3 a cabo en la plaza que lleva el nombre del pr\u00f3cer puertorrique\u00f1o, justo al lado de la Torre de la UPR. En la misma, particip\u00f3 la rectora interina del Recinto de R\u00edo Piedras, Ethel R\u00edos, y el presidente de la UPR, Uroyo\u00e1n Walker.<\/p>","protected":false},"excerpt":{"rendered":"<p>El principal centro educativo del Pa\u00eds conmemor\u00f3 el s\u00e1bado 175 a\u00f1os de natalicio de uno de los principales pilares del movimiento independentista de Puerto Rico, don Eugenio Mar\u00eda de Hostos, prominente abogado y mayag\u00fcezano ilustre que sirvi\u00f3, entre much\u00edsimas otras funciones, como educador, fil\u00f3sofo, intelectual y soci\u00f3logo. El Recinto de R\u00edo Piedras de la Universidad [&hellip;]<\/p>","protected":false},"author":0,"featured_media":438203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-79570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/79570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=79570"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/79570\/revisions"}],"predecessor-version":[{"id":438206,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/79570\/revisions\/438206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/438203"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=79570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=79570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=79570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}