{"id":777975,"date":"2021-05-17T05:50:00","date_gmt":"2021-05-17T09:50:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=162116"},"modified":"2025-08-15T19:51:37","modified_gmt":"2025-08-15T19:51:37","slug":"el-voto-write-in-transforma-la-eleccion-especial","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/politica\/20210517\/el-voto-write-in-transforma-la-eleccion-especial\/","title":{"rendered":"El voto \u2018write-in\u2019 transforma la elecci\u00f3n especial"},"content":{"rendered":"<h3>La CEE no reporta el nombre de las personas que reciben votos por nominaci\u00f3n directa la noche del evento, as\u00ed que ayer el PNP ofreci\u00f3 esa informaci\u00f3n de manera extraoficial.<\/h3>\n<p>La elecci\u00f3n especial para escoger a los seis delegados de la delegaci\u00f3n congresional pintaba como un evento insulso, pero la incursi\u00f3n a \u00faltima hora del exgobernador Ricardo Rossell\u00f3 Nevares alter\u00f3 la contienda, que llev\u00f3 a unas 100,000 personas a las urnas.<\/p>\n<p>Pese a que no volc\u00f3 a las huestes del Partido Nuevo Progresista (PNP) a los colegios de votaci\u00f3n, oblig\u00f3 a la colectividad a crear una hoja de conteo para desglosar el voto por nominaci\u00f3n directa o \u2018write-in\u2019 y as\u00ed proveer una proyecci\u00f3n m\u00e1s amplia de la votaci\u00f3n.<\/p>\n<p>La Comisi\u00f3n Estatal de Elecciones (CEE) no adjudica el voto \u2018write-in\u2019 la noche del evento. Ese conteo se realiza durante el escrutinio general, que arranca este mi\u00e9rcoles. Por eso, anoche, el presidente de la CEE, Francisco Rosado Colomer, promulg\u00f3 una certificaci\u00f3n preliminar con los resultados alcanzados con el 87.29% de los colegios reportados sin el desglose o el nombre de los candidatos y candidatas a\u00f1adidos a mano en la papeleta.<\/p>\n<p><strong id=\"strong-c4c398d69db92a35dfea4c6b250b8360\">Lea tambi\u00e9n: <\/strong><a href=\"https:\/\/noticel.com\/en\/junta-fiscal\/ahora\/20210512\/hasta-ahora-los-cabilderos-de-la-estadidad-van-trabajar-gratis-por-decision-de-la-junta\/\" id=\"link-411be3c85320717396f9a9b4a0012519\">Hasta ahora, los cabilderos de la estadidad van trabajar gratis por decisi\u00f3n de la Junta<\/a><\/p>\n<p>\u201cEste resultado parcial no constituye y tampoco debe interpretarse, como un resultado final o la proyecci\u00f3n, pues todav\u00eda hay votos proceso de de contabilizaci\u00f3n o escrutinio\u201d, afirm\u00f3 Rosado Colomer al filo de las 10:00 p.m.<\/p>\n<p>\u201cEl resultado final y oficial de este evento electoral solo ser\u00e1 y solo se anunciar\u00e1 al final el escrutinio general\u201d, agreg\u00f3 desde la sede de la CEE en Hato Rey.<\/p>\n<p>Seg\u00fan esa certificaci\u00f3n, Elizabeth Torres Rodr\u00edguez, conocida en las redes sociales como la \u201cPremisa Inarticulada\u201d encabezaba el cuadro de los candidatos que se disputaban las cuatro posiciones a la C\u00e1mara de Representantes de Estados Unidos con 54,258 votos. Le segu\u00edan Roberto Lefranc Fortu\u00f1o con 41,195, Mar\u00eda \u201cMayita\u201d Mel\u00e9ndez Altieri\u00a0con 36,207,\u00a0Adriel Jared V\u00e9lez\u00a0Torres con 27,618, Jorge Iv\u00e1n Rodr\u00edguez Feliciano\u00a0con 26,496, y\u00a0Ricardo Marrero Passapera\u00a0con 26,149.<\/p>\n<p>La certificaci\u00f3n tambi\u00e9n consign\u00f3 60,826 votos por nominaci\u00f3n directa.<\/p>\n<p>Pero no mencion\u00f3 por ninguna parte el nombre del exgobernador Ricardo Rossell\u00f3 Nevares, quien de acuerdo a los datos y proyecciones del PNP, se coronar\u00e1 como el delegado a la C\u00e1mara que recibi\u00f3 la mayor cantidad de votos.<\/p>\n<p>\u201cDesde que empezamos a contar, ha estado en la delantera\u201d,  indic\u00f3 Edwin Mundo, comisionado electoral alterno del PNP.<\/p>\n<p><strong id=\"strong-7675582ce1538829b16fd2011c2ff9d0\">Lea tambi\u00e9n:<\/strong> <a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/top-stories\/20210509\/los-tropiezos-de-la-eleccion-especial-proestadidad\/\" id=\"link-5db15c78a5fa4dd6a95f89865ea05e47\">Los tropiezos de la elecci\u00f3n especial proestadidad<\/a><\/p>\n<p>Los n\u00fameros que ofreci\u00f3 al filo de las 9:30 p.m. colocaban a Rossell\u00f3 Nevares en el primer escalaf\u00f3n de la lista con 56,223 sufragios. Le segu\u00edan Torres Rodr\u00edguez (50,826), Lefranc Fortu\u00f1o (38,634), Mel\u00e9ndez Altieri (34,070), V\u00e9lez Torres (25,883), Rodr\u00edguez Feliciano (24,681) y Marrero Passapera (24,704).<\/p>\n<p>Apoyado en la tendencia de sus datos, Mundo anticip\u00f3 que al final de escrutinio general Rossell\u00f3 Nevares lograr\u00e1 unos 60,000 votos y mantendr\u00e1 una distancia de 10,000 por encima de la pr\u00f3xima candidata.<\/p>\n<p>Se\u00f1al\u00f3 tambi\u00e9n que otras figuras conocidas el exalcalde de San Juan\u00a0Jorge Santini, el exmonitor de la Polic\u00eda\u00a0Arnaldo Claudio\u00a0y la exsenadora\u00a0Miriam Ramp\u00edez de Ferrer\u00a0quedaron fuera del cuadro general de candidatos porque lograron una cantidad peque\u00f1a de sufragios.<\/p>\n<p><strong id=\"strong-75c7244d5091bafb3234f3439910e4a2\">La delegaci\u00f3n del Senado<\/strong><\/p>\n<p>En el Senado, la certificaci\u00f3n oficial de la CEE y los datos recopilados por el PNP coincidieron.<\/p>\n<p>La exsenadora Melinda Romero Donnelly se manten\u00eda c\u00f3moda en el primer lugar con 49,808 votos, seguida por la exsecretaria de Correcci\u00f3n Zoraida Bux\u00f3 Santiago\u00a0con 39,513,\u00a0V\u00edctor P\u00e9rez Rentas\u00a0con 24,084 y\u00a0Roberto L\u00f3pez\u00a0con 16,714. Las dos personas con el mayor n\u00famero de votos formar\u00e1n la delegaci\u00f3n al Senado federal.<\/p>\n<p>La certificaci\u00f3n tambi\u00e9n report\u00f3 14,644 votos por nominaci\u00f3n directa, que en su mayor\u00eda correspond\u00edan a personas que a\u00f1adieron el nombre de Rossell\u00f3 Nevares a mano para ocupar cargos en ambas delegaciones, pese a que el movimiento que impuls\u00f3 su candidatura lo postulaba para una posici\u00f3n en la delegaci\u00f3n de la C\u00e1mara.<\/p>\n<p>Seg\u00fan Mundo, Rossell\u00f3 Nevares terminar\u00e1 en la quinta posici\u00f3n en esta papeleta.<\/p><div class=\"notic-content-middle\" id=\"notic-4179742182\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>\u201c(La CEE) no tiene ese dato (voto \u2018write-in\u2019) y ma\u00f1ana (lunes) el pueblo de Puerto Rico puede darse la sensaci\u00f3n de que hay una certificaci\u00f3n que no es la correcta. No es la correcta porque la Comisi\u00f3n no tiene el desglose de esos votos. El PNP los tiene y los ha podido ofrecer a ustedes porque hemos estado haciendo el trabajo con nuestros funcionarios de colegios que nos han dado un acta con los resultados de cada colegio\u201d, indic\u00f3.<\/p>\n<p>Luego de que Rossell\u00f3 Nevares anunci\u00f3 que interesaba la candidatura por nominaci\u00f3n directa, el PNP intent\u00f3 sin \u00e9xito que la CEE adjudicara los votos \u2018write-in\u2019 la noche del evento. El ente electoral, sin embargo, no objet\u00f3 que la colectividad adoptara el uso de un acta para que detallara esos votos.<\/p>\n<p><strong id=\"strong-33563412c9287e3270d896b1b78be802\">Lea tambi\u00e9n: <\/strong><a href=\"https:\/\/noticel.com\/en\/politica\/ahora\/top-stories\/20210516\/eleccion-especial-arranca-con-pocos-funcionarios-de-colegios-y-votantes\/\" id=\"link-0110884723a6301c93b7ec530b48dd03\">Elecci\u00f3n especial arranca con pocos funcionarios de colegios y votantes<\/a><\/p>\n<p>\u201cYo le inform\u00e9 al Gobernador en la tarde los cuatro iban a salir en la C\u00e1mara y los dos del Senado porque no ha variado y los que llevamos un tiempito en esto ya tenemos unas m\u00e9tricas que utilizamos para saber qui\u00e9nes van a salir\u201d, afirm\u00f3 Mundo.<\/p>\n<p>El gobernador y presidente del PNP, Pedro Pierluisi Urrutia, se encuentra en un viaje oficial en la capital federal, pero antes de partir vot\u00f3 por adelantado.<\/p>\n<p>La Ley que creo la consulta, que se celebr\u00f3 a un costo de $1.8 millones, dispone que los seis delegados especiales tienen que iniciar su gesti\u00f3n en Washington D.C. a partir del 1 de julio.<\/p>\n<p><strong id=\"strong-f08f2aa077505dbfcc8603906542506b\">Poca participaci\u00f3n<\/strong><\/p>\n<p>El Comisionado Electoral Alterno del PNP describi\u00f3 como \u201caceptable\u201d la participaci\u00f3n en la elecci\u00f3n especial y rechaz\u00f3 comparaciones con los resultados del plebiscito de noviembre pasado, donde la opci\u00f3n de la estadidad recibi\u00f3 el 52.52% de los votos o 655,505 sufragios.<\/p>\n<p>Contrario a otros eventos, no hubo filas ni el tumulto caracter\u00edstico de una elecci\u00f3n.<\/p>\n<p>El Presidente de la CEE calcul\u00f3 la cantidad de personas que sali\u00f3 a votar entre 100,000 a 150,000, pero Mundo estim\u00f3 que oscilaba entre 85,000 a 100,000.<\/p>\n<p>\u201cCompara con los resultados de los partidos ideol\u00f3gicos\u201d, apunt\u00f3.<\/p>\n<p>Al justificar la baja participaci\u00f3n, Mundo se\u00f1al\u00f3 que en las elecciones pasadas el Partido Independentista Puertorrique\u00f1o logr\u00f3 64,409 votos y el Proyecto Dignidad 62,295.<\/p>\n<p>Tambi\u00e9n neg\u00f3 que se hubieran cerrado colegios de votaci\u00f3n por falta de funcionarios. Pero el Presidente de la CEE mencion\u00f3 un caso en Caguas, que el comisionado electoral del Movimiento Victoria  Ciudadana, Olvin Valent\u00edn Rivera, ya hab\u00eda identificado a este medio digital.<\/p>\n<p>\u201cTenemos siete centros de votaci\u00f3n que no abrieron. De hecho me dijeron que son ocho. Uno fue objeto de discusi\u00f3n en el d\u00eda de ayer (s\u00e1bado) en Lares. Dos colegios fueron en San Juan, un colegio fue en Caguas, uno fue en Cidra y un colegio fue en Juana D\u00edaz\u201d, indic\u00f3 Rosado Colomer a preguntas de las prensa.<\/p>\n<p>\u201cEl \u00fanico que tengo confirmaci\u00f3n fue el de Lares, que ten\u00eda que ver con los accesos por las lluvias. El otro es en Caguas porque no hab\u00eda funcionarios para ese colegio y tuvieran que trasladar el material electoral a otro colegio. En San Juan, un colegio no se abri\u00f3 porque no ten\u00eda facilidades. Las dem\u00e1s no las tengo (las razones)\u201d, agreg\u00f3.<\/p>\n<p>Rosado Colomer tambi\u00e9n reconoci\u00f3 que en esta elecci\u00f3n no se inutilizaron las papeletas como suele hacerse ante un reclamo de Rossell\u00f3 Nevares. Al abordar una situaci\u00f3n ocurrida en un hospital y denunciada por el comisionado electoral del Partido Popular Democr\u00e1tica, Gerardo Curz, mencion\u00f3 que las papeletas que sobraron se guardaron en maletines con sello acompa\u00f1adas de una acta. \u201cPero la informaci\u00f3n que tengo es que no fueron necesarias as\u00ed que se mantienen en su malet\u00edn resguardadas\u201d, afirm\u00f3.<\/p>\n<p>Adem\u00e1s, una funcionaria de un colegio en Caguas que pesc\u00f3 votos por tel\u00e9fono enfrentar\u00e1 cargos por violaciones al C\u00f3digo Electoral vigente por alterar documentos oficiales al emitir votos por otras personas. Por esa violaci\u00f3n de Ley, podr\u00eda enfrentar hasta ocho a\u00f1os de c\u00e1rcel.<\/p>\n<p>Mira la certificaci\u00f3n de la CEE aqu\u00ed.<\/p>","protected":false},"excerpt":{"rendered":"<p>La CEE no reporta el nombre de las personas que reciben votos por nominaci\u00f3n directa la noche del evento, as\u00ed que ayer el PNP ofreci\u00f3 esa informaci\u00f3n de manera extraoficial. La elecci\u00f3n especial para escoger a los seis delegados de la delegaci\u00f3n congresional pintaba como un evento insulso, pero la incursi\u00f3n a \u00faltima hora del [&hellip;]<\/p>","protected":false},"author":25,"featured_media":846467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-777975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/777975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=777975"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/777975\/revisions"}],"predecessor-version":[{"id":846496,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/777975\/revisions\/846496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/846467"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=777975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=777975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=777975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}