{"id":77793,"date":"2017-09-27T00:00:00","date_gmt":"2017-09-27T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/galeria\/20170927\/el-paso-de-maria-por-aguadilla\/"},"modified":"2025-07-16T14:33:38","modified_gmt":"2025-07-16T14:33:38","slug":"el-paso-de-maria-por-aguadilla","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/videos-y-fotos\/fotos\/20170927\/el-paso-de-maria-por-aguadilla\/","title":{"rendered":"El paso de Mar\u00eda por Aguadilla"},"content":{"rendered":"<p><i>El paso de Mar\u00eda por Aguadilla<\/i><\/p><div class=\"notic-content-middle\" id=\"notic-507502524\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Lacosta de Aguadilla fue transformada por la fuerza del hurac\u00e1n Mar\u00eda. Las im\u00e1genes muestran la destrucci\u00f3n causada en el Crashboat as\u00ed como el Paseo Real Marina en el casco urbano.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>El paso de Mar\u00eda por Aguadilla Lacosta de Aguadilla fue transformada por la fuerza del hurac\u00e1n Mar\u00eda. Las im\u00e1genes muestran la destrucci\u00f3n causada en el Crashboat as\u00ed como el Paseo Real Marina en el casco urbano.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>","protected":false},"author":0,"featured_media":449816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[60],"tags":[],"class_list":["post-77793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotos"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=77793"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77793\/revisions"}],"predecessor-version":[{"id":449912,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77793\/revisions\/449912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/449816"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=77793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=77793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=77793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}