{"id":77132,"date":"2012-06-22T00:00:00","date_gmt":"2012-06-22T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20120622\/espana-se-enfrenta-a-la-historia-en-la-eurocopa\/"},"modified":"2025-07-16T15:20:33","modified_gmt":"2025-07-16T15:20:33","slug":"espana-se-enfrenta-a-la-historia-en-la-eurocopa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20120622\/espana-se-enfrenta-a-la-historia-en-la-eurocopa\/","title":{"rendered":"Espa\u00f1a se enfrenta a la historia en la Eurocopa"},"content":{"rendered":"<p>Donetsk (Ucrania) &#8211; Espa\u00f1a deber\u00e1 romper con la historia, vencer por primera vez en un partido oficial a Francia, si quiere aspirar a retener el t\u00edtulo continental y seguir su camino en la Eurocopa 2012 hacia la triple corona, en un duelo de cuartos que trae a la memoria errores del pasado, Arconada y Ra\u00fal, y una dolorosa eliminaci\u00f3n, la \u00faltima de un Mundial, ante Zinedine Zidane.<\/p>\n<p>Im\u00e1genes repletas de resignaci\u00f3n para el f\u00fatbol espa\u00f1ol, clavadas en todas las generaciones de futbolistas. Hasta en la actual, la m\u00e1s exitosa, la que ha conquistado Europa y el mundo. Luis Miguel Arconada sintiendo como se le escapaba el bal\u00f3n por debajo del cuerpo tras la falta de Michel Platini en la final de la Eurocopa de 1984. Ra\u00fal Gonz\u00e1lez aisl\u00e1ndose de todo, con la mirada perdida, con el dolor de mandar al limbo las ilusiones de Espa\u00f1a en la Eurocopa del 2000 desde el punto de penalti. El sentimiento de fracaso en el Mundial 2006, en octavos, ante una Francia envejecida que sac\u00f3 el orgullo de campe\u00f3n liderada por Zidane.<\/p>\n<p>El destino ha querido cruzar a dos candidatas al t\u00edtulo en el primer cruce. Duelo a vida o muerte. \u00c9xito o fracaso. Un despiste de Francia, ante una selecci\u00f3n ya eliminada como Suecia, lo provoc\u00f3. Su peor partido del campeonato. Como Espa\u00f1a ante Croacia. La campeona del mundo camin\u00f3 por el alambre. Recurri\u00f3 a su santo, Iker Casillas, y acab\u00f3 ganando uno de esos partidos que antes le mandaban a la calle a las primeras de cambio.<\/p>\n<p>La campeona de Europa y el mundo se siente observada. Es el rival a batir. Todos sus adversarios cambian su sistema para frenar la brillantez de su centro del campo. Y Vicente Del Bosque mantiene la identidad. El mismo equipo. Ante Francia puede repetir por primera vez en cuatro a\u00f1os de seleccionador un once titular en tres partidos consecutivos.<\/p>\n<p>Lo har\u00e1 si finalmente mantiene a Fernando Torres en punta. La inspiraci\u00f3n goleadora del &#8216;ni\u00f1o&#8217; tras su doblete a Irlanda se vino abajo con Croacia. No entr\u00f3 en juego. Por detr\u00e1s llega con fuerza Cesc F\u00e1bregas que ha brillado siempre que ha tenido oportunidad en la Eurocopa. Comenz\u00f3 de titular marcando a Italia. Marc\u00f3 con rabia a Irlanda en su regreso al banco e invent\u00f3 el pase que dej\u00f3 solo a Andr\u00e9s Iniesta en el gol de Jes\u00fas Navas a Croacia.<\/p>\n<p>El resto, los otros diez titulares, son fijos para Del Bosque. Prefiere el t\u00e9cnico salmantino que le acusen de inmovilismo antes que de no tener las ideas claras. No hay lesiones ni sanciones. Cinco apercibidos -Arbeloa, Jordi Alba, Xabi Alonso, Fernando Torres y Javi Mart\u00ednez- pero sustitutos preparados para rendir. Futbolistas con ansias de brillar que han aparecido minutos o ni han debutado.<\/p>\n<p>Espa\u00f1a lidera todas las estad\u00edsticas en ataque y defensa de la Eurocopa 2012. La que m\u00e1s goles marca, menos encaja, m\u00e1s posesi\u00f3n tiene y m\u00e1s chuta a la porter\u00eda rival. Ante Croacia le falt\u00f3 profundidad y qued\u00f3 en entredicho el aspecto f\u00edsico. Son dudas que tienen que resolver ante Francia, el d\u00eda que Xabi Alonso pasar\u00e1 a integrar el &#8216;club de los cien&#8217;. El quinto futbolista espa\u00f1ol que llega al centenar de internacionalidades tras Zubizarreta, Casillas, Ra\u00fal y Xavi Hern\u00e1ndez.<\/p>\n<p>La selecci\u00f3n francesa se aferrar\u00e1 a la costumbre y a la historia para doblegar a Espa\u00f1a, un rival que a priori es favorito para ganar a los hombres de Laurent Blanc, pero que jam\u00e1s ha vencido al combinado &#8216;blue&#8217; en un partido de competici\u00f3n oficial.<\/p>\n<p>Es un dato al que se agarran los rivales de la &#8216;Roja&#8217;, que saben que por una vez son ellos los que tienen que pensar un sistema para acabar con la hegemon\u00eda espa\u00f1ola en el mundo del f\u00fatbol. Anteriormente, siempre fue al rev\u00e9s. Espa\u00f1a jugaba asustada y con complejos y era eliminada por Francia de la competici\u00f3n que se estaba disputando.<\/p>\n<p>Ahora se medir\u00e1n a una selecci\u00f3n francesa en pleno ambiente enrarecido tras la derrota ante Suecia en el \u00faltimo duelo de la fase de grupos. Todo iba sobre ruedas hasta que Zlatan Ibrahimovich amarg\u00f3 la fiesta a los franceses, que hasta ese momento hab\u00edan tenido un camino pl\u00e1cido por el torneo.<\/p>\n<p>Tras el encuentro, en el vestuario hubo roces, tal y como despu\u00e9s reconoci\u00f3 el t\u00e9cnico Laurent Blanc, que abronc\u00f3 a sus jugadores por la imagen que ofrecieron. Los fantasmas de Sud\u00e1frica, donde hubo verdaderos motines contra el anterior entrenador, Raymond Domenech, volvieron a llamar a la puerta de &#8216;les blues&#8217;. Sin embargo, el problema era mucho menor y posteriormente, el segundo t\u00e9cnico, Alain Boghossian, anunci\u00f3 que el &#8216;incendio&#8217; se hab\u00eda &#8216;extinguido&#8217;.<\/p>\n<p>De puertas hacia fuera parece que s\u00f3lo se habla de f\u00fatbol y de c\u00f3mo contrarrestar a Espa\u00f1a. Y, como hicieran Italia y Croacia, Francia podr\u00eda cambiar de t\u00e1ctica y poner m\u00e1s centrocampistas para ahogar a los medios espa\u00f1oles. De este modo, el trivote formado por Yoyah Cabaye, Aloy Diarra y Yann M&#8217;Vila podr\u00eda hacer acto de presencia. M\u00fasculo y poco dominio del bal\u00f3n para destruir y no construir.<\/p>\n<p>Los dos \u00faltimos fueron titulares ante Croacia, mientras que Cabaye acaba de recuperarse de una lesi\u00f3n. La aparici\u00f3n del medio del Newcastle obligar\u00eda a Blanc a prescindir de uno de los tres jugadores que se ubican por detr\u00e1s de Karim Benzema. Hatem Ben Arfa y Jeremy Menez son candidatos a desaparecer. Mientras, en la defensa, habr\u00e1 un cambio obligado. El sancionado Phillipe Mexes dejar\u00e1 su sitio en el centro de la defensa a Laurent Koscielny, que se estrenar\u00e1 en el torneo.<\/p>\n<p>En el trasfondo del enfrentamiento, junto a la motivaci\u00f3n de avanzar a semifinales de una gran competici\u00f3n, est\u00e1 el historial a favor de Francia -seis partidos oficiales con cinco derrotas y un empate para Espa\u00f1a- y el acicate de los gui\u00f1oles franceses con sus acusaciones de dopaje al deporte espa\u00f1ol.<\/p>\n<p>Alineaciones probables:<\/p>\n<p>Espa\u00f1a: Casillas; Arbeloa, Piqu\u00e9, Sergio Ramos, Jordi Alba; Busquets, Xabi Alonso, Xavi; Iniesta, Silva y Fernando Torres.<\/p>\n<p>Francia: Lloris; Debuchy, Rami, Koscielny, Clichy; Diarra, M&#8217;Vila, Cabaye; Nasri, Rib\u00e9ry y Benzema.<\/p>\n<p>\u00c1rbitro: Nicola Rizzoli (ITA).<\/p>\n<p>Estadio: Donbass Arena.<\/p>\n<p>Hora: 20:45.<\/p>","protected":false},"excerpt":{"rendered":"<p>Donetsk (Ucrania) &#8211; Espa\u00f1a deber\u00e1 romper con la historia, vencer por primera vez en un partido oficial a Francia, si quiere aspirar a retener el t\u00edtulo continental y seguir su camino en la Eurocopa 2012 hacia la triple corona, en un duelo de cuartos que trae a la memoria errores del pasado, Arconada y Ra\u00fal, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":453416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-77132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=77132"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77132\/revisions"}],"predecessor-version":[{"id":453417,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77132\/revisions\/453417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/453416"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=77132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=77132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=77132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}