{"id":77069,"date":"2015-03-23T00:00:00","date_gmt":"2015-03-23T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20150323\/cientos-hacen-fila-para-ver-el-ataud-de-ricardo-iii\/"},"modified":"2025-07-16T15:26:02","modified_gmt":"2025-07-16T15:26:02","slug":"cientos-hacen-fila-para-ver-el-ataud-de-ricardo-iii","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20150323\/cientos-hacen-fila-para-ver-el-ataud-de-ricardo-iii\/","title":{"rendered":"Cientos hacen fila para ver el ata\u00fad de Ricardo III"},"content":{"rendered":"<p>Cientos de personas esperan hoy a las puertas de la catedral de Leicester para ver el ata\u00fad con los restos del rey ingles Ricardo III (1452-1485), que ayer recorrieron en procesi\u00f3n f\u00fanebre el centro hist\u00f3rico de la ciudad brit\u00e1nica como anticipo del entierro oficial, que tendr\u00e1 lugar el jueves.<\/p>\n<p>Alrededor de dos mil personas est\u00e1n haciendo una fila de alrededor de cuatro horas de espera para contemplar el f\u00e9retro de madera con los huesos del monarca.<\/p>\n<p>Las colas comenzaron a formarse hoy desde primera hora de la ma\u00f1ana, antes incluso de que la catedral de Leicester (centro de Inglaterra) abriese sus puertas, a las nueve.<\/p>\n<p>Personas de todo el mundo se han acercado hasta la catedral para ver los restos del monarca, y esperan con buen humor las largas filas, que apenas avanzan pocos metros a la hora.<\/p>\n<p>&#8216;Yo fui una de las afortunadas en conseguir una invitaci\u00f3n. C\u00f3mo no voy a venir a ver todo esto? Siempre me ha interesado la historia y, en especial, la monarqu\u00eda brit\u00e1nica&#8217;, dijo a la cadena BBC Rebecca McCole, que ha viajado desde New Hampshire (Estados Unidos), para ver el f\u00e9retro de Ricardo III.<\/p>\n<p>En la cola a las puertas de la catedral, McCole se\u00f1al\u00f3 adem\u00e1s que para ella esta visita est\u00e1 siendo &#8216;muy inspiradora&#8217;.<\/p>\n<p>Por su parte, otra de las personas que esperaban en la fila, John Wesseldine, dijo que hab\u00eda sacado a sus dos hijos, Jayden y Jenson, de 10 a\u00f1os, del colegio para acudir a la catedral.<\/p><div class=\"notic-content-middle\" id=\"notic-1340226348\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;El colegio no iba a organizar un viaje para visitar la catedral, as\u00ed que pap\u00e1 nos dijo que nos llevar\u00eda a ver el ata\u00fad del Rry&#8217;, declar\u00f3 Jayden.<\/p>\n<p>M\u00e1s de 35,000 personas acompa\u00f1aron ayer los restos de Ricardo III por las calles de Leicester, en una procesi\u00f3n f\u00fanebre por los lugares m\u00e1s emblem\u00e1ticos de la ciudad asociados con el rey, antes de entrar en la catedral.<\/p>\n<p>El f\u00e9retro permanecer\u00e1 expuesto en el templo hasta el pr\u00f3ximo jueves, cuando se celebrar\u00e1 una ceremonia de entierro en la que participar\u00e1 el arzobispo de Canterbury, Justin Welby (protestante), as\u00ed como representantes de la Iglesia Cat\u00f3lica y de otras religiones.<\/p>\n<p>&#8216;El momento m\u00e1s importante llegar\u00e1 el jueves, cuando el arzobispo de Canterbury se unir\u00e1 a nosotros&#8217;, dijo el obispo de Leicester, Tim Stevens.<\/p>\n<p>Los restos de Ricardo III fueron hallados por arque\u00f3logos de la Universidad de Leicester en 2012 bajo un aparcamiento municipal, donde se conservaba parte del antiguo monasterio donde el rey fue enterrado por primera vez.<\/p>\n<p>Las pruebas que compararon esos restos con el ADN de los descendientes de la hermana mayor del monarca confirmaron la identidad de Ricardo III, cuya muerte signific\u00f3 el fin de la Guerra de las Dos Rosas (1455-1485) entre los partidarios de la Casa de Lancaster y de la Casa de York.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cientos de personas esperan hoy a las puertas de la catedral de Leicester para ver el ata\u00fad con los restos del rey ingles Ricardo III (1452-1485), que ayer recorrieron en procesi\u00f3n f\u00fanebre el centro hist\u00f3rico de la ciudad brit\u00e1nica como anticipo del entierro oficial, que tendr\u00e1 lugar el jueves. Alrededor de dos mil personas est\u00e1n [&hellip;]<\/p>","protected":false},"author":0,"featured_media":453827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-77069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=77069"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77069\/revisions"}],"predecessor-version":[{"id":453829,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/77069\/revisions\/453829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/453827"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=77069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=77069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=77069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}