{"id":76808,"date":"2014-09-11T00:00:00","date_gmt":"2014-09-11T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/en-serio\/mundo\/20140911\/burger-king-presenta-su-cheeseburger-negro\/"},"modified":"2025-07-16T15:47:08","modified_gmt":"2025-07-16T15:47:08","slug":"burger-king-presenta-su-cheeseburger-negro","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20140911\/burger-king-presenta-su-cheeseburger-negro\/","title":{"rendered":"Burger King presenta su &#8216;cheeseburger negro&#8217;"},"content":{"rendered":"<p>La cadena de comida r\u00e1pida Burger King present\u00f3 recientemente una hamburgesa en la que el pan y el queso est\u00e1n te\u00f1idos de color negro<\/p>\n<p>Se trata del &#8216;Kuro Burger&#8217;, que est\u00e1 a la venta en Jap\u00f3n desde el 2012, pero este a\u00f1o le a\u00f1adieron el queso de color negro.<\/p>\n<p>El tinte se logra con carb\u00f3n. Tambi\u00e9n hay una salsa oscura confeccionada con tinta de calamar, ajo y cebolla.<\/p><div class=\"notic-content-middle\" id=\"notic-441032619\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Seg\u00fan reporta <a href=\"http:\/\/metro.co.uk\/2014\/09\/10\/burger-king-in-japan-launches-black-cheeseburger-the-world-recoils-in-horror-4863751\/?ito=facebook\">Metro UK<\/a>, se puede pedir la hamburguesa con o sin ensalada (Kuro Diamond y Kuro Pearl).<\/p>\n<p>El &#8216;Kuro Burger&#8217; s\u00f3lo est\u00e1 a la venta en Jap\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>La cadena de comida r\u00e1pida Burger King present\u00f3 recientemente una hamburgesa en la que el pan y el queso est\u00e1n te\u00f1idos de color negro Se trata del &#8216;Kuro Burger&#8217;, que est\u00e1 a la venta en Jap\u00f3n desde el 2012, pero este a\u00f1o le a\u00f1adieron el queso de color negro. El tinte se logra con carb\u00f3n. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":455425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-76808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/76808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=76808"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/76808\/revisions"}],"predecessor-version":[{"id":455426,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/76808\/revisions\/455426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/455425"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=76808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=76808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=76808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}