{"id":7641,"date":"2019-12-23T00:00:00","date_gmt":"2019-12-23T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/policiacas\/20191223\/arrestan-a-un-individuo-que-fue-agredido-en-cabo-rojo\/"},"modified":"2025-07-20T20:38:44","modified_gmt":"2025-07-20T20:38:44","slug":"arrestan-a-un-individuo-que-fue-agredido-en-cabo-rojo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20191223\/arrestan-a-un-individuo-que-fue-agredido-en-cabo-rojo\/","title":{"rendered":"Arrestan a un individuo que fue agredido en Cabo Rojo"},"content":{"rendered":"<p><i>Contra \u00e9ste pesaba una orden de arresto del 2018<\/i><\/p>\n<p>Las autoridades informaron que a eso de las 10:15 de la noche del domingo se report\u00f3 una agresi\u00f3n agravada en la calle Uni\u00f3n, intersecci\u00f3n con la calle Sol del barrio Corozo en Cabo Rojo.<\/p>\n<p>De acuerdo con el informe policiaco, Xavier Padilla V\u00e9lez de 34 a\u00f1os aleg\u00f3 que caminaba por el lugar antes mencionado cerca de su residencia, cuando se le acerc\u00f3 un individuo vestido de negro y con una gorra y portando un arma de fuego con la que le apunt\u00f3.<\/p>\n<p>Luego de un forcejeo, el perjudicado fue agredido en la parte posterior de la cabeza con la culata del arma, seg\u00fan aleg\u00f3 a las autoridades.<\/p><div class=\"notic-content-middle\" id=\"notic-3009172063\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Padilla V\u00e9lez, fue transportado por param\u00e9dicos al Centro M\u00e9dico de Mayag\u00fcez, donde fue atendido por el doctor Trujillo, quien le tom\u00f3 varios puntos de sutura. Su condici\u00f3n es estable.<\/p>\n<p>La Polic\u00eda detall\u00f3 que Contra Padilla V\u00e9lez hab\u00eda una orden de arresto pendiente desde el mes de agosto de 2018, expedida por el juez Luis O. V\u00e9lez del Tribunal de Primera Instancia de Mayag\u00fcez, con cinco mil d\u00f3lares de fianza por violaci\u00f3n al art\u00edculo 4.04 de la Ley de Sustancias Controladas.<\/p>\n<p>\u00c9ste fue arrestado y qued\u00f3 bajo custodia polic\u00edaca por agentes del distrito de Mayag\u00fcez, hasta que sea dado de alta. Posteriormente ser\u00e1 llevado a un magistrado para diligenciar la orden de arresto y de no prestar la fianza impuesta, ser\u00e1 ingresado en alguna instituci\u00f3n carcelaria.<\/p>\n<p>El agente Nelson Gonz\u00e1lez de la Divisi\u00f3n de Homicidios del Cuerpo de Investigaciones Criminales (CIC) de Mayag\u00fcez, se hizo cargo de la investigaci\u00f3n. El agente Heriberto Medina de Servicios T\u00e9cnicos trabaj\u00f3 la escena y levant\u00f3 como evidencia un casquillo de bala. Inicialmente se hab\u00eda indicado que la querella estaba relacionada con una persona herida de bala.<\/p>","protected":false},"excerpt":{"rendered":"<p>Contra \u00e9ste pesaba una orden de arresto del 2018 Las autoridades informaron que a eso de las 10:15 de la noche del domingo se report\u00f3 una agresi\u00f3n agravada en la calle Uni\u00f3n, intersecci\u00f3n con la calle Sol del barrio Corozo en Cabo Rojo. De acuerdo con el informe policiaco, Xavier Padilla V\u00e9lez de 34 a\u00f1os [&hellip;]<\/p>","protected":false},"author":0,"featured_media":540888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[],"class_list":["post-7641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/7641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=7641"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/7641\/revisions"}],"predecessor-version":[{"id":540889,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/7641\/revisions\/540889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/540888"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=7641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=7641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=7641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}