{"id":76334,"date":"2012-05-25T00:00:00","date_gmt":"2012-05-25T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20120525\/heridos-de-bala-en-carolina-rio-piedras-y-arecibo\/"},"modified":"2025-07-16T16:21:24","modified_gmt":"2025-07-16T16:21:24","slug":"heridos-de-bala-en-carolina-rio-piedras-y-arecibo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20120525\/heridos-de-bala-en-carolina-rio-piedras-y-arecibo\/","title":{"rendered":"Heridos de bala en Carolina, R\u00edo Piedras y Arecibo"},"content":{"rendered":"<p>En las \u00faltimas horas, y a parte de un doble asesinato en Barrio Obrero, se produjeron varios tiroteos en los que resultaron heridos varios j\u00f3venes en Carolina, R\u00edo Piedras y Arecibo.<\/p>\n<p>Un hombre result\u00f3 herido de bala anoche mientras se encontraba frente a su residencia en la calle Parque Florida de la urbanizaci\u00f3n Villa Fontana Park en Carolina, inform\u00f3 a la Polic\u00eda.<\/p>\n<p>Seg\u00fan la investigaci\u00f3n preliminar de la Polic\u00eda, Jean Luis Castro Rivera de 61 a\u00f1os se encontraba en referido lugar, cuando un sujeto portando un arma de fuego se le acerc\u00f3 y le arrebat\u00f3 una cadena del cuello, el asaltante intent\u00f3 entrar a la residencia, comenzando un forcejeo, en el que result\u00f3 herido Castro Rivera en tres ocasiones.<\/p>\n<p>Castro Rivera fue transportado al Centro M\u00e9dico en R\u00edo Piedras, donde se le diagnostic\u00f3 una herida de bala en el f\u00e9mur, una herida en el abdomen y otra en la mano izquierda.<\/p>\n<p>Su condici\u00f3n es de cuidado.<\/p>\n<p>Por otro lado, un joven result\u00f3 herido de bala en un incidente reportado a eso de las 9:40 de la noche de ayer, en la cancha bajo techo de la urbanizaci\u00f3n Reparto Sevilla, en R\u00edo Piedras.<\/p><div class=\"notic-content-middle\" id=\"notic-3191909977\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Seg\u00fan se inform\u00f3, Luis Mel\u00e9ndez Ramos, de 19 a\u00f1os y vecino de R\u00edo Piedras, aleg\u00f3 que mientras se encontraba jugando baloncesto en el lugar, escuch\u00f3 varias detonaciones resultando herido de bala en el muslo izquierdo.<\/p>\n<p>Mel\u00e9ndez Ramos fue transportado al CDT de R\u00edo Piedras donde el Dr. Casimir Lic. 15875 diagnostic\u00f3 lo anterior, refiri\u00e9ndolo en condici\u00f3n estable al Hospital Centro M\u00e9dico de R\u00edo Piedras.<\/p>\n<p>Tambi\u00e9n en horas de la noche del jueves un hombre result\u00f3 herido de bala en el garaje de gasolina Arecibo Service Station de la carretera PR-651, sector Juncos de Arecibo, inform\u00f3 la Polic\u00eda.<\/p>\n<p>Seg\u00fan la informaci\u00f3n preliminar, mientras el joven Gustavo Rivera Acevedo, de 19 a\u00f1os residente de Arecibo, se encontraba en el lugar antes mencionado un individuo se le acerc\u00f3 y le reclam\u00f3 sobre una deuda de dinero y acto seguido sac\u00f3 un arma de fuego y le hizo un impacto de bala.<\/p>\n<p>El joven fue transportado al Hospital Susoni de Arecibo, atendido por el m\u00e9dico de turno quien diagn\u00f3stico una herida de bala en la pierna izquierda con posible fractura y lo refiri\u00f3 al Centro M\u00e9dico de R\u00edo Piedras, en condici\u00f3n estable.<\/p>","protected":false},"excerpt":{"rendered":"<p>En las \u00faltimas horas, y a parte de un doble asesinato en Barrio Obrero, se produjeron varios tiroteos en los que resultaron heridos varios j\u00f3venes en Carolina, R\u00edo Piedras y Arecibo. Un hombre result\u00f3 herido de bala anoche mientras se encontraba frente a su residencia en la calle Parque Florida de la urbanizaci\u00f3n Villa Fontana [&hellip;]<\/p>","protected":false},"author":0,"featured_media":457915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-76334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/76334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=76334"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/76334\/revisions"}],"predecessor-version":[{"id":457917,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/76334\/revisions\/457917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/457915"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=76334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=76334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=76334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}