{"id":7614,"date":"2020-01-14T00:00:00","date_gmt":"2020-01-14T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/educacion\/top-stories\/20200114\/datos-el-numero-de-escuelas-declaradas-aptas-y-no-aptas-por-region\/"},"modified":"2025-07-20T17:39:48","modified_gmt":"2025-07-20T17:39:48","slug":"datos-el-numero-de-escuelas-declaradas-aptas-y-no-aptas-por-region","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200114\/datos-el-numero-de-escuelas-declaradas-aptas-y-no-aptas-por-region\/","title":{"rendered":"Datos: El n\u00famero de escuelas declaradas &#8216;aptas&#8217; y &#8216;no aptas&#8217; por regi\u00f3n"},"content":{"rendered":"<p><i>Sigue interrogante de qu\u00e9 pasar\u00e1 con las no aptas.<\/i><\/p>\n<p>El Gobierno de Puerto Rico notific\u00f3 que unas 392 escuelas ya han sido inspeccionadas a una semana de que un sismo de magnitud 6.4 despertara toda la isla el pasado martes.<\/p>\n<p>Seg\u00fan desglos\u00f3 el secretario de Estado, Elmer Rom\u00e1n, en conferencia de prensa, la cifra de planteles inspeccionados representa el 46% del total de esas instituciones educativas. Pese a que el Secretario no detall\u00f3 con nombres las escuelas inspeccionadas, ofreci\u00f3 cifras al respecto.<\/p>\n<p>A continuaci\u00f3n el detalle ofrecido de las escuelas inspeccionadas:<\/p>\n<p><strong>Regi\u00f3n de Arecibo, 44 escuelas inspeccionadas<\/strong>: de las que 34 fueron declaradas como aptas, 4 como no aptas y 6 como aptas parcialmente.<\/p>\n<p><strong>Regi\u00f3n de Bayam\u00f3n, 44 escuelas inspeccionadas<\/strong>: 36 declaradas como aptas, 1 como no apta y 7 como aptas parcialmente.<\/p>\n<p><strong>Regi\u00f3n de Caguas, 3 escuelas inspeccionadas<\/strong>: 1 catalogada como apta y 2 como aptas parcialmente.<\/p>\n<p><strong>Regi\u00f3n de Humacao, 40 escuelas inspeccionadas<\/strong>: 32 catalogadas como aptas, 1 no apta, 7 parcialmente aptas.<\/p>\n<p><strong>Regi\u00f3n de Ponce, 110 escuelas inspeccionadas<\/strong>: 64 catalogadas como aptas, 18 como no aptas y 28 parcialmente,<\/p>\n<p><strong>Regi\u00f3n de Mayag\u00fcez, 26 escuelas inspeccionadas<\/strong>: 13 certificadas como aptas, 4 como no aptas y 9 como parcialmente aptas.<\/p>\n<p><strong>Regi\u00f3n de San Juan, 49 escuelas inspeccionadas<\/strong>: 24 certificadas como aptas, 1 como no apta y 24 como aptas parcialmente.<\/p><div class=\"notic-content-middle\" id=\"notic-305175856\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;Los ingenieros est\u00e1n tomando su tiempo en cada escuela para asegurar que el trabajo se haga completo&#8230; En cuanto a las escuelas certificadas esta informaci\u00f3n se est\u00e1 recopilando para anunciarlo. Una vez se reciban las certificaciones, se eval\u00faan con el Comit\u00e9 de Infraestructura que preside el ingeniero Carlos Pesquera. Las escuelas del sur que fueron inspeccionadas volver\u00e1n a ser visitadas&#8217;, detall\u00f3 Rom\u00e1n en una rueda de prensa en la que se actualizan datos relacionados al sismo y los afectados en la zona sur.<\/p>\n<p>Consecuentemente, pese a que el Secretario no pudo detallar qu\u00e9 ocurrir\u00e1 con las escuelas que fueron declaradas como aptas parcialmente, expuso que el Departamento de Educaci\u00f3n buscar\u00e1 alternativas, entre ellas posiblemente el &#8216;home schooling&#8217; para que los alumnos estudien.<\/p>\n<p>&#8216;Los ni\u00f1os no van a perder el semestre escolar, se van a buscar medidas alternas&#8217;, sentenci\u00f3 Rom\u00e1n.<\/p>\n<p><strong>Mira tambi\u00e9n<\/strong>: <a href=\"https:\/\/noticel.com\/en\/ahora\/educacion\/inspeccion-de-escuelas-es-incierta-lo-cierto-es-que-contratos-fueron-a-donantes\/1156764860\/\">Inspecci\u00f3n de escuelas es incierta, lo cierto es que contratos fueron a donantes<\/a><\/p>\n<p>Las inspecciones de los planteles escolares han levantado bandera de la ciudadan\u00eda desde el terremoto, luego de que se conociera que la escuela intermedia Agripina Seda en Gu\u00e1nica se desplom\u00f3 durante el sismo del pasado martes. Tras el terremoto, el Colegio de Ingenieros y Agrimensores de Puerto Rico (CIAPR) se hizo disponible para colaborar con el Gobierno de Puerto Rico gratuitamente, sin embargo, la gobernadora, Wanda V\u00e1zquez Garced anunci\u00f3 que en cambio, se contrataron tres empresas para que revisaran las estructuras educativas.<\/p>\n<p>ROV Engineering Services, E.A.S &amp; Associates y Ben\u00edtez, Ramos y Asociados (BRA), son las firmas contratadas en una movida que supone un gasto de m\u00e1s de un mill\u00f3n de d\u00f3lares. Una investigaci\u00f3n de NotiCel refleja que todos los due\u00f1os de esas empresas han sido o son donantes del Partido Nuevo Progresista (PNP).<\/p>\n<p>Particularmente, ayer el CIAPR notific\u00f3 que el Gobierno de Puerto Rico acept\u00f3 recibir sus recomendaciones, pero que inspeccionan solo las estructuras que les sean referidas, que han sido situadas en los pueblos de Gu\u00e1nica, Guayanilla, Yauco, Ponce y Mayag\u00fcez.<\/p>\n<p>&#8216;[E]l Gobierno tambi\u00e9n ha contratado a una serie de empresas locales para inspeccionar. Nosotros estamos colaborando con recomendaciones y trabajo de campo, pero debe quedar claro que el Colegio<\/p>\n<p>no tiene autorizaci\u00f3n legal para entrar a inspeccionar estructuras si el Gobierno no nos autoriza. El Gobierno es quien nos abre la puerta. Nosotros trabajamos seg\u00fan lo que nos requiere el COE, y la estructura que nos asignan&#8217;, explic\u00f3 ayer el presidente del CIAPR, Juan F. Alicea.<\/p>\n<p>Las clases suponen comenzar el 22 de enero.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sigue interrogante de qu\u00e9 pasar\u00e1 con las no aptas. El Gobierno de Puerto Rico notific\u00f3 que unas 392 escuelas ya han sido inspeccionadas a una semana de que un sismo de magnitud 6.4 despertara toda la isla el pasado martes. Seg\u00fan desglos\u00f3 el secretario de Estado, Elmer Rom\u00e1n, en conferencia de prensa, la cifra de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":539800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/7614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=7614"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/7614\/revisions"}],"predecessor-version":[{"id":539801,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/7614\/revisions\/539801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/539800"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=7614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=7614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=7614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}