{"id":75268,"date":"2013-02-19T00:00:00","date_gmt":"2013-02-19T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20130219\/alemania-deroga-la-restriccion-a-los-homosexuales-para-adoptar\/"},"modified":"2025-07-16T17:39:25","modified_gmt":"2025-07-16T17:39:25","slug":"alemania-deroga-la-restriccion-a-los-homosexuales-para-adoptar","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20130219\/alemania-deroga-la-restriccion-a-los-homosexuales-para-adoptar\/","title":{"rendered":"Alemania deroga la restricci\u00f3n a los homosexuales para adoptar"},"content":{"rendered":"<p>El Tribunal Constitucional levant\u00f3 hoy las restricciones a las parejas homosexuales para adoptar ni\u00f1os, por considerarlas discriminatorias y contrarias al principio de igualdad ante la ley.<\/p>\n<p>Los jueces del TC, con sede en Karlruhe (suroeste del pa\u00eds) dictaminaron a favor de la demanda presentada contra la actual normativa, seg\u00fan la cual un homosexual s\u00f3lo puede adoptar al hijo de su pareja si se trata de su padre o madre biol\u00f3gico.<\/p>\n<p>Esto exclu\u00eda la posibilidad de facto de que una pareja homosexual adoptase como tal a un ni\u00f1o y tuvieran que recurrir a hacerlo uno de los dos, de manera que en caso de fallecimiento o ruptura no se reconoc\u00eda la tutela del otro.<\/p>\n<p>Tras la sentencia de hoy, se reconoce la igualdad de derechos en cuestiones de adopci\u00f3n a las parejas de hecho homosexuales y heterosexuales.<\/p>\n<p>El Gobierno alem\u00e1n, coalici\u00f3n de cristianodem\u00f3cratas y liberales que dirige la canciller, Angela Merkel, recibi\u00f3 hoy el fallo del TC con &#8216;gran respeto&#8217;, indic\u00f3 en un encuentro rutinario con medios de comunicaci\u00f3n su portavoz, Steffen Seibert.<\/p><div class=\"notic-content-middle\" id=\"notic-3400810671\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Ahora, agreg\u00f3, el Ejecutivo debe &#8216;estudiar&#8217; la argumentaci\u00f3n de la sentencia del alto tribunal y, a continuaci\u00f3n, legislar en consecuencia teniendo siempre presente que lo principal es &#8216;el bienestar del ni\u00f1o&#8217;.<\/p>\n<p>En Alemania, el llamado &#8216;matrimonio homosexual&#8217; consiste en inscribirse como pareja en el registro civil, de modo equivalente a las parejas de hecho, lo que no incluye la plena equiparaci\u00f3n en materia fiscal, de derecho hereditario ni, hasta ahora, de adopci\u00f3n de hijos.<\/p>\n<p>La mayor\u00eda de parejas de hecho homosexuales que tienen ni\u00f1os adoptados lo lograron solicit\u00e1ndolo uno de ellos, en solitario, de manera que s\u00f3lo \u00e9ste consta como padre leg\u00edtimo.<\/p>\n<p>La \u00fanica excepci\u00f3n a esa norma, hasta ahora, era en el caso de los hijos biol\u00f3gicos de uno de los miembros de la pareja, que s\u00ed pod\u00eda ser adoptado por el otro.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Tribunal Constitucional levant\u00f3 hoy las restricciones a las parejas homosexuales para adoptar ni\u00f1os, por considerarlas discriminatorias y contrarias al principio de igualdad ante la ley. Los jueces del TC, con sede en Karlruhe (suroeste del pa\u00eds) dictaminaron a favor de la demanda presentada contra la actual normativa, seg\u00fan la cual un homosexual s\u00f3lo puede [&hellip;]<\/p>","protected":false},"author":0,"featured_media":463928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-75268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/75268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=75268"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/75268\/revisions"}],"predecessor-version":[{"id":463930,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/75268\/revisions\/463930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/463928"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=75268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=75268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=75268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}