{"id":74359,"date":"2016-05-12T00:00:00","date_gmt":"2016-05-12T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20160512\/discusion-por-multas-de-auto-termina-con-un-baleado\/"},"modified":"2025-07-16T18:56:24","modified_gmt":"2025-07-16T18:56:24","slug":"discusion-por-multas-de-auto-termina-con-un-baleado","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20160512\/discusion-por-multas-de-auto-termina-con-un-baleado\/","title":{"rendered":"Discusi\u00f3n por multas de auto termina con un baleado"},"content":{"rendered":"<p>Un sujeto result\u00f3 herido de bala en hechos ocurridos cerca de las 5:30 de la tarde del miercoles en la entrada al camino Los Sol\u00e1 en la carretera PR-842 en Caimito.<\/p>\n<p>De acuerdo con el informe de novedades, Alex Serrano Rosa aleg\u00f3 que luego de sostener una discusi\u00f3n con un individuo relacionado a unas multas de un auto, fue tiroteado por \u00e9ste.<\/p><div class=\"notic-content-middle\" id=\"notic-3172385583\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.facebook.com\/magnapremiumlager\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Banners_970x90 3\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/13192924\/Banners_970x90-3.png\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/13192924\/Banners_970x90-3.png 970w, https:\/\/cdn.noticel.com\/2026\/05\/13192924\/Banners_970x90-3-300x28.png 300w, https:\/\/cdn.noticel.com\/2026\/05\/13192924\/Banners_970x90-3-768x71.png 768w, https:\/\/cdn.noticel.com\/2026\/05\/13192924\/Banners_970x90-3-18x2.png 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Las autoridades indicaron que Serrano Rosa recibi\u00f3 heridas de bala en el muslo izquierdo y en la rodilla derecha con fractura en la tibia. \u00c9ste fue transportado al Hospital Metro Pav\u00eda y luego al Centro M\u00e9dico de R\u00edo Piedras en condici\u00f3n estable.<\/p>\n<p>La Divisi\u00f3n de Agresiones del Cuerpo de Investigaciones Criminales (CIC) de San Juan, investiga los hechos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un sujeto result\u00f3 herido de bala en hechos ocurridos cerca de las 5:30 de la tarde del miercoles en la entrada al camino Los Sol\u00e1 en la carretera PR-842 en Caimito. De acuerdo con el informe de novedades, Alex Serrano Rosa aleg\u00f3 que luego de sostener una discusi\u00f3n con un individuo relacionado a unas multas [&hellip;]<\/p>","protected":false},"author":0,"featured_media":469004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-74359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=74359"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74359\/revisions"}],"predecessor-version":[{"id":469006,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74359\/revisions\/469006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/469004"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=74359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=74359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=74359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}