{"id":74207,"date":"2015-03-30T00:00:00","date_gmt":"2015-03-30T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/vida\/20150330\/tranquilo-el-tiempo-para-la-semana-santa\/"},"modified":"2025-08-17T14:23:35","modified_gmt":"2025-08-17T14:23:35","slug":"tranquilo-el-tiempo-para-la-semana-santa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20150330\/tranquilo-el-tiempo-para-la-semana-santa\/","title":{"rendered":"Tranquilo el tiempo para la Semana Santa"},"content":{"rendered":"<p>El Servicio Nacional de Meteorolog\u00eda (SNM) indic\u00f3 que un patr\u00f3n de tiempo generalmente tranquilo continuar\u00e1 a traves de la regi\u00f3n hoy a medida que una zona de alta presi\u00f3n persista sobre el \u00e1rea.<\/p>\n<p>Pocos aguaceros afectaran el este durante las horas de la ma\u00f1ana, seguidos por convecci\u00f3n en la tarde a trav\u00e9s del interior y oeste de Puerto Rico.<\/p>\n<p>A trav\u00e9s de las aguas costeras, los vientos alisios moderados persistir\u00e1n hasta el martes junto con oleaje hasta de cinco pies. Varias \u00e1reas alcanzaran vientos hasta de 17 nudos.<\/p><div class=\"notic-content-middle\" id=\"notic-4284022739\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/13202459\/JP-Monopoly-Teaser-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>El cielo prevaleci\u00f3 mayormente despejado sobre la isla a mayormente nublado a trav\u00e9s de Vieques y Culebra. El radar Doppler detect\u00f3 aguaceros pasajeros a trav\u00e9s del este mayormente a trav\u00e9s de Vieques, Culebra y las aguas adyacentes.<\/p>\n<p>Los vientos estuvieron mayormente leves y variables. Las temperaturas estuvieron mayormente en los 70 grados a lo largo de las \u00e1reas costeras y en los 60 grados en las \u00e1reas m\u00e1s altas y valles.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Servicio Nacional de Meteorolog\u00eda (SNM) indic\u00f3 que un patr\u00f3n de tiempo generalmente tranquilo continuar\u00e1 a traves de la regi\u00f3n hoy a medida que una zona de alta presi\u00f3n persista sobre el \u00e1rea. Pocos aguaceros afectaran el este durante las horas de la ma\u00f1ana, seguidos por convecci\u00f3n en la tarde a trav\u00e9s del interior y [&hellip;]<\/p>","protected":false},"author":0,"featured_media":859018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,69],"tags":[],"class_list":["post-74207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=74207"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74207\/revisions"}],"predecessor-version":[{"id":859085,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74207\/revisions\/859085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/859018"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=74207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=74207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=74207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}