{"id":74056,"date":"2015-11-18T00:00:00","date_gmt":"2015-11-18T04:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20151118\/francia-amplia-estado-de-emergencia-a-territorios-de-ultramar\/"},"modified":"2025-07-28T15:34:08","modified_gmt":"2025-07-28T15:34:08","slug":"francia-amplia-estado-de-emergencia-a-territorios-de-ultramar","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20151118\/francia-amplia-estado-de-emergencia-a-territorios-de-ultramar\/","title":{"rendered":"Francia ampl\u00eda estado de emergencia a territorios de ultramar"},"content":{"rendered":"<p>El Gobierno frances anunci\u00f3 el martes que ha ampliado a los territorios de ultramar el estado de emergencia, que el viernes por la noche se decret\u00f3 en la zona metropolitana tras la oleada de atentados terroristas en la capital.<\/p>\n<p>Esa medida, seg\u00fan un comunicado de la ministra de Ultramar, George Pau-Langevin, se justifica &#8216;por una necesidad de coherencia y de refuerzo del dispositivo de seguridad, en un momento en que el estado de emergencia se contempla a largo plazo y se prolongar\u00e1 tres meses mediante una ley sometida al Parlamento&#8217;.<\/p>\n<p>En concreto, el cambio se aplica a Guadalupe, Guayana, Martinica, Mayotte, La Reuni\u00f3n, Saint Barthelemy y Saint Martin, pero en sus territorios del Pac\u00edfico y en Saint-Pierre-et-Miquelon, &#8216;por sus especificidades geogr\u00e1ficas&#8217;, se mantiene el plan antiterrorista Vigipirate en su nivel reforzado.<\/p><div class=\"notic-content-middle\" id=\"notic-1590701364\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/06\/29122752\/CST_Suma-Pasa-La-Llave_300x250.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/06\/29122752\/CST_Suma-Pasa-La-Llave_300x250.jpg 300w, https:\/\/cdn.noticel.com\/2026\/06\/29122752\/CST_Suma-Pasa-La-Llave_300x250-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El estado de emergencia, de 12 d\u00edas de duraci\u00f3n, permite a las autoridades civiles, entre otros puntos, prohibir la circulaci\u00f3n de personas y establecer zonas de seguridad, vetar manifestaciones, ordenar la entrega de armas o de municiones o registrar domicilios &#8216;de d\u00eda como de noche&#8217;.<\/p>\n<p>El actual texto, en vigor desde 1955, establece que puede declararse en todo el territorio o en parte en caso de peligro &#8216;inminente&#8217; por alteraciones graves contra el orden p\u00fablico, ante acontecimientos que por su naturaleza o gravedad &#8216;puedan presentar un car\u00e1cter de calamidad p\u00fablica&#8217;.<\/p>\n<p>En el territorio metropolitano, ten\u00eda efecto desde el pasado s\u00e1bado a las 12:00 a.m. hora local y afectaba tambi\u00e9n a C\u00f3rcega.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Gobierno frances anunci\u00f3 el martes que ha ampliado a los territorios de ultramar el estado de emergencia, que el viernes por la noche se decret\u00f3 en la zona metropolitana tras la oleada de atentados terroristas en la capital. Esa medida, seg\u00fan un comunicado de la ministra de Ultramar, George Pau-Langevin, se justifica &#8216;por una [&hellip;]<\/p>","protected":false},"author":0,"featured_media":601139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-74056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=74056"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74056\/revisions"}],"predecessor-version":[{"id":601165,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/74056\/revisions\/601165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/601139"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=74056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=74056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=74056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}