{"id":73676,"date":"2016-10-13T00:00:00","date_gmt":"2016-10-13T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20161013\/bob-dylan-ganador-del-nobel-de-literatura-2016\/"},"modified":"2025-07-24T07:28:53","modified_gmt":"2025-07-24T07:28:53","slug":"bob-dylan-ganador-del-nobel-de-literatura-2016","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20161013\/bob-dylan-ganador-del-nobel-de-literatura-2016\/","title":{"rendered":"Bob Dylan, ganador del Nobel de Literatura 2016"},"content":{"rendered":"<p>El estadounidense Bob Dylan gan\u00f3 hoy el premio Nobel de Literatura 2016 por &#8216;haber creado una nueva expresi\u00f3n poetica dentro de la gran tradici\u00f3n de la canci\u00f3n americana&#8217;, anunci\u00f3 hoy la Academia sueca.<\/p>\n<p>La Academia, en los datos biogr\u00e1ficos sobre el ganador, recuerda que, adem\u00e1s de la producci\u00f3n de \u00e1lbumes con canciones suyas, Dylan ha publicado trabajos experimentales como &#8216;Tar\u00e1ntula&#8217; (1971) y una recopilaci\u00f3n de sus escritos y dibujos en 1973.<\/p>\n<p>Dylan, que adem\u00e1s public\u00f3 en 2004 unas cr\u00f3nicas autobiogr\u00e1ficas, ha llegado a convertirse, seg\u00fan la academia, en un &#8216;icono&#8217; y su obra ha sido objeto de muchos estudios cr\u00edticos.<\/p>\n<p>Bob Dylan naci\u00f3 el 24 de mayo de 1941 en Duluth (Minnesota) como hijo de una familia jud\u00eda norteamericana de clase media.<\/p>\n<p>Ya como adolescente, toc\u00f3 en varios grupos y se interes\u00f3 en profundizar en la m\u00fasica, con especial pasi\u00f3n en la tradici\u00f3n de la m\u00fasica &#8216;folk&#8217; americana. Uno de sus \u00eddolos ha sido el m\u00e1s c\u00e9lebre representante de ese g\u00e9nero, Woody Guthrie.<\/p><div class=\"notic-content-middle\" id=\"notic-2191180919\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Las letras de sus canciones fueron continuamente publicadas en libros bajo el t\u00edtulo de &#8216;Lyrics&#8217;.<\/p>\n<p>&#8216;Como artista ha sido altamente vers\u00e1til y ha trabajado como pintor, actor y autor de guiones&#8217;, recuerda la academia.<\/p>\n<p>El galardonado recibir\u00e1 un diploma, una medalla de oro y un premio econ\u00f3mico, que este a\u00f1o es de 8 millones de coronas suecas (832,000 euros)<\/p>\n<p>El a\u00f1o pasado la Academia reconoci\u00f3 por primera vez con un Nobel el reportaje period\u00edstico en la figura de la bielorrusa Svetlana Alexi\u00e9vich.<\/p>","protected":false},"excerpt":{"rendered":"<p>El estadounidense Bob Dylan gan\u00f3 hoy el premio Nobel de Literatura 2016 por &#8216;haber creado una nueva expresi\u00f3n poetica dentro de la gran tradici\u00f3n de la canci\u00f3n americana&#8217;, anunci\u00f3 hoy la Academia sueca. La Academia, en los datos biogr\u00e1ficos sobre el ganador, recuerda que, adem\u00e1s de la producci\u00f3n de \u00e1lbumes con canciones suyas, Dylan ha [&hellip;]<\/p>","protected":false},"author":0,"featured_media":569473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-73676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/73676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=73676"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/73676\/revisions"}],"predecessor-version":[{"id":569481,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/73676\/revisions\/569481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/569473"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=73676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=73676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=73676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}