{"id":73270,"date":"2013-09-17T00:00:00","date_gmt":"2013-09-17T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/el-tiempo\/huracanes\/la-calle\/20130917\/fema-desmiente-rumores-de-catastrofe-y-asegura-presupuesto-estable\/"},"modified":"2025-08-22T13:30:29","modified_gmt":"2025-08-22T13:30:29","slug":"fema-desmiente-rumores-de-catastrofe-y-asegura-presupuesto-estable","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20130917\/fema-desmiente-rumores-de-catastrofe-y-asegura-presupuesto-estable\/","title":{"rendered":"FEMA desmiente rumores de cat\u00e1strofe y asegura presupuesto estable"},"content":{"rendered":"<p>El presupuesto de Agencia Federal para el Manejo de Emergencia (FEMA, por sus siglas en ingles), no se ha visto afectado por los recortes que han habido en las agencias federales de los Estados Unidos a ra\u00edz de la crisis fiscal, asegur\u00f3 la oficial encargada de la agencia a nivel local, Ana Morales.<\/p>\n<p>&#8216;El fondo de emergencia de FEMA no ha sido reducido este a\u00f1o fiscal, contin\u00faa. No ha habido un recorte en el presupuesto. FEMA sigue comprometido con la misi\u00f3n de proveer ayuda a los ciudadanos a responder y recuperarse despu\u00e9s de un evento que afecte nuestra naci\u00f3n y no hay limitaciones en el presupuesto&#8217;, enfat\u00edz\u00f3 Morales.<\/p>\n<p>De hecho, debido a que septiembre es el Mes Nacional de Preparaci\u00f3n y representa el pico de la temporada de huracanes para Puerto Rico, los oficiales de FEMA trabajan diariamente junto al gobierno estatal y los municipios para asegurarse de que la estructura gubernamental est\u00e9 mejor preparada para cualquier tipo de evento.<\/p>\n<p>Quiz\u00e1 por esto se ha desatado una falsa alarma en las redes sociales ante la llegada de ata\u00fadesy bolsas pl\u00e1sticas a la isla. Seg\u00fan aclaraciones tanto de laAgencia Estatal para el Manejo de Emergencias y Administraci\u00f3n de Desastres (AEMEAD) como de FEMA son parte de las compras rutinarias que se realizan en esta \u00e9poca de huracanes.<\/p>\n<p>&#8216;FEMA est\u00e1 consciente de las especulaciones relacionadas con compras de materiales a trav\u00e9s de todos los Estados Unidos, particularmente en la regi\u00f3n del Atl\u00e1ntico. No hay ninguna amenaza espec\u00edfica, catalizador o alerta en FEMA para comprar suministros adicionales. Durante todo el a\u00f1o, FEMA realiza compras de rutina de materiales y abastece los almacenes a trav\u00e9s de toda la naci\u00f3n en anticipaci\u00f3n de desastres y para tener suministros pre-ubicados a trav\u00e9s de todos los Estados Unidos. No se han hecho compras extraordinarias o inusuales,&#8217; explic\u00f3 el Director de la Divisi\u00f3n del Caribe de FEMA, Alejandro De La Campa.<\/p>\n<p>Seg\u00fan <a href=\"http:\/\/www.fema.gov\/pdf\/about\/budget\/fema_fy2013_bib.pdf\">documentos <\/a>publicados por la agencia, el presupuesto grosso asignado para el ciclo que termina el 30 de septiembre es de alrededor de $13.6 billones. La cifra es $400 millones menos que la del 2012, pero $3 billones m\u00e1s a la del 2011. Las fluctuaciones aclar\u00f3, &#8216;se refieren al presupuesto administrativo, al pago de n\u00f3minas, etc\u00e9tera, y no tienen que ver con fondo el presidencial de emergencia&#8217;.<\/p>\n<p>Morales explic\u00f3 que a Puerto Rico no se le asigna una tajada del monto pues &#8216;el fondo presidencial de emergencia es un fondo nacional y no est\u00e1 asignado por regiones; es una partida de dinero asignada a un fondo para las necesidades en cualquier parte de la naci\u00f3n, en cualquier momento del a\u00f1o&#8217;.<\/p>\n<p>Ahora bien, para que ese fondo est\u00e9 accesible a los puertorrique\u00f1os el presidente de los Estados Unidos debe declarar a la Isla en estado de emergencia o zona de desastre. Sin la luz verde del presidente ning\u00fan reclamo es procesado.<\/p>\n<p>Personal encargado del servicio al ciudadano en la agencia se\u00f1al\u00f3 que, como de costumbre, luego de 10 a 15 d\u00edas de que se solicite la asistencia, un representante de FEMA visita la residencia afectada para inspeccionarla. Idealmente, es ese mismo tiempo el que les toma enviar el pago o hacer el dep\u00f3sito directo.<\/p>\n<p>Los funcionarios advirtieron que es importante que la ciudadan\u00eda recuerde que para hacer un reclamo se debe poseer un t\u00edtulo de propiedad y que cada solicitud se eval\u00faa de acuerdo a las necesidades de la familia. Las ayudas asignadas se destinan en su mayor\u00eda a la funcionalidad de la cocina y el ba\u00f1o. Enseres de lujo o en exceso en relaci\u00f3n a la cantidad de integrantes de la familia no son costeados.<\/p>\n<p>Los representantes tambi\u00e9n se\u00f1alaron que caso de que el solicitante cuente con un seguro privado, FEMA no duplica beneficios, s\u00f3lo cubre el remanente de los da\u00f1os.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre reclamaciones pulse<a href=\"http:\/\/www.fema.gov\/es\/asistencia-sobrevivientes-de-desastres\"> aqu\u00ed <\/a>o llame al (800) 621-3362.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presupuesto de Agencia Federal para el Manejo de Emergencia (FEMA, por sus siglas en ingles), no se ha visto afectado por los recortes que han habido en las agencias federales de los Estados Unidos a ra\u00edz de la crisis fiscal, asegur\u00f3 la oficial encargada de la agencia a nivel local, Ana Morales. &#8216;El fondo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":891098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[19,12],"tags":[],"class_list":["post-73270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huracanes","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/73270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=73270"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/73270\/revisions"}],"predecessor-version":[{"id":891153,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/73270\/revisions\/891153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/891098"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=73270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=73270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=73270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}