{"id":72492,"date":"2016-02-17T00:00:00","date_gmt":"2016-02-17T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20160217\/turismo-primer-sector-de-puerto-rico-que-supera-la-recesion\/"},"modified":"2025-07-27T04:52:02","modified_gmt":"2025-07-27T04:52:02","slug":"turismo-primer-sector-de-puerto-rico-que-supera-la-recesion","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20160217\/turismo-primer-sector-de-puerto-rico-que-supera-la-recesion\/","title":{"rendered":"Turismo, primer sector de Puerto Rico que supera la recesi\u00f3n"},"content":{"rendered":"<p>El gobernador de Puerto Rico, Alejandro Garc\u00eda Padilla, asegur\u00f3 hoy, miercoles, que el turismo ha sido el primer sector de la isla en superar la recesi\u00f3n econ\u00f3mica en que este Estado Libre Asociado a Estados Unidos lleva diez a\u00f1os sumida.<\/p>\n<p>&#8216;Le seguir\u00e1n la manufactura y la agricultura&#8217;, afirm\u00f3 hoy Garc\u00eda Padilla durante una conferencia de prensa tras la inauguraci\u00f3n de Routes Americas, una convenci\u00f3n que comenz\u00f3 este mi\u00e9rcoles en San Juan y que re\u00fane a representantes de aerol\u00edneas y aeropuertos de todo el continente americano.<\/p>\n<p>Seg\u00fan dijo, se trata del primer sector que crece, y poco a poco est\u00e1 ganando peso en el producto interior bruto (PIB), hasta suponer cerca del 7.1 %, un porcentaje que hist\u00f3ricamente se ha mantenido en torno al 6 %.<\/p>\n<p>El objetivo del Gobierno es alcanzar el 8 %, una cifra que a\u00fan as\u00ed es relativamente baja si se compara con otras islas del Caribe y que, seg\u00fan Garc\u00eda Padilla, se explica porque el peso de la manufactura sobre el conjunto de la econom\u00eda es &#8216;enorme&#8217; (48 %), ya que &#8216;somos el mayor fabricante de medicamentos y de equipamiento m\u00e9dico del mundo&#8217;.<\/p>\n<p>&#8216;La manufactura pesa tanto que, en t\u00e9rminos porcentuales, resta peso al resto de industrias&#8217;, explic\u00f3 el Gobernador, quien apunt\u00f3 que la industria de los servicios tambi\u00e9n tiene un peso muy elevado en el PIB.<\/p>\n<p>Preguntado por Efe por el plazo que se ha dado el Gobierno para que el turismo alcance el 8 % del PIB, Garc\u00eda Padilla respondi\u00f3 gr\u00e1ficamente: &#8216;para antes de ayer&#8217;.<\/p>\n<p>&#8216;Lo m\u00e1s pronto posible&#8217;, a\u00f1adi\u00f3, tras se\u00f1alar que la isla va por buen camino, ya que en el \u00faltimo ejercicio fiscal incorpor\u00f3 500 habitaciones de hotel a su oferta hotelera y la ocupaci\u00f3n media subi\u00f3 dos puntos, para alcanzar el 73 %.<\/p>\n<p>Adem\u00e1s, en los \u00faltimos a\u00f1os se ha pasado de contar con una sola conexi\u00f3n a\u00e9rea a Europa a tener diversos vuelos directos con Air Europa, Condor y Norwegian a Madrid, Fr\u00e1ncfort y Oslo, al tiempo que se ha incorporado tambi\u00e9n conexiones directas con Colombia, M\u00e9xico y diversas islas del Caribe.<\/p>\n<p>As\u00ed, el aeropuerto internacional de Luis Mu\u00f1oz Mar\u00edn registra ya 8,7 millones de pasajeros al a\u00f1o, una cifra r\u00e9cord que supera incluso la cota de los 8 millones que se alcanz\u00f3 en los a\u00f1os 80 y que se perdi\u00f3 con la crisis.<\/p>","protected":false},"excerpt":{"rendered":"<p>El gobernador de Puerto Rico, Alejandro Garc\u00eda Padilla, asegur\u00f3 hoy, miercoles, que el turismo ha sido el primer sector de la isla en superar la recesi\u00f3n econ\u00f3mica en que este Estado Libre Asociado a Estados Unidos lleva diez a\u00f1os sumida. &#8216;Le seguir\u00e1n la manufactura y la agricultura&#8217;, afirm\u00f3 hoy Garc\u00eda Padilla durante una conferencia de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":588444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-72492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/72492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=72492"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/72492\/revisions"}],"predecessor-version":[{"id":588460,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/72492\/revisions\/588460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/588444"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=72492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=72492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=72492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}