{"id":72165,"date":"2016-02-15T00:00:00","date_gmt":"2016-02-15T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20160215\/cuba-y-ee-uu-logran-acuerdo-sobre-aviacion-civil\/"},"modified":"2025-07-27T09:08:28","modified_gmt":"2025-07-27T09:08:28","slug":"cuba-y-ee-uu-logran-acuerdo-sobre-aviacion-civil","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20160215\/cuba-y-ee-uu-logran-acuerdo-sobre-aviacion-civil\/","title":{"rendered":"Cuba y EE.UU. logran acuerdo sobre aviaci\u00f3n civil"},"content":{"rendered":"<p>Cuba y EE.UU. firmar\u00e1n el martes en La Habana un acuerdo sobre aviaci\u00f3n civil que permitir\u00e1 conectar los dos pa\u00edses con vuelos directos por primera vez en m\u00e1s de cincuenta a\u00f1os, rutas que se espera empiecen a operar el pr\u00f3ximo oto\u00f1o.<\/p>\n<p>El secretario de Transporte estadounidense, Anthony R. Foxx, viajar\u00e1 a Cuba para la firma de este memorando de entendimiento, que rubricar\u00e1 por la parte cubana el ministro de Transporte, Adel Yzquirdo, un acto que tendr\u00e1 lugar en el Hotel Nacional de la capital cubana.<\/p>\n<p>Tambi\u00e9n asistir\u00e1n a la firma del acuerdo el secretario adjunto para Asuntos Econ\u00f3micos y Negocios del Departamento de Estado, Charles H. Rivkin; y presidente del Instituto de Aeron\u00e1utica Civil de Cuba, Alfredo Cordero.<\/p>\n<p>A partir de la firma del documento, se abre un plazo de quince d\u00edas para que las aerol\u00edneas estadounidenses presenten sus solicitudes al Departamento de Transporte para las rutas que les gustar\u00eda operar.<\/p>\n<p>El pasado 17 de diciembre, aniversario del anuncio del restablecimiento de las relaciones entre Cuba y EE.UU., las partes anunciaron que hab\u00edan logrado un entendimiento sobre aviaci\u00f3n civil, acuerdo que finalmente sellar\u00e1n ma\u00f1ana.<\/p>\n<p>Seg\u00fan se ha avanzado, el acuerdo representa un potencial de 110 conexiones de ida y vuelta, con veinte vuelos diarios a La Habana y diez vuelos diarios a otros aeropuertos en la isla.<\/p><div class=\"notic-content-middle\" id=\"notic-234613307\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>El proceso de licitaci\u00f3n se abre exclusivamente para aerol\u00edneas estadounidenses, ya que se excluye a la estatal Cubana de Aviaci\u00f3n debido a litigios en EE.UU. que podr\u00edan llevar a que sus bienes fueran embargados si entran en territorio norteamericano, seg\u00fan explic\u00f3 el pasado viernes el subsecretario de Estado adjunto para Asuntos de Transporte, Thomas Engle.<\/p>\n<p>El funcionario estadounidense explic\u00f3 que el Departamento de Transporte comenzar\u00e1 a adjudicar rutas lo antes posible, a m\u00e1s tardar en verano, de manera que los primeros pasajes se podr\u00edan comenzar a vender para el oto\u00f1o.<\/p>\n<p>El inicio de los vuelos regulares entre Cuba y EE.UU. facilitar\u00e1 los viajes para los estadounidenses que entren dentro de las doce categor\u00edas en las que se permiten las visitas a la isla, a donde todav\u00eda no pueden entrar como turistas.<\/p>\n<p>Desde el anuncio del restablecimiento de relaciones entre ambos pa\u00edses, el presidente Barack Obama ha flexibilizado restricciones al comercio de algunos bienes y a los viajes, pero todav\u00eda sigue vigente el embargo y la prohibici\u00f3n del turismo a la isla, que s\u00f3lo se podr\u00e1n levantar con la autorizaci\u00f3n del Congreso.<\/p>\n<p>Despu\u00e9s de m\u00e1s de un a\u00f1o de negociaciones para restaurar sus v\u00ednculos, las partes han logrado acuerdos en cooperaci\u00f3n medioambiental, para el restablecimiento del correo postal directo y el convenio sobre aviaci\u00f3n civil que se firmar\u00e1 ma\u00f1ana.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cuba y EE.UU. firmar\u00e1n el martes en La Habana un acuerdo sobre aviaci\u00f3n civil que permitir\u00e1 conectar los dos pa\u00edses con vuelos directos por primera vez en m\u00e1s de cincuenta a\u00f1os, rutas que se espera empiecen a operar el pr\u00f3ximo oto\u00f1o. El secretario de Transporte estadounidense, Anthony R. Foxx, viajar\u00e1 a Cuba para la firma [&hellip;]<\/p>","protected":false},"author":0,"featured_media":589900,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-72165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/72165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=72165"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/72165\/revisions"}],"predecessor-version":[{"id":589921,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/72165\/revisions\/589921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/589900"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=72165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=72165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=72165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}