{"id":69482,"date":"2018-06-02T00:00:00","date_gmt":"2018-06-02T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20180602\/mas-de-10-sectores-estaran-sin-agua\/"},"modified":"2025-07-30T09:09:43","modified_gmt":"2025-07-30T09:09:43","slug":"mas-de-10-sectores-estaran-sin-agua","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20180602\/mas-de-10-sectores-estaran-sin-agua\/","title":{"rendered":"M\u00e1s de 10 sectores estar\u00e1n sin agua"},"content":{"rendered":"<p><i>Por una aver\u00eda interna.<\/i><\/p>\n<p>El director del \u00e1rea de Manat\u00ed de la Autoridad de Acueductos y Alcantarillados (AAA), Luis Bruno Figueroa, inform\u00f3 el s\u00e1bado que la planta de filtros Morovis Sur se encuentra fuera de operaci\u00f3n, debido a una aver\u00eda electrica interna en la represa.<\/p>\n<p>&#8216;Personal de mantenimiento preventivo trabaja en la reparaci\u00f3n para restablecer el servicio a la brevedad posible. De no ocurrir inconvenientes, la distribuci\u00f3n del servicio comenzar\u00e1 en horas de la noche de hoy&#8217;, notific\u00f3 el funcionario mediante declaraciones escritas.<\/p><div class=\"notic-content-middle\" id=\"notic-611775437\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Ante esta situaci\u00f3n, los sectores que pudieran experimentar bajas presiones hasta interrupci\u00f3n en el servicio de agua potable en el municipio de Morovis son: Unib\u00f3n, Morovis Sur, Jobos, Cuchillas, Barahona, Morovis Norte, R\u00edo Grande, Pimiento, Palmas del Sur y La L\u00ednea.<\/p>\n<p>Ante la posibilidad de turbidez al restablecerse el servicio, se recomienda hervir por tres minutos el agua destinada para consumo humano.<\/p>\n<p>Para m\u00e1s informaci\u00f3n, los abonados se pueden comunicarse al Centro Telef\u00f3nico de Servicio al Cliente al (787)-805-2482 o acceder a la p\u00e1gina de internet www.acueductospr.com. Adem\u00e1s, a traves de las redes sociales Twitter y Facebook.<\/p>","protected":false},"excerpt":{"rendered":"<p>Por una aver\u00eda interna. El director del \u00e1rea de Manat\u00ed de la Autoridad de Acueductos y Alcantarillados (AAA), Luis Bruno Figueroa, inform\u00f3 el s\u00e1bado que la planta de filtros Morovis Sur se encuentra fuera de operaci\u00f3n, debido a una aver\u00eda electrica interna en la represa. &#8216;Personal de mantenimiento preventivo trabaja en la reparaci\u00f3n para restablecer [&hellip;]<\/p>","protected":false},"author":0,"featured_media":615723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-69482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/69482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=69482"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/69482\/revisions"}],"predecessor-version":[{"id":615742,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/69482\/revisions\/615742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/615723"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=69482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=69482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=69482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}