{"id":68996,"date":"2015-05-07T00:00:00","date_gmt":"2015-05-07T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20150507\/le-roban-coleccion-de-monedas-a-un-sujeto-en-ponce\/"},"modified":"2025-08-16T17:54:18","modified_gmt":"2025-08-16T17:54:18","slug":"le-roban-coleccion-de-monedas-a-un-sujeto-en-ponce","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20150507\/le-roban-coleccion-de-monedas-a-un-sujeto-en-ponce\/","title":{"rendered":"Le roban colecci\u00f3n de monedas a un sujeto en Ponce"},"content":{"rendered":"<p>Un caso de apropiaci\u00f3n ilegal ocurrido a eso de las 10:30 de la noche del miercoles en la calle Jengibre de Ponce, inform\u00f3 la Polic\u00eda.<\/p>\n<p>Seg\u00fan el informe de novedades, Wilson Figueroa aleg\u00f3 que alguien con libre acceso a su residencia, se apropi\u00f3 de una computadora port\u00e1til valorada en 498 d\u00f3lares, una &#8216;tablet&#8217; de 10 pulgadas valorada en 162 d\u00f3lares y una colecci\u00f3n de 40 monedas de plata, valorada en 10 mil d\u00f3lares.<\/p>\n<p>La Uniformada no report\u00f3 si el perjudicado result\u00f3 herido.<\/p>\n<p>El caso fue referido al Cuerpo de Investigaciones Criminales (CIC) de Ponce para investigaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un caso de apropiaci\u00f3n ilegal ocurrido a eso de las 10:30 de la noche del miercoles en la calle Jengibre de Ponce, inform\u00f3 la Polic\u00eda. Seg\u00fan el informe de novedades, Wilson Figueroa aleg\u00f3 que alguien con libre acceso a su residencia, se apropi\u00f3 de una computadora port\u00e1til valorada en 498 d\u00f3lares, una &#8216;tablet&#8217; de 10 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":852849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-68996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=68996"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68996\/revisions"}],"predecessor-version":[{"id":852859,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68996\/revisions\/852859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/852849"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=68996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=68996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=68996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}