{"id":68808,"date":"2012-07-26T00:00:00","date_gmt":"2012-07-26T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20120726\/gj-acusa-a-negro-por-carjacking-a-stefano\/"},"modified":"2025-08-26T09:19:40","modified_gmt":"2025-08-26T09:19:40","slug":"gj-acusa-a-negro-por-carjacking-a-stefano","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20120726\/gj-acusa-a-negro-por-carjacking-a-stefano\/","title":{"rendered":"GJ acusa a &#8216;Negro&#8217; por &#8216;carjacking&#8217; a Stefano"},"content":{"rendered":"<p>Un gran jurado emiti\u00f3 el mediod\u00eda del jueves una acusaci\u00f3n contra Alexis Amador Huggins, mejor conocido como ?Negro?, por cometer el robo de auto a mano armada, ?carjacking?, que culmin\u00f3 con la vida del joven Stefano Steenbakkers Betancourt, el pasado 24 de junio en Dorado.<\/p>\n<p>El Gran Jurado baj\u00f3 con la acusaci\u00f3n que consta de un solo cargo e indica que en esa fecha, Amador Huggins, en concierto y com\u00fan acuerdo con otra persona conocida por el Gran Jurado y con la intenci\u00f3n de causar la muerte o serio da\u00f1o corporal, intent\u00f3 robar bajo fuerza e intimidaci\u00f3n la guagua Lexus que manejaba el joven de ascendencia holandesa, dispar\u00e1ndole y asesin\u00e1ndolo.<\/p>\n<p>La magistrada federal Silvia Carre\u00f1o Coll paut\u00f3 la vista de lectura formal de cargos contra Amador Huggins para el 2 de agosto a las 9:30 de la ma\u00f1ana.<\/p><div class=\"notic-content-middle\" id=\"notic-2860761027\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Por este mismo caso la fiscal\u00eda federal, representada por Mar\u00eda Dom\u00ednguez y Jacqueline Novas, radic\u00f3 una denuncia criminal el 17 de julio contra John Anthony Morales L\u00f3pez, mejor conocido como &#8216;Jongy&#8217; y quien tiene 19 a\u00f1os por el carjacking, tras este confesar al Negociado Federal de Investigaciones (FBI) haber sido quien acompanaba a Amador Huggins el d\u00eda del carjacking.<\/p>\n<p>Su confesi\u00f3n desmiti\u00f3 en gran parte la versi\u00f3n de Amador Huggins, primer arrestado y acusado de este caso, quien hab\u00eda asegurado al FBI que actu\u00f3 junto a Jordan Ayala Cruz.<\/p>\n<p>Ayala Cruz fue arrestado y despu\u00e9s de dos semanas en prisi\u00f3n, la fiscal\u00eda federal solicit\u00f3 la desestimaci\u00f3n del caso en su contra, y su excarcelaci\u00f3n inmediata.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un gran jurado emiti\u00f3 el mediod\u00eda del jueves una acusaci\u00f3n contra Alexis Amador Huggins, mejor conocido como ?Negro?, por cometer el robo de auto a mano armada, ?carjacking?, que culmin\u00f3 con la vida del joven Stefano Steenbakkers Betancourt, el pasado 24 de junio en Dorado. El Gran Jurado baj\u00f3 con la acusaci\u00f3n que consta de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":915671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-68808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=68808"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68808\/revisions"}],"predecessor-version":[{"id":915715,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68808\/revisions\/915715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/915671"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=68808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=68808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=68808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}