{"id":68612,"date":"2016-11-03T00:00:00","date_gmt":"2016-11-03T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/baloncesto\/bsn\/deportes\/20161103\/christian-dalmau-pide-un-time-out-con-la-ley-de-quiebras\/"},"modified":"2025-07-24T00:19:35","modified_gmt":"2025-07-24T00:19:35","slug":"christian-dalmau-pide-un-time-out-con-la-ley-de-quiebras","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20161103\/christian-dalmau-pide-un-time-out-con-la-ley-de-quiebras\/","title":{"rendered":"Christian Dalmau pide un &#8216;time out&#8217; con la Ley de Quiebras"},"content":{"rendered":"<p>El baloncelista Christian Dalmau Santana, miembro de la dinast\u00eda deportiva iniciada por su padre, Raymond Dalmau, pidi\u00f3 la protecci\u00f3n de la Ley de Quiebras para reorganizar sus deudas.<\/p>\n<p>La petici\u00f3n a Tribunal de Quiebras fue radicada el 29 de octubre pasado, seg\u00fan consta en el Bolet\u00edn de Puerto Rico, y es para reorganizar sus finanzas.<\/p><div class=\"notic-content-middle\" id=\"notic-2323326521\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La deuda reportada asciende a $233,617 y los principales acreedores son el Servicio de Rentas Internas federal ($70,249.87), y las instituciones financieras Banco Popular y Jefferson Capital (con $49,568.15).<\/p>\n<p>M\u00e1s recientemente, Dalmau figur\u00f3 en la palestra p\u00fablica por su romance con la actriz y presentadora Daniela Droz.<\/p>","protected":false},"excerpt":{"rendered":"<p>El baloncelista Christian Dalmau Santana, miembro de la dinast\u00eda deportiva iniciada por su padre, Raymond Dalmau, pidi\u00f3 la protecci\u00f3n de la Ley de Quiebras para reorganizar sus deudas. La petici\u00f3n a Tribunal de Quiebras fue radicada el 29 de octubre pasado, seg\u00fan consta en el Bolet\u00edn de Puerto Rico, y es para reorganizar sus finanzas. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":566499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[33,31],"tags":[],"class_list":["post-68612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=68612"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68612\/revisions"}],"predecessor-version":[{"id":566502,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/68612\/revisions\/566502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/566499"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=68612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=68612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=68612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}