{"id":67482,"date":"2012-09-17T00:00:00","date_gmt":"2012-09-17T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20120917\/angel-rosa-trae-propuesta-para-crear-40000-empleos\/"},"modified":"2025-08-25T13:14:51","modified_gmt":"2025-08-25T13:14:51","slug":"angel-rosa-trae-propuesta-para-crear-40000-empleos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20120917\/angel-rosa-trae-propuesta-para-crear-40000-empleos\/","title":{"rendered":"\u00c1ngel Rosa trae propuesta para crear 40,000 empleos"},"content":{"rendered":"<p>Ante l\u00edderes del sector econ\u00f3mico del pa\u00eds y candidatos al Senado de su partido, el candidato a senador por acumulaci\u00f3n del Partido<\/p>\n<p>Popular Democr\u00e1tico, \u00c1ngel Rosa, present\u00f3 hoy en el Hotel La Concha de San Juan, una propuesta legislativa de creaci\u00f3n de empleos e inversi\u00f3n que crear\u00e1 40,000 empleos directos en 24 meses.<\/p>\n<p>&#8216;Puerto Rico vive momentos terribles. Continuamos sumidos en una recesi\u00f3n econ\u00f3mica<\/p>\n<p>que nos asfixia y cientos de miles de hermanos puertorrique\u00f1os han perdido sus empleos. Por eso, estoy present\u00e1ndoles lo que ser\u00e1 la Ley de Empleos y Prosperidad<\/p>\n<p>para Puerto Rico. Esta Ley se fundamenta en dos estrategias y tres t\u00e1cticas dirigidas a<\/p>\n<p>estimular la producci\u00f3n y la inversi\u00f3n de capital puertorrique\u00f1o, para crear 40,000 empleos directos en 24 meses&#8217;, destac\u00f3 Rosa.<\/p>\n<p>Rosa, quien es profesor de ciencias pol\u00edticas y econom\u00eda pol\u00edtica internacional en el RUM, destac\u00f3 que en los \u00faltimos diez a\u00f1os sobre 300,000 puertorrique\u00f1os han abandonado el pa\u00eds y s\u00f3lo en este cuatrienio 150,000 han perdido sus empleos.<\/p>\n<p>Seg\u00fan el candidato, esto se debe a<\/p><div class=\"notic-content-middle\" id=\"notic-3468439527\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/07\/13201344\/JP-Monopoly-Teaser-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>las pol\u00edticas econ\u00f3micas equivocadas adoptadas por el gobierno de Luis Fortu\u00f1o y su<\/p>\n<p>Legislatura, as\u00ed como a la eliminaci\u00f3n de la Secci\u00f3n 936 de C\u00f3digo de Rentas Internas federal.<\/p>\n<p>La primera estrategia presentada por Rosa, denominada Est\u00edmulo a la Producci\u00f3n, est\u00e1 dirigida a que el Gobierno inyecte capital directamente a empresas exitosas existentes, mediante el mecanismo de acciones preferidas, aumentando as\u00ed los niveles de producci\u00f3n de la econom\u00eda.<\/p>\n<p>Para esto, Rosa propuso la creaci\u00f3n de un fondo llamado Apoyo al \u00c9xito, que<\/p>\n<p>utilizar\u00e1 $500 millones del Banco Gubernamental de Fomento (BGF), para invertir en empresas<\/p>\n<p>puertorrique\u00f1as s\u00f3lidas que puedan expandir sus operaciones inmediatamente. Rosa tambi\u00e9n<\/p>\n<p>propuso la creaci\u00f3n de la Corporaci\u00f3n de Inversi\u00f3n Apremiante, adscrita al BGF, para<\/p>\n<p>administrar dicho fondo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ante l\u00edderes del sector econ\u00f3mico del pa\u00eds y candidatos al Senado de su partido, el candidato a senador por acumulaci\u00f3n del Partido Popular Democr\u00e1tico, \u00c1ngel Rosa, present\u00f3 hoy en el Hotel La Concha de San Juan, una propuesta legislativa de creaci\u00f3n de empleos e inversi\u00f3n que crear\u00e1 40,000 empleos directos en 24 meses. &#8216;Puerto Rico [&hellip;]<\/p>","protected":false},"author":0,"featured_media":911607,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-67482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/67482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=67482"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/67482\/revisions"}],"predecessor-version":[{"id":911627,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/67482\/revisions\/911627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/911607"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=67482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=67482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=67482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}