{"id":67142,"date":"2011-09-30T00:00:00","date_gmt":"2011-09-30T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20110930\/justicieros-en-mexico-no-perdonan-al-narco\/"},"modified":"2025-08-29T00:01:35","modified_gmt":"2025-08-29T00:01:35","slug":"justicieros-en-mexico-no-perdonan-al-narco","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20110930\/justicieros-en-mexico-no-perdonan-al-narco\/","title":{"rendered":"Justicieros en M\u00e9xico no perdonan al narco"},"content":{"rendered":"<p>En M\u00e9xico se han producido 45,000 muertes violentas relacionadas con el narcotr\u00e1fico en los \u00faltimos a\u00f1os. La guerra contra los c\u00e1rteles de la droga emprendida por el presidente Felipe Calder\u00f3n no est\u00e1 dando resultados positivos. El tejido social se descompone. La gente de bien ya no puede m\u00e1s. En este contexto ha surgido un grupo de justicieros enmascarados que&#8230;<\/p>\n<p>&#8230;como el Zorro en la ficci\u00f3n, aseguran defender los intereses de la poblaci\u00f3n y combatir las injusticias. Adem\u00e1s dicen defender la democracia. Insisten en que no lo hacen por dinero y que no aceptar\u00e1n pagos ni de individuos ni del Estado. Los &#8216;Mata Zetas&#8217; se responsabilizaron de la muerte de unos 35 narcotraficantes cuyos cad\u00e1veres aparecieron la semana pasada en una avenida de Veracruz.<\/p><div class=\"notic-content-middle\" id=\"notic-3217361831\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Para algunos, los &#8216;Mata Zetas&#8217; no son m\u00e1s que otro grupo criminal surgido a ra\u00edz de la inestabilidad social que el estatus legal de las drogas ha provocado. Para otros, son los h\u00e9roes que estaban esperando.<\/p>\n<p>Vea el v\u00eddeo manifiesto de los &#8216;Mata Zetas&#8217;:<\/p>","protected":false},"excerpt":{"rendered":"<p>En M\u00e9xico se han producido 45,000 muertes violentas relacionadas con el narcotr\u00e1fico en los \u00faltimos a\u00f1os. La guerra contra los c\u00e1rteles de la droga emprendida por el presidente Felipe Calder\u00f3n no est\u00e1 dando resultados positivos. El tejido social se descompone. La gente de bien ya no puede m\u00e1s. En este contexto ha surgido un grupo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":929310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-67142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/67142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=67142"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/67142\/revisions"}],"predecessor-version":[{"id":929331,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/67142\/revisions\/929331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/929310"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=67142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=67142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=67142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}