{"id":66939,"date":"2015-10-14T00:00:00","date_gmt":"2015-10-14T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/retiro\/20151014\/proponen-ventana-de-retiro-para-mas-de-5000-maestros\/"},"modified":"2025-07-29T17:11:42","modified_gmt":"2025-07-29T17:11:42","slug":"proponen-ventana-de-retiro-para-mas-de-5000-maestros","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20151014\/proponen-ventana-de-retiro-para-mas-de-5000-maestros\/","title":{"rendered":"Proponen ventana de retiro para m\u00e1s de 5,000 maestros"},"content":{"rendered":"<p>La senadora Maritere Gonz\u00e1lez y el representante Carlos Vargas Ferrer presentaron el miercoles una medida legislativa en ambos cuerpos, que propone crear el Programa de Separaci\u00f3n Voluntaria Incentivada para que maestros puedan separarse del servicio con un incentivo econ\u00f3mico del 65 por ciento del sueldo mensual.<\/p>\n<p>Las medidas son el Proyecto del Senado 1491 y Proyecto de la C\u00e1mara 2697.<\/p>\n<p>&#8216;Este programa tiene como objetivo principal crear un mecanismo alterno para aquel maestro que tenga entre 25 y 29 a\u00f1os de servicio, debidamente cotizados en el Sistema de Retiro. Al acogerse voluntariamente al mismo, podr\u00eda separarse del servicio p\u00fablico con un incentivo econ\u00f3mico del 65 por ciento de su sueldo bruto mensual promedio basado en los doce meses anteriores a la fecha de la elecci\u00f3n para participar. El incentivo ser\u00eda pagadero en plazos quincenales y los fondos para sufragar ese incentivo provendr\u00edan del presupuesto del Departamento de Educaci\u00f3n (DE) y del Sistema de Retiro para Maestros (SRM), seg\u00fan sea el caso. Por otra parte, el maestro que acceda al programa recibir\u00eda una aportaci\u00f3n al plan de salud por un periodo de doce meses. Este programa ofrece la oportunidad a los maestros de emprender nuevos horizontes en su vida privada y profesional, benefici\u00e1ndose de un incentivo econ\u00f3mico hasta cumplir sus 30 a\u00f1os de servicio&#8217;, puntualiz\u00f3 el legislador en un comunicado de prensa.<\/p>\n<p>La medida presentada resalta que la Ley 70-2010 cre\u00f3 un programa similar que le ofrec\u00eda a los empleados que decidieran acogerse a la ventana unos beneficios y alternativas para el desarrollo de los empleados fuera del sector p\u00fablico. Sin embargo, tuvo un efecto negativo para la salud fiscal del los Sistemas de Retiro, debido a que no dispon\u00eda de herramientas para subsanar el efecto causado como consecuencia de la s\u00fabita p\u00e9rdida de las aportaciones individuales de los empleados que se acogieran.<\/p><div class=\"notic-content-middle\" id=\"notic-2949576909\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;A diferencia de programas similares presentados anteriormente, este proyecto no afecta el Sistema de Retiro para Maestros. Por el contrario, permite la continuidad de las aportaciones requeridas al Sistema de Retiro por parte del patrono y del empleado acogido al programa. Esta Ley, que va m\u00e1s all\u00e1 de mantener estable al Sistema de Retiro, busca encaminarlo a una mejor salud fiscal porque dispone que el 60 por ciento de los ahorros -resultado de la implantaci\u00f3n del Programa- pasar\u00e1 a capitalizar el Sistema. El restante 40 por ciento ir\u00e1 destinado a la contrataci\u00f3n de maestros, de acuerdo con las necesidades actuales del Departamento, por lo que la totalidad de los ahorros permanecer\u00e1 beneficiando a los integrantes del Sistema P\u00fablico de Educaci\u00f3n&#8217;, indic\u00f3 la senadora.<\/p>\n<p>Finalmente, Vargas Ferrer resalt\u00f3 que el programa, adem\u00e1s de proveer flexibilidad y apoyo econ\u00f3mico a sus participantes, atiende las necesidades e intereses de nuestros maestros y aporta a la renovaci\u00f3n de nuestro sistema p\u00fablico de ense\u00f1anza.<\/p>\n<p>&#8216;Concientes de la actual reorganizaci\u00f3n del Departamento de Educaci\u00f3n y la necesidad de redirigir los recursos ante la realidad fiscal y la poblaci\u00f3n estudiantil a quien le sirve, el programa permitir\u00e1 generar econom\u00edas en el presupuesto del Departamento. Estas ser\u00edan destinadas al cumplimiento con la Ley Federal 107-110 (No Child Left Behind\/2001), y para solventar parte del d\u00e9ficit millonario del Sistema de Retiro para Maestros&#8217;, asegur\u00f3 el Representante.<\/p>\n<p>Por \u00faltimo, Gonz\u00e1lez y Vargas estimaron quecerca de 5,478 maestros podr\u00edan beneficiarse del programa. Adem\u00e1s, el DE ahorrar\u00eda en n\u00f3mina aproximadamente 138 millones de d\u00f3lares en cinco a\u00f1os.<\/p>","protected":false},"excerpt":{"rendered":"<p>La senadora Maritere Gonz\u00e1lez y el representante Carlos Vargas Ferrer presentaron el miercoles una medida legislativa en ambos cuerpos, que propone crear el Programa de Separaci\u00f3n Voluntaria Incentivada para que maestros puedan separarse del servicio con un incentivo econ\u00f3mico del 65 por ciento del sueldo mensual. Las medidas son el Proyecto del Senado 1491 y [&hellip;]<\/p>","protected":false},"author":0,"featured_media":610062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[78,2],"tags":[],"class_list":["post-66939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-retiro","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/66939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=66939"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/66939\/revisions"}],"predecessor-version":[{"id":610085,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/66939\/revisions\/610085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/610062"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=66939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=66939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=66939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}