{"id":66890,"date":"2011-05-31T00:00:00","date_gmt":"2011-05-31T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20110531\/la-fortaleza-cantina-de-fortuno\/"},"modified":"2025-08-29T19:17:35","modified_gmt":"2025-08-29T19:17:35","slug":"la-fortaleza-cantina-de-fortuno","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20110531\/la-fortaleza-cantina-de-fortuno\/","title":{"rendered":"La Fortaleza: &#8216;cantina de Fortu\u00f1o&#8217;"},"content":{"rendered":"<p>Dos senadores populares denunciaron hoy que el gobernador Luis Fortu\u00f1o ha convertido La Fortaleza en &#8216;una cantina&#8217; para agasajar a l\u00edderes de barrio del Partido Nuevo Progresista y realzar su maltrecha imagen como candidato a la reelecci\u00f3n.<\/p>\n<p>&#8216;El due\u00f1o de la cantina, el que maneja la cantina, es Luis Fortu\u00f1o. Que conteste \u00e9l y no el Secretario de la Gobernaci\u00f3n&#8217;, expres\u00f3 el senador Cirilo Tirado en rueda de prensa.<\/p>\n<p>Tirado y su hom\u00f3logo Jorge Su\u00e1rez presentaron como evidencia \u00f3rdenes de compra para la Mansi\u00f3n Ejecutiva por m\u00e1s de $10,000 en bebidas alcoh\u00f3licas.<\/p>\n<p>Las cuatro requisiciones de bienes o servicios son del 19 de mayo e incluyen decenas de cajas de licor y en una de ellas se adquirieron 40 cajas de &#8216;Cerveza Light de Puerto Rico&#8217;.<\/p>\n<p>En una de las \u00f3rdenes de compra, se adquirieron 15 cajas de whisky, 15 cajas de vodka, 15 cajas de ron blanco, 4 cajas de licor de naranja, y 3 cajas de ginebra, entre otras.<\/p>\n<p>En la orden de compra de las 40 cajas de cerveza, tambi\u00e9n se pidieron 10 botellas de vino tinto para sangr\u00eda.<\/p>\n<p>En otra orden, se compraron 15 cajas de vino tinto, 17 cajas de vino blanco y 5 cajas de champagne.<\/p>\n<p>&#8216;Es lamentable que se est\u00e9 utilizando el dinero del pueblo para comprar bebidas alcoh\u00f3licas para convertir La Fortaleza en una cantina parta agasajar a los l\u00edderes de barrio del PNP&#8217;, denunci\u00f3 Tirado, quien reclam\u00f3 que si Fortu\u00f1o quiere fiestar con l\u00edderes del PNP, lo debe hacer en la sede de su comit\u00e9 y con fondos de la colectividad, no con dinero p\u00fablico.<\/p>\n<p>Su\u00e1rez, por su parte, repudi\u00f3 lo que llam\u00f3 el gobierno de &#8216;such is life&#8217; y el gasto publicitario para realzar la imagen de la presente administraci\u00f3n.<\/p>\n<p>Detall\u00f3 que, en el a\u00f1o fiscal 2009-2010, se gastaron $13 millones en publicidad, cuando s\u00f3lo se autorizaron $5 millones.<\/p>\n<p>&#8216;Hasta d\u00f3nde van a continuar el gasto publicitario para realzar la imagen del Gobernador&#8217;, cuestion\u00f3.<\/p>\n<p>Lee la reacci\u00f3n de La Fortaleza y del PNP <a href=\"https:\/\/noticel.com\/en\/noticia\/105331\/rodriguez-ema-desautoriza-cantina-y-el-pnp-la-defiende.html\/\" target=\"_blank\">aqu\u00ed<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dos senadores populares denunciaron hoy que el gobernador Luis Fortu\u00f1o ha convertido La Fortaleza en &#8216;una cantina&#8217; para agasajar a l\u00edderes de barrio del Partido Nuevo Progresista y realzar su maltrecha imagen como candidato a la reelecci\u00f3n. &#8216;El due\u00f1o de la cantina, el que maneja la cantina, es Luis Fortu\u00f1o. Que conteste \u00e9l y no [&hellip;]<\/p>","protected":false},"author":0,"featured_media":939677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-66890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/66890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=66890"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/66890\/revisions"}],"predecessor-version":[{"id":939684,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/66890\/revisions\/939684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/939677"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=66890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=66890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=66890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}