{"id":65597,"date":"2015-08-26T00:00:00","date_gmt":"2015-08-26T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20150826\/sujeto-muerde-a-policias-en-intervencion-en-bayamon\/"},"modified":"2025-07-25T14:33:57","modified_gmt":"2025-07-25T14:33:57","slug":"sujeto-muerde-a-policias-en-intervencion-en-bayamon","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20150826\/sujeto-muerde-a-policias-en-intervencion-en-bayamon\/","title":{"rendered":"Sujeto muerde a polic\u00edas en intervenci\u00f3n en Bayam\u00f3n"},"content":{"rendered":"<p>Un individuo que hab\u00eda sido reportado desaparecido, mordi\u00f3 a un polic\u00eda municipal de Bayam\u00f3n y un agente estatal de Bayam\u00f3n Norte a eso de las 12:00 de la madrugada del miercoles en la marginal de la carretera PR-2, frente al Departamento de la Familia en Bayam\u00f3n.<\/p>\n<p>Seg\u00fan el informe policiaco, una llamada al Sistema de Emergencias 9-1-1, alert\u00f3 sobre una persona desorientada. Cuando los agentes intentaron intervenir con Rafael Rodr\u00edguez Mundo de 65 a\u00f1os, \u00e9ste se torn\u00f3 agresivo y los mordi\u00f3.<\/p><div class=\"notic-content-middle\" id=\"notic-3637867609\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Las autoridades detallaron que el agente Jos\u00e9 Arce Santiago, adscrito al Precinto de Bayam\u00f3n Norte fue mordido en la mano izquierda, mientras que el polic\u00eda Jos\u00e9 Rivera Morales fue mordido en el antebrazo derecho. Ambos est\u00e1n en condici\u00f3n estable.<\/p>\n<p>Entretanto, la Polic\u00eda detall\u00f3 que el agresor hab\u00eda sido reportado desaparecido el pasado 15 de agosto pasado, cuando fue visto por \u00faltima vez en el Residencial Jardines de Monte Hatillo. El hombre qued\u00f3 bajo custodia de los polic\u00edas municipales de Bayam\u00f3n pueblo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un individuo que hab\u00eda sido reportado desaparecido, mordi\u00f3 a un polic\u00eda municipal de Bayam\u00f3n y un agente estatal de Bayam\u00f3n Norte a eso de las 12:00 de la madrugada del miercoles en la marginal de la carretera PR-2, frente al Departamento de la Familia en Bayam\u00f3n. Seg\u00fan el informe policiaco, una llamada al Sistema de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":574577,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-65597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/65597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=65597"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/65597\/revisions"}],"predecessor-version":[{"id":574588,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/65597\/revisions\/574588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/574577"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=65597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=65597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=65597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}