{"id":65106,"date":"2014-02-18T00:00:00","date_gmt":"2014-02-18T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20140218\/maduro-destituye-al-director-del-servicio-bolivariano-de-inteligencia\/"},"modified":"2025-08-20T08:43:14","modified_gmt":"2025-08-20T08:43:14","slug":"maduro-destituye-al-director-del-servicio-bolivariano-de-inteligencia","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20140218\/maduro-destituye-al-director-del-servicio-bolivariano-de-inteligencia\/","title":{"rendered":"Maduro destituye al director del Servicio Bolivariano de inteligencia"},"content":{"rendered":"<p>El presidente venezolano, Nicol\u00e1s Maduro, destituy\u00f3 hoy al general de brigada Manuel Bernal como director del Servicio Bolivariano de inteligencia Nacional (Sebin), d\u00edas despues de que reconociera que miembros de ese cuerpo desobedecieron la orden de acuartelarse el pasado miercoles.<\/p>\n<p>El jefe de Estado admiti\u00f3 el domingo que en la marcha que efectuaron estudiantes y opositores el pasado 12 de febrero, tras la cual se registraron hechos de violencia que dejaron 3 muertos, &#8216;un grupo de funcionarios del Sebin incumplieron directamente las \u00f3rdenes del director del Sebin de ese d\u00eda de acuartelarse y nadie salir a la calle&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-236018278\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Las \u00fanicas Polic\u00edas y funcionarios que deb\u00edan estar en las calles, como estuvieron conteniendo la violencia, era la Polic\u00eda Nacional y la Guardia Nacional (polic\u00eda militarizada) en una segunda l\u00ednea&#8217;, indic\u00f3 el gobernante.<\/p>\n<p>El nombramiento de Gustavo Gonz\u00e1lez en sustituci\u00f3n de Bernal consta en la edici\u00f3n de la Gaceta Oficial que circul\u00f3 hoy, donde se se\u00f1ala que la decisi\u00f3n se basa en &#8216;el supremo compromiso y voluntad de lograr la mayor eficacia pol\u00edtica y calidad revolucionaria en la construcci\u00f3n del socialismo&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente venezolano, Nicol\u00e1s Maduro, destituy\u00f3 hoy al general de brigada Manuel Bernal como director del Servicio Bolivariano de inteligencia Nacional (Sebin), d\u00edas despues de que reconociera que miembros de ese cuerpo desobedecieron la orden de acuartelarse el pasado miercoles. El jefe de Estado admiti\u00f3 el domingo que en la marcha que efectuaron estudiantes y [&hellip;]<\/p>","protected":false},"author":0,"featured_media":881054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-65106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/65106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=65106"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/65106\/revisions"}],"predecessor-version":[{"id":881072,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/65106\/revisions\/881072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/881054"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=65106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=65106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=65106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}