{"id":64869,"date":"2011-09-28T00:00:00","date_gmt":"2011-09-28T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20110928\/amazon-prende-en-fuego-al-ipad\/"},"modified":"2025-07-24T06:36:26","modified_gmt":"2025-07-24T06:36:26","slug":"amazon-prende-en-fuego-al-ipad","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20110928\/amazon-prende-en-fuego-al-ipad\/","title":{"rendered":"Amazon prende en fuego al iPad"},"content":{"rendered":"<p>La tienda por internet Amazon present\u00f3 hoy en Nueva York el &#8216;Kindle Fire&#8217;, una nueva tableta electr\u00f3nica que vender\u00e1 a partir de 199 d\u00f3lares y con la que tratar\u00e1 de competir en un mercado dominado por el iPad de Apple.<\/p>\n<p>Adem\u00e1s del &#8216;Kindle Fire&#8217;, una tableta con conexi\u00f3n 3G, un peso de 414 gramos y una longitud de 17.8 cent\u00edmetros, Amazon desvel\u00f3 en esa presentaci\u00f3n el lector &#8216;Kindle Touch&#8217;, que tendr\u00e1 un precio de 99 d\u00f3lares en su versi\u00f3n Wi-Fi y de 149 d\u00f3lares en su versi\u00f3n 3G.<\/p><div class=\"notic-content-middle\" id=\"notic-80801683\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La presentaci\u00f3n de la nueva tableta de Amazon provoc\u00f3 que las acciones de la tecnol\u00f3gica subieran un 3.47 % en el mercado Nasdaq, donde se cambiaban por 232 d\u00f3lares.<\/p>","protected":false},"excerpt":{"rendered":"<p>La tienda por internet Amazon present\u00f3 hoy en Nueva York el &#8216;Kindle Fire&#8217;, una nueva tableta electr\u00f3nica que vender\u00e1 a partir de 199 d\u00f3lares y con la que tratar\u00e1 de competir en un mercado dominado por el iPad de Apple. Adem\u00e1s del &#8216;Kindle Fire&#8217;, una tableta con conexi\u00f3n 3G, un peso de 414 gramos y [&hellip;]<\/p>","protected":false},"author":0,"featured_media":569162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-64869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=64869"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64869\/revisions"}],"predecessor-version":[{"id":569175,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64869\/revisions\/569175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/569162"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=64869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=64869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=64869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}