{"id":64830,"date":"2014-08-19T00:00:00","date_gmt":"2014-08-19T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20140819\/predominan-los-aguaceros-dispersos\/"},"modified":"2025-08-19T06:44:15","modified_gmt":"2025-08-19T06:44:15","slug":"predominan-los-aguaceros-dispersos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20140819\/predominan-los-aguaceros-dispersos\/","title":{"rendered":"Predominan los aguaceros dispersos"},"content":{"rendered":"<p>Aguaceros dispersos se esperan para el resto de la ma\u00f1ana a traves de las aguas locales al igual que sobre el norte y este de Puerto Rico, seg\u00fan el Servicio Nacional de Meteorolog\u00eda (SNM).<\/p>\n<p>Durante las horas de la tarde, aguaceros y tronadas aisladas podr\u00e1n desarrollarse a trav\u00e9s del cuadrante suroeste de la isla, incluyendo los sectores del interior.<\/p>\n<p>A trav\u00e9s de las aguas costeras se esperan vientos hasta de 20 nudos y oleaje hasta de cinco pies hoy.<\/p><div class=\"notic-content-middle\" id=\"notic-1161957692\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>El cielo prevaleci\u00f3 variablemente nublado a trav\u00e9s de Puerto Rico, Culebra y Vieques durante las horas de la noche. Aguaceros dispersos fueron observados a trav\u00e9s de las aguas locales al igual que sobre el norte y este del pa\u00eds.<\/p>\n<p>Las temperaturas estuvieron en los bajos 80 grados a trav\u00e9s de \u00e1reas bajas y entre los altos 60 a bajos 70 grados a trav\u00e9s de \u00e1reas m\u00e1s altas. El viento estuvo calmado a leve y variable.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aguaceros dispersos se esperan para el resto de la ma\u00f1ana a traves de las aguas locales al igual que sobre el norte y este de Puerto Rico, seg\u00fan el Servicio Nacional de Meteorolog\u00eda (SNM). Durante las horas de la tarde, aguaceros y tronadas aisladas podr\u00e1n desarrollarse a trav\u00e9s del cuadrante suroeste de la isla, incluyendo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":871403,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-64830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=64830"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64830\/revisions"}],"predecessor-version":[{"id":871437,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64830\/revisions\/871437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/871403"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=64830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=64830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=64830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}