{"id":64098,"date":"2012-08-30T00:00:00","date_gmt":"2012-08-30T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20120830\/record-en-natacion-paralimpica\/"},"modified":"2025-08-26T04:32:18","modified_gmt":"2025-08-26T04:32:18","slug":"record-en-natacion-paralimpica","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20120830\/record-en-natacion-paralimpica\/","title":{"rendered":"R\u00e9cord en nataci\u00f3n paral\u00edmpica"},"content":{"rendered":"<p>El nadador brasile\u00f1o Daniel Dias se proclam\u00f3 campe\u00f3n paral\u00edmpico de Londres 2012 en la prueba de 50 metros libre con un tiempo de 32.05 segundos, nuevo r\u00e9cord del mundo en la disciplina.<\/p>\n<p>Dias, de 24 a\u00f1os, a\u00f1adi\u00f3 una nueva presea a las nueve que consigui\u00f3 en Pek\u00edn (cuatro oros, cuatro platas y un bronce) al imponerse holgadamente en el Centro Acu\u00e1tico de Londres al espa\u00f1ol Sebasti\u00e1n Garc\u00eda (33.44) y al estadounidense Roy Perkin (33.69).<\/p>\n<p>El brasile\u00f1o, que en la cita de China se tuvo que conformar con el segundo puesto en esta distancia, ya demostr\u00f3 su superioridad en las rondas clasificatorias de la ma\u00f1ana en las que logr\u00f3 el mejor tiempo con un registro de 33.02 segundos.<\/p><div class=\"notic-content-middle\" id=\"notic-1112304281\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Su compatriota, Clodoaldo Silva, quinto en las clasificatorias, tuvo que conformarse con un diploma ol\u00edmpico al quedar en la misma plaza en la final con una marca de 34.99 segundos.<\/p>\n<p>Dias consigui\u00f3 as\u00ed la primera medalla de oro de Brasil en los Juegos Paral\u00edmpicos de Londres aunque aspira a engrosar esta cifra en las otras siete pruebas en que compite.<\/p>","protected":false},"excerpt":{"rendered":"<p>El nadador brasile\u00f1o Daniel Dias se proclam\u00f3 campe\u00f3n paral\u00edmpico de Londres 2012 en la prueba de 50 metros libre con un tiempo de 32.05 segundos, nuevo r\u00e9cord del mundo en la disciplina. Dias, de 24 a\u00f1os, a\u00f1adi\u00f3 una nueva presea a las nueve que consigui\u00f3 en Pek\u00edn (cuatro oros, cuatro platas y un bronce) al [&hellip;]<\/p>","protected":false},"author":0,"featured_media":913195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-64098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=64098"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64098\/revisions"}],"predecessor-version":[{"id":913233,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/64098\/revisions\/913233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/913195"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=64098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=64098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=64098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}