{"id":63803,"date":"2014-12-03T00:00:00","date_gmt":"2014-12-03T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20141203\/maestros-colocan-pancartas-en-denuncia-por-atropellos\/"},"modified":"2025-08-17T14:09:27","modified_gmt":"2025-08-17T14:09:27","slug":"maestros-colocan-pancartas-en-denuncia-por-atropellos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20141203\/maestros-colocan-pancartas-en-denuncia-por-atropellos\/","title":{"rendered":"Maestros colocan pancartas en denuncia por atropellos"},"content":{"rendered":"<p>Miembros de la Asociaci\u00f3n de Maestros de Puerto Rico (AMPR) colocaron pancartas la ma\u00f1ana del miercoles en diversos puntos de la isla en reclamo por diversos asuntos, especialmente por la reducci\u00f3n del bono de Navidad.<\/p>\n<p>&#8216;Esta es una serie de actividades de denuncia que est\u00e1 haciendo el magisterio puertorrique\u00f1o. Esta es nuestra segunda Navidad atropellada que ha tenido el magisterio. El a\u00f1o pasado fue la amenaza al Retiro de Maestros y este a\u00f1o es el menoscabo al bono navide\u00f1o&#8217;, dijo el maestro Bryan Molina Cabrera en entrevista radial (Radio Isla).<\/p>\n<p>Indic\u00f3 que en diversos lugares colocaron pancartas que leen: \u2018Indignaci\u00f3n magisterial&#8217;, con las que adem\u00e1s reclaman mejores condiciones de empleo y un salario justo.<\/p><div class=\"notic-content-middle\" id=\"notic-1436711659\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Seg\u00fan record\u00f3, la Ley 66 de Sostenibilidad Fiscal establece que el bono de los maestros, que era de mil d\u00f3lares, se reducir\u00e1 a 600 d\u00f3lares.<\/p>\n<p>Finalmente, adelant\u00f3 que tienen una serie de actividades que realizar\u00e1n hasta el viernes, cuando acudir\u00e1n a la Fortaleza para emplazar al gobernador, al secretario de Justicia y al procurador general para exigir una investigaci\u00f3n sobre el uso de los fondos p\u00fablicos destinados a la educaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Miembros de la Asociaci\u00f3n de Maestros de Puerto Rico (AMPR) colocaron pancartas la ma\u00f1ana del miercoles en diversos puntos de la isla en reclamo por diversos asuntos, especialmente por la reducci\u00f3n del bono de Navidad. &#8216;Esta es una serie de actividades de denuncia que est\u00e1 haciendo el magisterio puertorrique\u00f1o. Esta es nuestra segunda Navidad atropellada [&hellip;]<\/p>","protected":false},"author":0,"featured_media":858940,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-63803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=63803"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63803\/revisions"}],"predecessor-version":[{"id":858988,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63803\/revisions\/858988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/858940"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=63803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=63803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=63803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}