{"id":63597,"date":"2017-11-06T00:00:00","date_gmt":"2017-11-06T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/transito\/20171106\/cierran-via-en-ponce-por-accidente\/"},"modified":"2025-07-28T23:32:47","modified_gmt":"2025-07-28T23:32:47","slug":"cierran-via-en-ponce-por-accidente","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20171106\/cierran-via-en-ponce-por-accidente\/","title":{"rendered":"Cierran v\u00eda en Ponce por accidente"},"content":{"rendered":"<p><i>Est\u00e1 parcialmente cerrada.<\/i><\/p>\n<p>La Divisi\u00f3n de Patrullas de Carreteras Ponce investiga un accidente entre dos veh\u00edculos en la carretera PR-2 intersecci\u00f3n con la PR-585 de Ponce, (\u00e1rea de P\u00e1mpanos), en direcci\u00f3n del Tuque hacia Ponce.<\/p>\n<p>Las autoridades indicaron que la v\u00eda est\u00e1 parcialmente cerrada, transcurre lenta y se est\u00e1 desviando el tr\u00e1nsito por un ramal de la referida carretera.<\/p>\n<p>Se desconocen detalles adicionales sobr este accidente, mientras las autordiades se aprestan a trabajar con la pesquisa.<\/p>","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 parcialmente cerrada. La Divisi\u00f3n de Patrullas de Carreteras Ponce investiga un accidente entre dos veh\u00edculos en la carretera PR-2 intersecci\u00f3n con la PR-585 de Ponce, (\u00e1rea de P\u00e1mpanos), en direcci\u00f3n del Tuque hacia Ponce. Las autoridades indicaron que la v\u00eda est\u00e1 parcialmente cerrada, transcurre lenta y se est\u00e1 desviando el tr\u00e1nsito por un ramal [&hellip;]<\/p>","protected":false},"author":0,"featured_media":603943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-63597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=63597"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63597\/revisions"}],"predecessor-version":[{"id":603961,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63597\/revisions\/603961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/603943"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=63597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=63597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=63597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}