{"id":63484,"date":"2014-09-15T00:00:00","date_gmt":"2014-09-15T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20140915\/roban-cientos-de-galones-de-diesel-en-moca\/"},"modified":"2025-07-18T11:45:18","modified_gmt":"2025-07-18T11:45:18","slug":"roban-cientos-de-galones-de-diesel-en-moca","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20140915\/roban-cientos-de-galones-de-diesel-en-moca\/","title":{"rendered":"Roban cientos de galones de diesel en Moca"},"content":{"rendered":"<p>Las autoridades informaron que un escalamiento se report\u00f3 a eso de la 4:39 de la madrugada del domingo en la carretera PR-110 del barrio Centro de Moca, de donde se robaron cientos de galones de diesel.<\/p>\n<p>Seg\u00fan el parte policiaco, Miguel Emmanuelli Llorens, gerente de operaciones de la compa\u00f1\u00eda Open Mobile, aleg\u00f3 que alguien rompi\u00f3 la verja que da acceso a una torre de comunicaciones y perforaron un tanque de gasolina para robarse de 300 galones del mencionado combustible.<\/p>\n<p>Las autoridades detallaron que la propiedad fue valorada en 2,200 d\u00f3lares.<\/p>\n<p>La Divisi\u00f3n de Propiedad del Cuerpo de Investigaciones Criminales (CIC) Aguadilla se hizo cargo de la investigaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Las autoridades informaron que un escalamiento se report\u00f3 a eso de la 4:39 de la madrugada del domingo en la carretera PR-110 del barrio Centro de Moca, de donde se robaron cientos de galones de diesel. Seg\u00fan el parte policiaco, Miguel Emmanuelli Llorens, gerente de operaciones de la compa\u00f1\u00eda Open Mobile, aleg\u00f3 que alguien rompi\u00f3 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":517791,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-63484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=63484"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63484\/revisions"}],"predecessor-version":[{"id":517794,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/63484\/revisions\/517794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/517791"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=63484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=63484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=63484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}