{"id":62377,"date":"2015-07-07T00:00:00","date_gmt":"2015-07-07T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20150707\/robots-gigantes-de-japon-y-eeuu-libraran-batalla-cuerpo-a-cuerpo\/"},"modified":"2025-07-25T15:32:29","modified_gmt":"2025-07-25T15:32:29","slug":"robots-gigantes-de-japon-y-eeuu-libraran-batalla-cuerpo-a-cuerpo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20150707\/robots-gigantes-de-japon-y-eeuu-libraran-batalla-cuerpo-a-cuerpo\/","title":{"rendered":"Robots gigantes de Jap\u00f3n y EEUU librar\u00e1n batalla cuerpo a cuerpo"},"content":{"rendered":"<p>El fabricante de robots japones Suidobashi Heavy Industries ha aceptado el duelo lanzado esta semana por su competidor estadounidense Megabot y se medir\u00e1 en una batalla de aut\u00f3matas gigantes.<\/p>\n<p>Aunque a\u00fan no se han anunciado ni la fecha ni el lugar, un robot nip\u00f3n de 4.000 kilos, y un estadounidense de 5,400, se ver\u00e1n pronto las caras en lo que muchos esperan que sea el inicio de un nuevo tipo de espect\u00e1culo que ya sido profusamente retratado en obras de ciencia ficci\u00f3n: las batallas de robots gigantes.<\/p>\n<p>Megabot public\u00f3 esta semana un v\u00eddeo cargado de humor presentando su Mark II &#8216;el primer robot gigante pilotable completamente funcional&#8217; de Estados Unidos.<\/p>\n<p>Al son del &#8216;Barras y estrellas por siempre&#8217; de Sousa, dos de los fundadores de Megabot, Gui Cavalcanti y Matt Oehrlein, explican, enfundados en banderas estadounidenses, que &#8216;al ser americanos&#8217; han equipado al Mark II &#8216;con unos ca\u00f1ones muy grandes&#8217; de &#8216;paintball&#8217; antes de desafiar a Suidobashi y a su modelo Kuratas a un duelo.<\/p>\n<p>El v\u00eddeo de respuesta de Kogoro Kurata, consejero delegado de la empresa nipona, ha tardado un d\u00eda en llegar y en las im\u00e1genes, el ingeniero y creador principal del Kuratas, se enfunda a su vez en una ense\u00f1a japonesa y acepta el reto de Megabot.<\/p>\n<p>&#8216;Me parece muy interesante (la propuesta)&#8217;, dice Kurata, que a\u00fan as\u00ed considera que su competidor estadounidense podr\u00eda haberlo &#8216;hecho mejor&#8217;.<\/p>\n<p>&#8216;Construir una cosa gigante y ponerle ca\u00f1ones&#8230; es tan americano. No podemos permitir que otro pa\u00eds gane; los robots gigantes son parte de la cultura nipona&#8217;, dice con sorna antes de a\u00f1adir que su intenci\u00f3n es &#8216;mandar al desguace&#8217; al Mark II a pu\u00f1etazo limpio.<\/p>","protected":false},"excerpt":{"rendered":"<p>El fabricante de robots japones Suidobashi Heavy Industries ha aceptado el duelo lanzado esta semana por su competidor estadounidense Megabot y se medir\u00e1 en una batalla de aut\u00f3matas gigantes. Aunque a\u00fan no se han anunciado ni la fecha ni el lugar, un robot nip\u00f3n de 4.000 kilos, y un estadounidense de 5,400, se ver\u00e1n pronto [&hellip;]<\/p>","protected":false},"author":0,"featured_media":574941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-62377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/62377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=62377"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/62377\/revisions"}],"predecessor-version":[{"id":574960,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/62377\/revisions\/574960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/574941"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=62377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=62377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=62377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}