{"id":622341,"date":"2020-02-27T00:00:00","date_gmt":"2020-02-27T04:00:00","guid":{"rendered":"https:\/\/test.noticel.com\/ahora\/gobierno\/20200227\/sectores-en-aguadilla-podrian-estar-sin-agua-por-trabajos-en-aaa\/"},"modified":"2025-08-01T14:59:34","modified_gmt":"2025-08-01T14:59:34","slug":"sectores-en-aguadilla-podrian-estar-sin-agua-por-trabajos-en-aaa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200227\/sectores-en-aguadilla-podrian-estar-sin-agua-por-trabajos-en-aaa\/","title":{"rendered":"Sectores en Aguadilla podr\u00edan estar sin agua por trabajos en AAA"},"content":{"rendered":"<p><i>Las reparaciones se har\u00e1n ma\u00f1ana jueves.<\/i><\/p>\n<p>La Autoridad de Acueductos y Alcantarillados (AAA) informa que ma\u00f1ana jueves 27 de febrero, se llevar\u00e1n a cabo trabajos de reparaci\u00f3n de una reguladora en la carretera PR 459 de Aguadilla, inform\u00f3 el director del \u00e1rea operacional, Ing. Nelson Saavedra.<\/p>\n<p>Como resultado, los barrios y sectores que se sirven del sistema de bombeo de Caimital tendr\u00e1n bajas presiones o interrupci\u00f3n del servicio de agua a partir de horas de la madrugada.<\/p>\n<p>Los lugares afectados son Caimital, Ceiba Baja, Ceiba Alta, Corrales, Guerrero, Arenales, San Antonio, Villas Universitarias; y en Moca el barrio Centro.<\/p>\n<p>Una vez completados los trabajos se iniciar\u00e1 la recuperaci\u00f3n del servicio de agua, a partir de horas de la tarde del mismo jueves.<\/p>\n<p>Ante la posibilidad de turbidez al restablecerse el servicio, se recomienda hervir por tres minutos el agua destinada para consumo humano.<\/p>","protected":false},"excerpt":{"rendered":"<p>Las reparaciones se har\u00e1n ma\u00f1ana jueves. La Autoridad de Acueductos y Alcantarillados (AAA) informa que ma\u00f1ana jueves 27 de febrero, se llevar\u00e1n a cabo trabajos de reparaci\u00f3n de una reguladora en la carretera PR 459 de Aguadilla, inform\u00f3 el director del \u00e1rea operacional, Ing. Nelson Saavedra. Como resultado, los barrios y sectores que se sirven [&hellip;]<\/p>","protected":false},"author":3,"featured_media":537061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-622341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/622341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=622341"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/622341\/revisions"}],"predecessor-version":[{"id":840210,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/622341\/revisions\/840210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/537061"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=622341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=622341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=622341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}