{"id":622065,"date":"2020-02-02T00:00:00","date_gmt":"2020-02-02T04:00:00","guid":{"rendered":"https:\/\/test.noticel.com\/beisbol\/deportes\/serie-del-caribe\/top-stories\/20200202\/homenaje-al-invicto-dream-team-puertorriqueno-del-95\/"},"modified":"2025-08-01T14:58:49","modified_gmt":"2025-08-01T14:58:49","slug":"homenaje-al-invicto-dream-team-puertorriqueno-del-95","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20200202\/homenaje-al-invicto-dream-team-puertorriqueno-del-95\/","title":{"rendered":"Homenaje al invicto &#8216;dream team&#8217; puertorrique\u00f1o del &#8217;95"},"content":{"rendered":"<p>Ataviados con uniformes de Puerto Rico, algunos de los miembros del emblem\u00e1tico &#8216;Equipo de Ensue\u00f1o&#8217; (<em>Dream Team<\/em>) que gan\u00f3 de manera invicta la Serie del Caribe de B\u00e9isbol 1995, fueron homenajeados este s\u00e1bado en la apertura de la edici\u00f3n 62 que se juega en el Estadio Hiram Bithorn, en San Juan.<\/p>\n<p>Roberto Alomar, miembro del Sal\u00f3n de la Fama del B\u00e9isbol, encabez\u00f3 al grupo de honrados, integrados por Bernie Williams, Carlos Delgado, Juan &#8216;Igor&#8217; Gonz\u00e1lez, Rub\u00e9n Sierra, Carlos Baerga, Roberto Hern\u00e1ndez, Carmelo Mart\u00ednez y Ricky Bones, quienes fueron recibidos con v\u00edtores.<\/p>\n<p>Los exjugadores saltaron al campo junto e hicieron el lanzamiento de honor previo al partido de la Serie del Caribe 2020 entre los puertorrique\u00f1os Cangrejeros de Santurce y los paname\u00f1os Astronautas de Chiriqu\u00ed, campeones defensores del torneo caribe\u00f1o. En la ceremonia, la cantante Melina Le\u00f3n enton\u00f3 los himnos.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"1158625695\" embed-content-groupid=\"593030471\" embed-content-id=\"1158625695\" embed-content-imgalign=\"none\" embed-content-index=\"0\" embed-content-location=\"input_story-body\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2020\/02\/01\/serie%20del%20caribe%202020%20melina%20leon_1580605728858.jpeg_39804682_ver1.0_640_360.jpg\" style=\"width:100%;\"\/><\/p>\n<p>Esta fue la segunda ocasi\u00f3n que esta legendaria novena es homenajeada en una Serie del Caribe.<\/p>\n<p>La primera vez fue en la edici\u00f3n de 2015, tambi\u00e9n celebrada en el estadio sanjuanero.<\/p>\n<p>La novena fue bautizada como el &#8216;Equipo de Ensue\u00f1o&#8217; porque a principios de la d\u00e9cada de los 90 algunos eran estrellas en las Grandes Ligas, entre ellos, Alomar, quien ya hab\u00eda ganado dos campeonatos como segunda base regular de los Azulejos de Toronto, as\u00ed como cinco juegos de Estrellas y guantes de Oro.<\/p>\n<p>Gonz\u00e1lez fue l\u00edder en jonrones de la Liga Americana en 1992 con 42 y en 1993 con 46, que en su momento fue un r\u00e9cord para un latinoamericano, mientras que Mart\u00ednez fue l\u00edder de bateo en 1992 y en dobles, 46, en la misma liga.<\/p><div class=\"notic-content-middle\" id=\"notic-228468062\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Ellos jugaron la liga invernal puertorrique\u00f1a porque la temporada de 1994 en las Grandes Ligas se detuvo por una huelga de peloteros.<\/p>\n<p>Tras sus destacadas carreras, Alomar y Mart\u00ednez fueron exaltados al Sal\u00f3n de la Fama de las Grandes Ligas.<\/p>\n<p>A trav\u00e9s de sus carreras, Williams gan\u00f3 cuatro campeonatos con los Yankees de Nueva York, Mart\u00ednez est\u00e1 considerado por muchos como el bateador designado m\u00e1s efectivo de la historia y Delgado culmin\u00f3 como el m\u00e1ximo jonronero puertorrique\u00f1o.<\/p>\n<p>Mart\u00ednez, exjugador de los Marineros de Seattle, sali\u00f3 como designado en 1,412 de sus 2,055 partidos, por lo que en 2004 las Grandes Ligas lo distingui\u00f3 como el Mejor Bateador Designado.<\/p>\n<p>Adem\u00e1s, gan\u00f3 dos t\u00edtulos de bateo en la Liga Americana (1992 y 1995) para conseguir .312 de promedio con 309 jonrones. Incluso fue escogido como bateador designado del Juego de Estrellas de 1996.<\/p>\n<p>Mart\u00ednez tiene tambi\u00e9n entre sus estad\u00edsticas 514 dobles, 1,261 carreras impulsadas y 1,209 carreras anotadas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ataviados con uniformes de Puerto Rico, algunos de los miembros del emblem\u00e1tico &#8216;Equipo de Ensue\u00f1o&#8217; (Dream Team) que gan\u00f3 de manera invicta la Serie del Caribe de B\u00e9isbol 1995, fueron homenajeados este s\u00e1bado en la apertura de la edici\u00f3n 62 que se juega en el Estadio Hiram Bithorn, en San Juan. Roberto Alomar, miembro del [&hellip;]<\/p>","protected":false},"author":3,"featured_media":538779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[32,31],"tags":[],"class_list":["post-622065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/622065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=622065"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/622065\/revisions"}],"predecessor-version":[{"id":839928,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/622065\/revisions\/839928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/538779"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=622065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=622065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=622065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}