{"id":621879,"date":"2020-02-08T00:00:00","date_gmt":"2020-02-08T04:00:00","guid":{"rendered":"https:\/\/test.noticel.com\/ahora\/economia\/top-stories\/tribunales\/20200208\/demandan-al-banco-popular-por-cobros-multiples-indebidos-a-sus-clientes\/"},"modified":"2025-08-01T14:58:42","modified_gmt":"2025-08-01T14:58:42","slug":"demandan-al-banco-popular-por-cobros-multiples-indebidos-a-sus-clientes","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200208\/demandan-al-banco-popular-por-cobros-multiples-indebidos-a-sus-clientes\/","title":{"rendered":"Demandan al Banco Popular por cobros m\u00faltiples indebidos a sus clientes"},"content":{"rendered":"<p><i>Le imputan violaci\u00f3n contractual, entre otras<\/i><\/p>\n<p>El Banco Popular enfrenta una demanda federal que pretende representar a todos sus clientes que hayan sido v\u00edctimas de lo que se alega son cobros m\u00faltiples indebidos que no est\u00e1n especificados en el contrato de cuentas de sus clientes.<\/p>\n<p>La demanda est\u00e1 presentada en el Tribunal Federal para el Distrito de Puerto Rico desde el 31 de enero pasado por el bufete de Washington DC, Kaliel PLLC, especializado en pleitos de clase en el sector financiero.<\/p>\n<p>El demandante representante de la clase es Pedro Soto Melendez, un cliente de Las Piedras que tiene una cuenta corriente en el Popular.<\/p>\n<p>Los cobros objetados son los de fondos insuficientes (NSF Fee) y cargos por sobregiro (OD Fees). Lo que se alega no es que estos cargos sean ilegales de por s\u00ed, es que el banco ilegalmente aplica ambos cargos a una misma transacci\u00f3n y que los aplican de manera m\u00faltiple.<\/p>\n<p>El contrato del Popular con sus clientes les permite cobrar un cargo de $15 cada uno por estas dos categor\u00edas.<\/p>\n<p>En el caso de Soto Melendez, realiz\u00f3 un pago a su tarjeta American Express para el cual no ten\u00eda fondos suficientes. Al realizar el pago de esa manera, el Banco le cobr\u00f3 $15 pero, sin que el cliente lo pidiera, el Banco intent\u00f3 completar la transacci\u00f3n en dos ocasiones posteriores corridas y en cada una le cobr\u00f3 $15. Al final, el cliente hab\u00eda acumulado $45 en cargos por esa transacci\u00f3n.<\/p>\n<p>&#8216;Esta pr\u00e1ctica abusiva no es universal en la industria de servicios financieros&#8217;, dice la demanda al asegurar que la pr\u00e1ctica general es que los bancos no hacen cobros m\u00faltiples por la misma transacci\u00f3n o, si lo hacen, aclaran en su contrato que as\u00ed lo har\u00e1n.<\/p>\n<p>Los fundamentos legales para la demanda son violaci\u00f3n contractual, enriquecimiento injusto y violaci\u00f3n de la buena fe.<\/p>\n<p>&#8216;El demandante realiz\u00f3 una sola acci\u00f3n para hacer un solo pago, por tanto, solo se le debe cobrar un solo cargo&#8217;, sostiene el documento. &#8216;La misma transacci\u00f3n electr\u00f3nica o cheque en una cuenta no puede concebirse que se convierte en una nueva transacci\u00f3n cada vez que se rechaza el pago y se reprocesa, especialmente cuando, como es este caso, el demandante no tom\u00f3 ninguna acci\u00f3n para resometer el pago&#8217;, a\u00f1ade.<\/p>\n<p>Al ped\u00edrsele reacci\u00f3n, el Banco Popular se limit\u00f3 a se\u00f1alar que &#8216;Popular no acostumbra emitir comentarios sobre los meritos de un litigio activo. Estaremos evaluando las alegaciones en la demanda para determinar el curso a seguir junto con nuestros abogados&#8217;.<\/p>\n<p><strong><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2020\/02\/06\/bppr%20dem%20clase_1581046882270_39813841_ver1.0.pdf\" target=\"_blank\">Para ver la demanda, pulse aqu\u00ed.<\/a><\/strong><\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"1159150422\" embed-content-groupid=\"593030471\" embed-content-id=\"1159150422\" embed-content-imgalign=\"none\" embed-content-index=\"0\" embed-content-location=\"input_story-body\" embed-content-type=\"FILE\" height=\"240px\" src=\"\/amino-v1-theme\/images\/placeholder\/placeholder-16x9.jpg\" style=\"width:100%;\" width=\"360px\"\/><\/p>","protected":false},"excerpt":{"rendered":"<p>Le imputan violaci\u00f3n contractual, entre otras El Banco Popular enfrenta una demanda federal que pretende representar a todos sus clientes que hayan sido v\u00edctimas de lo que se alega son cobros m\u00faltiples indebidos que no est\u00e1n especificados en el contrato de cuentas de sus clientes. La demanda est\u00e1 presentada en el Tribunal Federal para el [&hellip;]<\/p>","protected":false},"author":3,"featured_media":538291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22,13,2],"tags":[],"class_list":["post-621879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-tribunales","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/621879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=621879"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/621879\/revisions"}],"predecessor-version":[{"id":839876,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/621879\/revisions\/839876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/538291"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=621879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=621879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=621879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}