{"id":621197,"date":"2020-02-19T00:00:00","date_gmt":"2020-02-19T04:00:00","guid":{"rendered":"https:\/\/test.noticel.com\/ahora\/fama\/pop\/top-stories\/tribunales\/20200219\/celimar-adames-demanda-por-discrimen-a-wapa-que-enfrenta-otras-querellas-s\/"},"modified":"2025-08-01T14:59:21","modified_gmt":"2025-08-01T14:59:21","slug":"celimar-adames-demanda-por-discrimen-a-wapa-que-enfrenta-otras-querellas-s","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200219\/celimar-adames-demanda-por-discrimen-a-wapa-que-enfrenta-otras-querellas-s\/","title":{"rendered":"Celimar Adames demanda por discrimen a WAPA, que enfrenta otras querellas s"},"content":{"rendered":"<p><i>Contrataci\u00f3n de Katiria Soto deton\u00f3 pleito.<\/i><\/p>\n<p>La reportera y exmujer ancla de Noticentro, Celimar Adames Casalduc, demand\u00f3 a Televicentro de Puerto Rico (WAPA TV) alegando un patr\u00f3n de discrimen por g\u00e9nero y edad, manifestado en una larga trayectoria de recibir menor paga que sus contrapartes masculinos y tambi\u00e9n en removerla como mujer ancla mientras se manten\u00edan a hombres ancla en sus posiciones.<\/p>\n<p>La demanda, radicada el viernes pasado, divulga que la reportera tiene una querella pendiente en la Comisi\u00f3n Federal de Igual Oportunidad en el Empleo (EEOC, por sus siglas en ingl\u00e9s) y que, adem\u00e1s, el canal tiene pendiente otras querellas en ese foro de parte de empleadas mujeres.<\/p>\n<p>De hecho, la reclamaci\u00f3n de Adames contiene una alegaci\u00f3n de represalia porque supuestamente el canal la removi\u00f3 como mujer ancla en mayo de 2019 como riposta\u00a0a la radicaci\u00f3n de la querella en la EEOC.<\/p>\n<p>De las alegaciones en el escrito suscrito por la licenciada Nora Vargas Acosta, surge que el detonante para la radicaci\u00f3n de la demanda en el Tribunal de Primera Instancia de Bayam\u00f3n, aparte del tr\u00e1mite pendiente en la EEOC, ha sido la contrataci\u00f3n de Katiria Soto como ancla anunciada el 30 de enero pasado.<\/p><div class=\"notic-content-middle\" id=\"notic-1940532730\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Adames reclama al tribunal que ordene: la restituci\u00f3n de sus funciones como mujer ancla, pagos retroactivos correspondientes a lo que le dejaron de pagar en comparaci\u00f3n con sus contrapartes masculinos, equipararle su salario como ancla al que tienen contrapartes masculinos (como Normando Valent\u00edn) y que se estima en $300,000, un pago de $500,000 por da\u00f1os y perjuicios y &#8216;proveer el salario, bonificaciones y beneficios correspondientes al provisto a los colegas que realizan trabajo similar o igual a ella como Reportera\/Ancla&#8217;.<\/p>\n<p>&#8216;Como resultado de la conducta discriminatoria y de represalias su desarrollo profesional como Reportera\/Ancla se ve coartado y descarrilado provocando incertidumbre a pesar de su excelente desempe\u00f1o, a\u00f1os de experiencia, compromiso y lealtad no tan solo con Televicentro pero con el p\u00fablico&#8217;, sostiene la demanda.<\/p>\n<p>&#8216;Seg\u00fan nuestra pol\u00edtica, los asuntos relacionados a los empleados del Canal se atienden de manera privada&#8217;, indic\u00f3 Televicentro al ped\u00edrsele\u00a0reacci\u00f3n.<\/p>\n<p><a href=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/document_dev\/2020\/02\/18\/Demanda%20de%20Celimar%20Adames%20contra%20Televicentro%20WAPA%20febrero%202020_1582037847770_39828179_ver1.0.pdf\" target=\"_blank\">Para ver la demanda, pulse aqu\u00ed.<\/a><\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"1160444968\" embed-content-groupid=\"593030471\" embed-content-id=\"1160444968\" embed-content-imgalign=\"none\" embed-content-index=\"0\" embed-content-location=\"input_story-body\" embed-content-type=\"FILE\" height=\"240px\" src=\"\/amino-v1-theme\/images\/placeholder\/placeholder-16x9.jpg\" style=\"width:100%;\" width=\"360px\"\/><\/p>","protected":false},"excerpt":{"rendered":"<p>Contrataci\u00f3n de Katiria Soto deton\u00f3 pleito. La reportera y exmujer ancla de Noticentro, Celimar Adames Casalduc, demand\u00f3 a Televicentro de Puerto Rico (WAPA TV) alegando un patr\u00f3n de discrimen por g\u00e9nero y edad, manifestado en una larga trayectoria de recibir menor paga que sus contrapartes masculinos y tambi\u00e9n en removerla como mujer ancla mientras se [&hellip;]<\/p>","protected":false},"author":3,"featured_media":537467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[54,13,2],"tags":[],"class_list":["post-621197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fama","category-tribunales","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/621197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=621197"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/621197\/revisions"}],"predecessor-version":[{"id":840120,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/621197\/revisions\/840120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/537467"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=621197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=621197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=621197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}