{"id":619968,"date":"2018-08-07T04:00:00","date_gmt":"2018-08-07T08:00:00","guid":{"rendered":"https:\/\/site.prod.ew.ntc.navigacloud.com\/2018\/08\/07\/cooperativa-sagrada-familia-busca-100-emprendedores-para-proyecto-de-incuba\/"},"modified":"2025-08-15T08:26:12","modified_gmt":"2025-08-15T08:26:12","slug":"cooperativa-sagrada-familia-busca-100-emprendedores-para-proyecto-de-incuba","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20180807\/cooperativa-sagrada-familia-busca-100-emprendedores-para-proyecto-de-incuba\/","title":{"rendered":"Cooperativa Sagrada Familia busca 100 emprendedores para proyecto de incuba"},"content":{"rendered":"<p>La Cooperativa Sagrada Familia busca 100 emprendedores para participar de su primer programa de incubaci\u00f3n de negocios, a traves del cual recibir\u00e1n capacitaci\u00f3n y acompa\u00f1amiento durante un a\u00f1o para convertir sus ideas en realidad, anunci\u00f3 su presidente ejecutivo, Eddie W. Alicea S\u00e1ez.<\/p>\n<p>La Cooperativa desarroll\u00f3 la Incubadora de Negocios Ahora para apoyar a residentes de Guaynabo y municipios adyacentes, ofreciendoles educaci\u00f3n y planificaci\u00f3n a traves del modelo de Incubadora de MicroEmpresas\u00ae Comunitarias Solidarias (iMECs). El proyecto comenzar\u00e1 a finales de agosto.<\/p>\n<p>&#8216;Creamos la Incubadora de Negocios Ahora convencidos de que nos toca diversificar las maneras en que servimos a nuestra comunidad. Creemos que es ahora que el pa\u00eds necesita desarrollar micro, peque\u00f1as o medianas empresas s\u00f3lidas, porque su creaci\u00f3n y fortalecimiento ser\u00e1 el motor que mover\u00e1 a Puerto Rico a una econom\u00eda estable, una econom\u00eda m\u00e1s justa y solidaria&#8217;, expres\u00f3 Alicea S\u00e1ez. El ejecutivo explic\u00f3 que la Incubadora surge de una alianza con el Municipio de Guaynabo y la Comisi\u00f3n de Desarrollo Cooperativo, con el objetivo de desarrollar el empresarismo solidario, una ruta viable de mover la econom\u00eda a traves de los micro y peque\u00f1os empresarios.<\/p>\n<p>El proyecto incluir\u00e1 un proceso de pre-incubaci\u00f3n en el que los propios participantes determinar\u00e1n la viabilidad de sus ideas. Luego, comenzar\u00e1 la incubaci\u00f3n, en la que los expertos Nelson Reyes y Lucy Carrasquillo, de la empresa social Consultores Comunitarios, ofrecer\u00e1n 70 horas de capacitaci\u00f3n sobre an\u00e1lisis de viabilidad, plan de negocios y mercadeo, aspectos legales y permisolog\u00eda, presupuesto, financiamiento y servicio al cliente, entre otros.<\/p><div class=\"notic-content-middle\" id=\"notic-305118363\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Esta alianza parte de una experiencia ya probada en otros espacios a traves de Puerto Rico y queremos, m\u00e1s que replicar algo que funciona, ser veh\u00edculos para la autosostenibilidad de individuos, familias y comunidades&#8217;, manifest\u00f3, por su parte el alcalde de Guaynabo, Angel Perez Otero. Mientras que la comisionada de Desarrollo Cooperativo, Ivelisse Torres Rivera, reiter\u00f3 su respaldo a esta iniciativa de desarrollo empresarial por parte de una cooperativa de ahorro y credito. La Comisionada puso a disposici\u00f3n del grupo de emprendedores un experto en desarrollo cooperativo, para ofrecerle gu\u00eda y orientaci\u00f3n a quienes opten por el modelo cooperativo para desarrollar su negocio.<\/p>\n<p>Las personas interesadas en ser parte de la Incubadora de Negocios Ahora, pueden informarse y solicitar accediendo a www.ahorapuertorico.com. La fecha l\u00edmite de solicitud es el 19 de agosto y la primera orientaci\u00f3n a los solicitantes el pr\u00f3ximo 22 de agosto. El curso de pre-incubaci\u00f3n comenzar\u00e1 el 29 de agosto en el Museo del Deporte de Guaynabo.<\/p>\n<p>La Cooperativa Sagrada Familia tiene sucursales en Guaynabo, San Juan, Bayam\u00f3n, Naranjito y Corozal. Cuenta con m\u00e1s de 26 mil socios en Puerto Rico y Estados Unidos, y $176 millones en activos.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Cooperativa Sagrada Familia busca 100 emprendedores para participar de su primer programa de incubaci\u00f3n de negocios, a traves del cual recibir\u00e1n capacitaci\u00f3n y acompa\u00f1amiento durante un a\u00f1o para convertir sus ideas en realidad, anunci\u00f3 su presidente ejecutivo, Eddie W. Alicea S\u00e1ez. La Cooperativa desarroll\u00f3 la Incubadora de Negocios Ahora para apoyar a residentes de [&hellip;]<\/p>","protected":false},"author":3,"featured_media":844293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[81,22,26],"tags":[],"class_list":["post-619968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auspiciado","category-economia","category-empresarismo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/619968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=619968"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/619968\/revisions"}],"predecessor-version":[{"id":844327,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/619968\/revisions\/844327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/844293"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=619968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=619968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=619968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}