{"id":61702,"date":"2012-07-21T00:00:00","date_gmt":"2012-07-21T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20120721\/noruega-recuerda-la-masacre-que-amenazo-su-sociedad-abierta\/"},"modified":"2025-08-26T07:21:14","modified_gmt":"2025-08-26T07:21:14","slug":"noruega-recuerda-la-masacre-que-amenazo-su-sociedad-abierta","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20120721\/noruega-recuerda-la-masacre-que-amenazo-su-sociedad-abierta\/","title":{"rendered":"Noruega recuerda la masacre que amenaz\u00f3 su sociedad abierta"},"content":{"rendered":"<p>Copenhague &#8211; Noruega recordar\u00e1 ma\u00f1ana en todo su territorio a las 77 v\u00edctimas mortales del doble atentado perpetrado hace un a\u00f1o por el ultraderechista Anders Behring Breivik, que conmocion\u00f3 el pa\u00eds y amenaz\u00f3 su modelo de sociedad abierta.<\/p>\n<p>Los actos principales estar\u00e1n centrados en los escenarios del atentado: en el complejo gubernamental de Oslo, donde Breivik hizo estallar una furgoneta bomba que mat\u00f3 a 8 personas; y en la isla de Ut\u00f8ya, al oeste de la capital, donde cometi\u00f3 una matanza en el campamento de las Juventudes Laboristas en la que murieron otras 69.<\/p>\n<p>En ambos habr\u00e1 una ceremonia privada para familiares de las v\u00edctimas y supervivientes, con ofrenda floral incluida y discurso del primer ministro, el socialdem\u00f3crata Jens Stoltenberg.<\/p>\n<p>Las Juventudes Laboristas (AUF, por sus siglas en noruego) organizar\u00e1n el que es posiblemente el acto central del d\u00eda en Ut\u00f8ya, donde un millar de miembros de todas las federaciones regionales y varias autoridades homenajear\u00e1n a las v\u00edctimas de la matanza.<\/p>\n<p>Su l\u00edder, Eskil Pedersen, defiende el derecho a &#8216;recuperar&#8217; la isla y no ceder ante Breivik, una idea ampliamente apoyada en el seno de las AUF, a pesar de las cr\u00edticas de alg\u00fan superviviente, que considera volver a Ut\u00f8ya un ultraje a los muertos.<\/p>\n<p>La direcci\u00f3n de las AUF s\u00f3lo ha decidido de momento derribar la cafeter\u00eda de la isla, donde Breivik asesin\u00f3 a 13 j\u00f3venes, y erigir en un par de a\u00f1os un monumento, pero Pedersen ha insinuado que en 2013 podr\u00eda volver a organizarse all\u00ed el campamento de verano, que este a\u00f1o se trasladar\u00e1 al norte del pa\u00eds.<\/p>\n<p>El lema &#8216;Recuperar Ut\u00f8ya&#8217;, lanzado por Pedersen el d\u00eda siguiente a los atentados, encaja bien con la idea de Stoltenberg y la clase pol\u00edtica de reaccionar con &#8216;m\u00e1s democracia y m\u00e1s apertura&#8217;.<\/p>\n<p>La sociedad noruega, con supervivientes y familiares de las v\u00edctimas a la cabeza, ha respondido de forma mayoritaria a esa llamada, ignorando las provocaciones de Breivik durante el juicio, y manifest\u00e1ndose &#8216;por la uni\u00f3n, la solidaridad y la diversidad, en vez de encerrarnos y ser m\u00e1s desconfiados&#8217;, en palabras de Stoltenberg.<\/p>\n<p>Tanto el primer ministro como Pedersen resaltan que hay m\u00e1s gente involucrada en los debates y ponen como ejemplo la amplia reacci\u00f3n a los comentarios racistas contra los gitanos rumanos acampados a las afueras de Oslo, que centran estos d\u00edas la actualidad en Noruega.<\/p>\n<p>La defensa de la democracia y de la sociedad multicultural, contra la que atent\u00f3 Breivik, contrastan con la recuperaci\u00f3n en los sondeos del ultranacionalista Partido del Progreso, que parece haber superado la fuerte ca\u00edda sufrida en los comicios municipales de septiembre y ha echado mano de nuevo del discurso antiinmigraci\u00f3n.<\/p>\n<p>Los atentados evidenciaron graves errores de coordinaci\u00f3n de las fuerzas de seguridad, muy criticados por las familias de las v\u00edctimas, que tuvieron que esperar ocho meses para que la Polic\u00eda admitiera algunos fallos y pidiera disculpas.<\/p>\n<p>Hasta dentro de tres semanas no presentar\u00e1 su informe la comisi\u00f3n creada por el Parlamento sobre la actuaci\u00f3n policial, pero \u00e9sta ya se ha cobrado dos v\u00edctimas en forma de dimisiones: el ministro de Justicia y la jefa de los servicios de inteligencia, aunque ambos apelaron a motivos personales para dejar el cargo.<\/p>\n<p>El Gobierno lanz\u00f3 hace unos d\u00edas una propuesta de reforma de la ley antiterrorista que da amplias facultades para investigar potenciales actos terroristas de individuos aislados, aunque le han llovido cr\u00edticas apuntando a que se quiere castigar las ideas.<\/p>\n<p>M\u00e1s duras y generalizadas han sido las protestas contra la nueva ley para quienes sean condenados a recibir atenci\u00f3n psiqui\u00e1trica por parecer hecha a medida para Breivik, que podr\u00eda recibir ese castigo.<\/p>\n<p>El juicio al ultraderechista noruego de 33 a\u00f1os, cuya sentencia se pronunciar\u00e1 previsiblemente el 24 de agosto, ha provocado un amplio debate sobre la necesidad de cambiar los criterios que en el Derecho noruego permiten declarar a alguien penalmente responsable de sus actos atendiendo a si existen dudas sobre su estado mental.<\/p>\n<p>Un a\u00f1o despu\u00e9s, a\u00fan queda una huella f\u00edsica de los atentados en el centro de Oslo: hace unos d\u00edas se acabaron de retirar las m\u00e1s de 4.300 toneladas de escombros de los edificios m\u00e1s afectados por la bomba, pero el complejo gubernamental de H\u00f8yblokka, el centro de poder del pa\u00eds, sigue inutilizado.<\/p>\n<p>Las autoridades a\u00fan no han decidido si derriban los nueve edificios y construyen un nuevo complejo, que no estar\u00eda listo hasta como poco dentro de 8 a\u00f1os, mientras varios departamentos trabajan en locales provisionales, incluido el primer ministro, cuya oficina est\u00e1 ahora en el Ministerio de Defensa.<\/p>","protected":false},"excerpt":{"rendered":"<p>Copenhague &#8211; Noruega recordar\u00e1 ma\u00f1ana en todo su territorio a las 77 v\u00edctimas mortales del doble atentado perpetrado hace un a\u00f1o por el ultraderechista Anders Behring Breivik, que conmocion\u00f3 el pa\u00eds y amenaz\u00f3 su modelo de sociedad abierta. Los actos principales estar\u00e1n centrados en los escenarios del atentado: en el complejo gubernamental de Oslo, donde [&hellip;]<\/p>","protected":false},"author":0,"featured_media":914674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=61702"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61702\/revisions"}],"predecessor-version":[{"id":914675,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61702\/revisions\/914675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/914674"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=61702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=61702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=61702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}