{"id":61534,"date":"2014-03-20T00:00:00","date_gmt":"2014-03-20T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20140320\/jorge-franco-gana-el-premio-alfaguara\/"},"modified":"2025-08-20T10:56:17","modified_gmt":"2025-08-20T10:56:17","slug":"jorge-franco-gana-el-premio-alfaguara","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20140320\/jorge-franco-gana-el-premio-alfaguara\/","title":{"rendered":"Jorge Franco gana el Premio Alfaguara"},"content":{"rendered":"<p>El escritor colombiano Jorge Franco gan\u00f3 hoy, por mayor\u00eda, la XVII edici\u00f3n del Premio Alfaguara con &#8216;El mundo de afuera&#8217;, una novela sobre el amor y la muerte, basada en un secuestro que conmocion\u00f3 a Medell\u00edn (Colombia) en 1971 y que supuso el comienzo de la violencia que luego invadir\u00eda la ciudad.<\/p>\n<p>El fallo de este premio, dotado con 175,000 d\u00f3lares y considerado uno de los m\u00e1s importantes del \u00e1mbito hisp\u00e1nico, se hizo un d\u00eda despu\u00e9s de que se hiciera p\u00fablica la venta de Alfaguara y de otros sellos literarios del grupo Santillana Penguin Random House por 72 millones de euros (100.2 millones d\u00f3lares).<\/p>\n<p>El jurado estuvo presidido por la escritora colombiana Laura Restrepo y formaron parte Sergio Vila-Sanju\u00e1n, Ignacio Mart\u00ednez de Pis\u00f3n, Ana Ca\u00f1ellas, Nelleke Geel y Pilar Reyes (con voz pero sin voto).<\/p>\n<p>Al leer el acta del jurado, Restrepo destac\u00f3 que la obra premiada narra &#8216;un desquiciado secuestro, en un ambiente progresivamente enrarecido, mediante la combinaci\u00f3n original de elementos de f\u00e1bula y cuento de hadas, y rasgos expresivos de un momento de violencia y crisis&#8217;.<\/p>\n<p>El jurado valor\u00f3 en la novela &#8216;el sentido del humor, la eficacia de los di\u00e1logos, la construcci\u00f3n de personajes complejos y la agilidad narrativa que hace que la tensi\u00f3n se mantenga hasta la \u00faltima p\u00e1gina&#8217;.<\/p>\n<p>La novela ganadora fue presentada bajo el t\u00edtulo &#8216;Aquel monstruo indomable&#8217; y con el seud\u00f3nimo de Antonio Benjam\u00edn.<\/p>\n<p>&#8216;El mundo de afuera&#8217; incorpora t\u00e9cnicas cinematogr\u00e1ficas como el &#8216;flashback&#8217; y la narraci\u00f3n paralela, y &#8216;bebe de fuentes como el cuento folcl\u00f3rico o la cr\u00f3nica de sucesos&#8217;, seg\u00fan el dossier facilitado por Alfaguara.<\/p><div class=\"notic-content-middle\" id=\"notic-1882009753\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>El libro est\u00e1 basado en un hecho real, aunque el autor se ha tomado &#8216;todo tipo de licencias&#8217; para recrear la historia que narra en \u00e9l, &#8216;muy cercana&#8217; a la infancia de Franco y a su propia vida, porque el don Diego que es secuestrado en la ficci\u00f3n fue un personaje real, pariente de la familia pol\u00edtica del escritor.<\/p>\n<p>A trav\u00e9s de la familia pudo &#8216;obtener mucha informaci\u00f3n para narrar la historia&#8217;, dijo el novelista en una entrevista con Efe.<\/p>\n<p>La novela refleja, adem\u00e1s, &#8216;un Medell\u00edn id\u00edlico y tranquilo que empez\u00f3 a cambiar a ra\u00edz de ese suceso que se cuenta en el libro&#8217;.<\/p>\n<p>En el Medell\u00edn de 1971 &#8216;hubo un secuestro y, posteriormente, un crimen, pero lo que solo forma parte de la ficci\u00f3n son los hechos que condujeron a la muerte de don Diego&#8217;, comenta el autor.<\/p>\n<p>Al campo de la ficci\u00f3n pertenece la relaci\u00f3n de don Diego con su secuestrador porque &#8216;parece que no hubo supervivientes del &#8216;bando malo\u00bb, a\u00f1ade el novelista colombiano, que vive en Bogot\u00e1 desde hace m\u00e1s de veinte a\u00f1os.<\/p>\n<p>Nacido en 1962, Franco hizo estudios de literatura en la Universidad Javeriana y de cine en The London International Film School. Es autor de novelas como &#8216;Rosario Tijeras&#8217; (Premio Internacional de Novela Hammett 2000), traducida a m\u00e1s de quince idiomas y llevada al cine y a la televisi\u00f3n, y de &#8216;Para\u00edso Travel&#8217;, cuya adaptaci\u00f3n cinematogr\u00e1fica se convirti\u00f3 en una de las pel\u00edculas m\u00e1s taquilleras del cine colombiano.<\/p>","protected":false},"excerpt":{"rendered":"<p>El escritor colombiano Jorge Franco gan\u00f3 hoy, por mayor\u00eda, la XVII edici\u00f3n del Premio Alfaguara con &#8216;El mundo de afuera&#8217;, una novela sobre el amor y la muerte, basada en un secuestro que conmocion\u00f3 a Medell\u00edn (Colombia) en 1971 y que supuso el comienzo de la violencia que luego invadir\u00eda la ciudad. El fallo de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":882103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-61534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=61534"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61534\/revisions"}],"predecessor-version":[{"id":882134,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61534\/revisions\/882134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/882103"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=61534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=61534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=61534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}