{"id":61116,"date":"2012-12-04T00:00:00","date_gmt":"2012-12-04T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20121204\/lai-bicampeones-los-gallitos-de-upr-rp-en-futbol\/"},"modified":"2025-08-24T17:42:08","modified_gmt":"2025-08-24T17:42:08","slug":"lai-bicampeones-los-gallitos-de-upr-rp-en-futbol","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20121204\/lai-bicampeones-los-gallitos-de-upr-rp-en-futbol\/","title":{"rendered":"LAI: Bicampeones los Gallitos de UPR RP en f\u00fatbol"},"content":{"rendered":"<p>Los Gallitos de la Universidad de Puerto Rico de R\u00edo Piedras (UPR RP) ganaron hoy, lunes, 1-0, a los Tigres de la Universidad Interamericana para conseguir el segundo campeonato consecutivo en el f\u00fatbol de la Liga Atletica Interuniversitaria.<\/p>\n<p>El gallo Lemuel S\u00e1lamo goleo en el minuto 6 rompiendo la barrera de defensa de los Tigres de la Interamericana.<\/p>\n<p>&#8216;Muy orgulloso del trabajo que hicimos desde el principio. Llegamos invictos a la final y as\u00ed ten\u00edamos que hacer. Gracias a Dios por permitirme llevar a la victoria a los Gallitos. Mi equipo&#8217;, dijo un euf\u00f3rico S\u00e1lamo.<\/p>\n<p>El goleador de oro de los bicampeones de la LAI est\u00e1 celebrando la victoria con mucho furor, ya que en el minuto 65 fue expulsado del juego con tarjeta roja.<\/p>\n<p>&#8216;Mi gol fue una ventaja sobre ellos (Interamericana). En el segundo tiempo seguimos luchando. Despu\u00e9s de mi expulsi\u00f3n yo sude m\u00e1s afuera en el banco que los minutos que tuve en juego&#8217;, expres\u00f3 el tambi\u00e9n competidor de pista y campo muy sonriente.<\/p><div class=\"notic-content-middle\" id=\"notic-420206883\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Por el tercer lugar, los Ta\u00ednos de la Universidad del Turabo ganaron 5-1 a los Tarzanes del Colegio de Mayag\u00fcez.<\/p>\n<p>El Festival Deportivo de la LAI del primer semestre continuar\u00e1 ma\u00f1ana, martes, con el inicio de Halterofilia. El evento ser\u00e1 desde las 10:00 a.m. en la UPR de Cayey.<\/p>\n<p>A las 11:00 a.m. ser\u00e1 el partido por el tercer lugar del b\u00e9isbol entre los Pitirres de la Universidad del Este y los Cocodrilos de la Universidad Metropolitana.<\/p>\n<p>El mi\u00e9rcoles continuar\u00e1 la final del b\u00e9isbol con partido decisivo entre los Tigres de la Universidad Interamericana y los Gryphons de la Caribbean University a las 11:00 a.m. en San Lorenzo.<\/p>\n<p>En la noche, 7:00 p.m., estar\u00e1 el segundo partido de la final de voleibol. Este puede ser victo por Sistema TV (Canal 40) de Ana G. M\u00e9ndez desde Gurabo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los Gallitos de la Universidad de Puerto Rico de R\u00edo Piedras (UPR RP) ganaron hoy, lunes, 1-0, a los Tigres de la Universidad Interamericana para conseguir el segundo campeonato consecutivo en el f\u00fatbol de la Liga Atletica Interuniversitaria. El gallo Lemuel S\u00e1lamo goleo en el minuto 6 rompiendo la barrera de defensa de los Tigres [&hellip;]<\/p>","protected":false},"author":0,"featured_media":906755,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-61116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=61116"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61116\/revisions"}],"predecessor-version":[{"id":906791,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/61116\/revisions\/906791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/906755"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=61116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=61116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=61116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}