{"id":5934,"date":"2018-08-21T00:00:00","date_gmt":"2018-08-21T04:00:00","guid":{"rendered":"https:\/\/test.noticel.com\/a-viajar\/hack\/vida\/20180821\/lanzan-aplicacion-para-turistas-de-pr\/"},"modified":"2025-08-27T22:37:08","modified_gmt":"2025-08-27T22:37:08","slug":"lanzan-aplicacion-para-turistas-de-pr","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20180821\/lanzan-aplicacion-para-turistas-de-pr\/","title":{"rendered":"Lanzan aplicaci\u00f3n para turistas de PR"},"content":{"rendered":"<p><i>Busca reforzar el turismo.<\/i><\/p>\n<p>La Compa\u00f1\u00eda de Turismo de Puerto Rico (CTPR) anunci\u00f3 la implementaci\u00f3n de una aplicaci\u00f3n de nombre &#8216;My Puerto Rico&#8217; que tendr\u00e1 como fin logra un trato m\u00e1s directo y r\u00e1pido entre los turistas y los hoteles.<\/p>\n<p>El anuncio, realizado entre el gobernador Ricardo Rossell\u00f3 Nevares y la directora ejecutiva de la CTPR, Carla Campos, incluye un incentivo para varios hoteles que indica que el Gobierno de Puerto Rico correr\u00e1 como el 90% de la anualidad de la plataforma durante los primeros 12 meses de su establecimiento.<\/p>\n<p>&#8216;Enfocados en mejorar la experiencia del visitante en nuestro destino, desarrollamos My Puerto Rico como parte de los esfuerzos para fortalecer nuestra oferta tur\u00edstica. Para competir a nivel global necesitamos reinventarnos y acoplarnos a las necesidades de un viajero moderno, que realiza todas sus gestiones desde el telefono m\u00f3vil&#8217;, expres\u00f3 el Primer Ejecutivo.<\/p><div class=\"notic-content-middle\" id=\"notic-3910041138\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Seg\u00fan se indic\u00f3, la plataforma permitir\u00e1 a los huespedes realizar desde una reservaci\u00f3n en el spa, la petici\u00f3n de una toalla, as\u00ed como solicitar servicios de transportaci\u00f3n, entre otros ofrecimientos que depender\u00e1n de cada hospeder\u00eda.<\/p>\n<p>&#8216;Con My Puerto Rico nos convertimos en un destino pionero, capaz de convertir tecnolog\u00eda previamente utilizada exitosamente por algunos hoteles, en una plataforma accesible a todas las hospeder\u00edas de la Isla, sin importar su presupuesto o tama\u00f1o. Servir al visitante de una manera innovadora y tecnol\u00f3gica ser\u00e1 ahora la norma en Puerto Rico&#8217;, expuso por su parte Campos.<\/p>\n<p>Esta plataforma fue creada por la compa\u00f1\u00eda tecnol\u00f3gica de reconocimiento mundial, ALICE.<\/p>","protected":false},"excerpt":{"rendered":"<p>Busca reforzar el turismo. La Compa\u00f1\u00eda de Turismo de Puerto Rico (CTPR) anunci\u00f3 la implementaci\u00f3n de una aplicaci\u00f3n de nombre &#8216;My Puerto Rico&#8217; que tendr\u00e1 como fin logra un trato m\u00e1s directo y r\u00e1pido entre los turistas y los hoteles. El anuncio, realizado entre el gobernador Ricardo Rossell\u00f3 Nevares y la directora ejecutiva de la [&hellip;]<\/p>","protected":false},"author":100,"featured_media":594437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-5934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/5934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=5934"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/5934\/revisions"}],"predecessor-version":[{"id":594458,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/5934\/revisions\/594458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/594437"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=5934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=5934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=5934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}